{"id":41678,"date":"2021-11-02T18:07:06","date_gmt":"2021-11-02T21:07:06","guid":{"rendered":"https:\/\/dev.explora.cl\/valparaiso\/?p=41678"},"modified":"2021-11-29T10:46:16","modified_gmt":"2021-11-29T13:46:16","slug":"con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/","title":{"rendered":"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas"},"content":{"rendered":"<h3><span style=\"font-weight: 400\">El pr\u00f3ximo s\u00e1bado 13 de noviembre, desde las 12.00 horas, podr\u00e1s visitar de manera presencial y gratuita este recorrido que combina la ciencia de la bot\u00e1nica y el arte presente <\/span><span style=\"font-weight: 400\">en el Museo Baburizza.\u00a0<\/span><\/h3>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400\">El Proyecto Explora Valpara\u00edso, del Ministerio de Ciencia, junto al Museo Baburizza y el Instituto de Biolog\u00eda de la PUCV, invitan a toda la ciudadan\u00eda a disfrutar de <strong>\u201cLa Ruta de la Bot\u00e1nica\u201d<\/strong>, actividad que se realizar\u00e1 de manera presencial el pr\u00f3ximo <strong>s\u00e1bado 13 de noviembre a partir de las 12.00 horas, en el marco del ya tradicional Festival Puerto de Ideas.\u00a0<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400\">En la ocasi\u00f3n, personas de todas las edades podr\u00e1n ser parte de un recorrido en el que junto al <strong>bot\u00e1nico, docente y Encargado de Vinculaci\u00f3n con el Medio de la Facultad de Ciencias de la PUCV, Dr. Cristian Atala Bianchi y el mediador del Museo, Daniel Fern\u00e1ndez;<\/strong> los y las participantes podr\u00e1n identificar especies bot\u00e1nicas presentes en la regi\u00f3n y representada en distintas obras pict\u00f3ricas de autores\/as como Dora Puelma, Alfredo Valenzuela, Thomas Somerscales, entre otros y otras.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/1-4-2\/\" rel=\"attachment wp-att-41682\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-41682 alignleft\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/1-4-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/1-4-300x200.jpeg 300w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/1-4-768x512.jpeg 768w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/1-4-1024x682.jpeg 1024w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/1-4.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>De esta forma, se desarrollar\u00e1 una visita guiada en la que a trav\u00e9s del arte se invita a conocer el patrimonio natural de la regi\u00f3n, y valorarlo mediante la observaci\u00f3n, el reconocimiento y la reflexi\u00f3n cient\u00edfica y art\u00edstica. Una diferencia respecto a su primera versi\u00f3n, es que en este nuevo lanzamiento la ruta incluye cinco nuevas obras presentes en el Museo. Adem\u00e1s, una vez finalizado el recorrido y l<\/span><span style=\"font-weight: 400\">uego de visitar el palacio, se realizar\u00e1 un taller de pl\u00e1stica y los y las asistentes podr\u00e1n conocer el sitio web <\/span><a href=\"blank\"><span style=\"font-weight: 400\">www.rutadelabot\u00e1nica.cl<\/span><\/a><span style=\"font-weight: 400\"> , plataforma en la que podr\u00e1s conocer algunas de las obras que componen este recorrido de manera virtual, identificando la flora presente, y adem\u00e1s pintar parte de las obras que son parte de esta exhibici\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\"><strong>Cabe se\u00f1alar que \u201cLa Ruta de la Bot\u00e1nica\u201d es\u00a0 es una actividad dise\u00f1ada el a\u00f1o 2016 en conjunto por Explora Valpara\u00edso, el Museo Baburizza y el Instituto de Biolog\u00eda de la Pontificia Universidad Cat\u00f3lica de Valpara\u00edso<\/strong>, con el objetivo de dar a conocer y poner en valor el patrimonio natural de la regi\u00f3n. Desde sus inicios, esta actividad, ha recibido la visita de m\u00e1s de 10 mil personas y esta ser\u00e1 la segunda vez que se presentar\u00e1 de manera presencial.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Si quieres ser parte de la actividad, inscr\u00edbete en <\/span><a href=\"https:\/\/festivalvalparaiso.puertodeideas.cl\/es\/programa\/ruta-de-la-botanica\/\"><span style=\"font-weight: 400\">este enlace<\/span><\/a><span style=\"font-weight: 400\"> o en el bot\u00f3n de inscripciones disponible en el <\/span><a href=\"http:\/\/festivalvalparaiso.puertodeideas.cl\"><span style=\"font-weight: 400\">sitio web del Festival Puerto de Ideas<\/span><\/a><span style=\"font-weight: 400\">.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo s\u00e1bado 13 de noviembre, desde las 12.00 horas, podr\u00e1s visitar de manera presencial y gratuita este recorrido que combina la ciencia de la bot\u00e1nica y el arte presente en el Museo Baburizza.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":41679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[310,1127,405,339,1128,110,156,158,713,526,166,186,523,174,1126],"class_list":["post-41678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-arte","tag-biologia-pucv","tag-botanica","tag-ciencia-regional","tag-ciencia-y-arte","tag-cultura-cientifica","tag-exposicion","tag-exposicion-interactiva-e-itinerante","tag-festival-puerto-de-ideas","tag-museo-baburizza","tag-proyecto-asociativo-regional-explora-valparaiso","tag-pucv","tag-puerto-de-ideas","tag-region-de-valparaiso","tag-ruta-de-la-botanica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas - Valpara\u00edso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas - Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo s\u00e1bado 13 de noviembre, desde las 12.00 horas, podr\u00e1s visitar de manera presencial y gratuita este recorrido que combina la ciencia de la bot\u00e1nica y el arte presente en el Museo Baburizza.\u00a0\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T21:07:06+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-29T13:46:16+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"jcastaneda\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"jcastaneda\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\"},\"author\":{\"name\":\"jcastaneda\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d\"},\"headline\":\"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas\",\"datePublished\":\"2021-11-02T21:07:06+00:00\",\"dateModified\":\"2021-11-29T13:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\"},\"wordCount\":468,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg\",\"keywords\":[\"arte\",\"Biolog\u00eda PUCV\",\"bot\u00e1nica\",\"ciencia regional\",\"ciencia y arte\",\"cultura cientifica\",\"exposici\u00f3n\",\"exposici\u00f3n interactiva e itinerante\",\"Festival Puerto de Ideas\",\"museo baburizza,\",\"Proyecto Asociativo Regional EXPLORA Valparaiso\",\"pucv\",\"Puerto de Ideas\",\"Regi\u00f3n de Valpara\u00edso\",\"Ruta de la Bot\u00e1nica\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\",\"name\":\"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas - Valpara\u00edso\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg\",\"datePublished\":\"2021-11-02T21:07:06+00:00\",\"dateModified\":\"2021-11-29T13:46:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/valparaiso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"name\":\"Valpara\u00edso\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\",\"name\":\"Valpara\u00edso\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"width\":2035,\"height\":584,\"caption\":\"Valpara\u00edso\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d\",\"name\":\"jcastaneda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g\",\"caption\":\"jcastaneda\"},\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/author\/jcastaneda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas - Valpara\u00edso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas - Valpara\u00edso","og_description":"El pr\u00f3ximo s\u00e1bado 13 de noviembre, desde las 12.00 horas, podr\u00e1s visitar de manera presencial y gratuita este recorrido que combina la ciencia de la bot\u00e1nica y el arte presente en el Museo Baburizza.\u00a0","og_url":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/","og_site_name":"Valpara\u00edso","article_published_time":"2021-11-02T21:07:06+00:00","article_modified_time":"2021-11-29T13:46:16+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg","type":"image\/jpeg"}],"author":"jcastaneda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jcastaneda","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/"},"author":{"name":"jcastaneda","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d"},"headline":"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas","datePublished":"2021-11-02T21:07:06+00:00","dateModified":"2021-11-29T13:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/"},"wordCount":468,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg","keywords":["arte","Biolog\u00eda PUCV","bot\u00e1nica","ciencia regional","ciencia y arte","cultura cientifica","exposici\u00f3n","exposici\u00f3n interactiva e itinerante","Festival Puerto de Ideas","museo baburizza,","Proyecto Asociativo Regional EXPLORA Valparaiso","pucv","Puerto de Ideas","Regi\u00f3n de Valpara\u00edso","Ruta de la Bot\u00e1nica"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/","url":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/","name":"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas - Valpara\u00edso","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg","datePublished":"2021-11-02T21:07:06+00:00","dateModified":"2021-11-29T13:46:16+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#primaryimage","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/11\/Foto-Ruta-presencial-2016.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/valparaiso\/con-mas-obras-y-flora-la-ruta-de-la-botanica-vuelve-a-puerto-de-ideas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/valparaiso\/"},{"@type":"ListItem","position":2,"name":"\u00a1Con m\u00e1s obras y m\u00e1s flora! La Ruta de la Bot\u00e1nica vuelve al Festival Puerto de Ideas"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/valparaiso\/#website","url":"https:\/\/dev.explora.cl\/valparaiso\/","name":"Valpara\u00edso","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization","name":"Valpara\u00edso","url":"https:\/\/dev.explora.cl\/valparaiso\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","width":2035,"height":584,"caption":"Valpara\u00edso"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d","name":"jcastaneda","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g","caption":"jcastaneda"},"url":"https:\/\/dev.explora.cl\/valparaiso\/author\/jcastaneda\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/comments?post=41678"}],"version-history":[{"count":3,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41678\/revisions"}],"predecessor-version":[{"id":41683,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41678\/revisions\/41683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media\/41679"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media?parent=41678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/categories?post=41678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/tags?post=41678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}