{"id":41432,"date":"2021-08-26T14:09:24","date_gmt":"2021-08-26T18:09:24","guid":{"rendered":"https:\/\/dev.explora.cl\/valparaiso\/?p=41432"},"modified":"2021-10-04T14:00:23","modified_gmt":"2021-10-04T17:00:23","slug":"congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/","title":{"rendered":"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias"},"content":{"rendered":"<h3>Para algunos\/as estudiantes de la regi\u00f3n, realizar investigaci\u00f3n e innovaci\u00f3n escolar dentro de sus establecimientos educacionales ha significado un camino sin retorno al fascinante mundo de las ciencias y para muchos y muchas, el pase fundamental para llegar a la carrera de sus sue\u00f1os.<\/h3>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400\">Aprender a trabajar en equipo, conocer nuevas realidades y fomentar el pensamiento cr\u00edtico, son algunos de los conceptos que m\u00e1s se repiten a la hora de preguntarle a los y las estudiantes sobre las<\/span><a href=\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\"> <b>Academias Explora y los proyectos que han desarrollado en investigaci\u00f3n e innovaci\u00f3n escolar (IIE)<\/b><\/a><span style=\"font-weight: 400\"> dentro y fuera de sus establecimientos educacionales, apoyados por el Programa Explora por m\u00e1s de dos d\u00e9cadas. Para socializar estos proyectos con sus pares y la comunidad, se realizan los <\/span><b>Congresos Explora<\/b><span style=\"font-weight: 400\">, en donde han participado activamente miles de estudiantes de la regi\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La posibilidad de pensar junto a otros y otras es parte fundamental del proceso de IIE y a trav\u00e9s de actividades cient\u00edficas, los ni\u00f1os ni\u00f1as y j\u00f3venes logran comprender ciertos procesos que muchas veces los llevan a hacerse interrogantes que no siempre est\u00e1n ligadas a lo estrictamente cient\u00edfico; existe un abanico de posibilidades en donde aprenden a plantearse problemas, pasar obst\u00e1culos y buscar soluciones, en m\u00faltiples disciplinas<\/span><span style=\"font-weight: 400\">. <\/span><span style=\"font-weight: 400\">Para Diego Parraguez, de 17 a\u00f1os, y quien cursa actualmente cuarto medio en el Colegio Arauco de Quillota, la experiencia de a\u00f1os anteriores haciendo IIE lo tiene determinado a entrar a la carrera de Medicina.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/dev.explora.cl\/valparaiso\/mas-de-cien-proyectos-participaron-de-los-congresos-provinciales-de-las-ciencias-y-la-tecnologia-explora-2019\/img_5469\/\" rel=\"attachment wp-att-39642\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-39642 alignleft\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-300x200.jpg 300w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-768x512.jpg 768w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u201cMis asignaturas favoritas son biolog\u00eda y matem\u00e1ticas, pero siempre busqu\u00e9 adquirir nuevos conocimientos en otras \u00e1reas. Cuando entr\u00e9 a la<\/span><b> Academia Explora <\/b><span style=\"font-weight: 400\">de mi colegio comenzamos a trabajar sin muchas expectativas, pero el proyecto que investigamos fue \u201cagarrando vuelo\u201d y nos fue ganando en pasi\u00f3n, por lo que llegamos incluso al Congreso Nacional, el 2018\u201d, cuenta el estudiante.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En la oportunidad, Parraguez, junto a su docente gu\u00eda y sus compa\u00f1eros\/as de equipo, pudieron ser parte de un encuentro \u00fanico. \u201cMi experiencia en los Congresos fue muy agradable porque hab\u00eda una gran cantidad de j\u00f3venes con los cuales pod\u00edamos conversar y entablar nuevas amistades. Adem\u00e1s, el hecho de haber trabajado con un asesor cient\u00edfico fue de gran ayuda en toda la investigaci\u00f3n, porque se sent\u00eda como un compa\u00f1ero m\u00e1s del proyecto y era muy motivante escucharlo hablar y aprender de \u00e9l, ya que se notaba que las ciencias eran su pasi\u00f3n\u201d, agrega.<\/span><\/p>\n<p><b>Seguir el camino de las ciencias<\/b><\/p>\n<p><span style=\"font-weight: 400\">Para la Dra. Mar\u00eda Elena Tarnok, realizar investigaci\u00f3n e innovaci\u00f3n escolar en su colegio y participar de los Congresos, tambi\u00e9n fue el detonante para que la ahora bioqu\u00edmica de la Pontificia Universidad Cat\u00f3lica de Valpara\u00edso (PUCV) decidiera seguir el camino de las ciencias. El 2006, Tarnok -junto a su compa\u00f1era Andrea Oyarce- particip\u00f3 del Congreso Regional Explora con un estudio sobre la evoluci\u00f3n de los caparazones de los caracoles de tierra y de mar; siendo seleccionadas para representar a la regi\u00f3n en la instancia nacional, que dicho a\u00f1o se llev\u00f3 a cabo en la Regi\u00f3n de Coquimbo.<a href=\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/mariaelenatarnok\/\" rel=\"attachment wp-att-41435\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-41435 alignright\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/08\/Mar\u00edaElenaTarnok-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/08\/Mar\u00edaElenaTarnok-300x225.jpg 300w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/08\/Mar\u00edaElenaTarnok.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cMe enter\u00e9 del Programa Explora en tercero medio a trav\u00e9s de mi profesora de biolog\u00eda Mirtha Andaur, en el Liceo N\u00b02 de Ni\u00f1as Matilde Brandau de Ross de Valpara\u00edso. Siempre me gust\u00f3 mucho la qu\u00edmica y la biolog\u00eda y esta profesora era muy motivada con nosotras sus estudiantes, para que particip\u00e1ramos de este tipo de actividades extracurriculares. La verdad es que fue en esa \u00e9poca en que decid\u00ed estudiar bioqu\u00edmica, debido al proyecto en el que est\u00e1bamos trabajando, pero lo principal que aprend\u00ed en ese tiempo, fue a realizar un proyecto bas\u00e1ndome en el m\u00e9todo cient\u00edfico, el cual utilizo hasta el d\u00eda de hoy\u201d, cuenta la profesional.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cRespecto a mi participaci\u00f3n en los Congresos, sin duda que son instancias ideales para interactuar con otros grupos de investigaci\u00f3n. Yo era un poco t\u00edmida, as\u00ed que recuerdo<\/span><span style=\"font-weight: 400\"> que me pon\u00eda muy nerviosa al momento de exponer delante de todas las personas. En una ocasi\u00f3n, hab\u00eda un periodista de Explora que se me acerc\u00f3 y me dijo que a medida que fuera realizando m\u00e1s presentaciones, con el tiempo ya no me pondr\u00eda tan nerviosa y que con la pr\u00e1ctica podr\u00eda dominarlo, que a \u00e9l tambi\u00e9n le hab\u00eda pasado; as\u00ed que con su consejo qued\u00e9 mucho m\u00e1s tranquila\u201d, cuenta la tambi\u00e9n profesora de Qu\u00edmica General de la Facultad de Ciencias de la PUCV.<\/span><\/p>\n<p><b>Trayectoria cient\u00edfica y universidad<\/b><\/p>\n<p><span style=\"font-weight: 400\">Para Constanza Cisternas, de 18 a\u00f1os y estudiante de primer a\u00f1o de la carrera Ingenier\u00eda Civil Industrial en la Universidad T\u00e9cnica Federico Santa Mar\u00eda (USM), la posibilidad de hacer investigaci\u00f3n e innovaci\u00f3n escolar en su colegio signific\u00f3 no solo aprender nuevos conocimientos y la posibilidad de hacer amigos y amigas con intereses en com\u00fan; fue su pase para ingresar a la universidad a trav\u00e9s del <\/span><b>Cupo Explora**.<\/b><\/p>\n<p><span style=\"font-weight: 400\">\u201cMis asignaturas favoritas siempre fueron ligadas a las ciencias, as\u00ed que cuando se implement\u00f3 un taller de rob\u00f3tica en mi colegio no dud\u00e9 en participar. Luego, y ya en primero medio, nuestro profesor de biolog\u00eda, Pablo Castillo, nos mostr\u00f3 las <\/span><b>Academias Explora<\/b><span style=\"font-weight: 400\"> y lo que significa hacer proyectos de investigaci\u00f3n. Primero particip\u00e9 apoyando a compa\u00f1eros\/as m\u00e1s grandes, pero luego, en segundo y tercero medio, pude ser parte de los proyectos en su totalidad, haciendo l\u00e1minas e informes y participando de los Congresos el 2018 y el 2019<\/span><span style=\"font-weight: 400\">\u201d, cuenta la universitaria.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/dev.explora.cl\/valparaiso\/banner3\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-39155 alignleft\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/banner3-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/banner3-300x185.jpg 300w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/banner3.jpg 736w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u201cLo principal que aprend\u00ed durante el tiempo en las Academias Explora fue a trabajar en equipo, a adquirir nuevas habilidades y a trabajar la disciplina y la tolerancia. Para m\u00ed era un sue\u00f1o entrar a la USM y cuando me enter\u00e9 del <\/span><b>Cupo Explora<\/b><span style=\"font-weight: 400\">, se me meti\u00f3 en la cabeza que deb\u00eda postular y como contaba con los requisitos de trayectoria cient\u00edfica para acceder, me puse a reunir todo lo necesario para que, independiente de mi puntaje, se diera esa posibilidad y afortunadamente, pude matricularme gracias al Cupo\u201d, a\u00f1ade la egresada del Colegio San Ignacio de La Salle, de Quillota.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Frente a estos y otros testimonios de estudiantes de la regi\u00f3n, Mabel Keller, directora de Explora Valpara\u00edso reflexiona: \u201cEn los \u00faltimos a\u00f1os, nuestro objetivo de llevar las Academias Explora a m\u00e1s estudiantes y a m\u00e1s rincones de la Regi\u00f3n de Valpara\u00edso se ha llevado a cabo con mucho esfuerzo y dedicaci\u00f3n. Es por ello, que como proyecto nos pone muy contentos y contentas <\/span><span style=\"font-weight: 400\">de que las competencias que adquieren estos\/as estudiantes les sirvan en su desarrollo profesional, ya sea en el camino de las ciencias naturales, sociales o en cualquier otra disciplina del conocimiento que decidan seguir&#8221;<\/span><span style=\"font-weight: 400\">, comenta.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Actualmente, se encuentran abierta hasta el 12 de septiembre las<a href=\"https:\/\/dev.explora.cl\/valparaiso\/abiertas-las-postulaciones-al-congreso-regional-de-investigacion-e-innovacion-escolar-de-la-region-de-valparaiso\/banner_web\/\" rel=\"attachment wp-att-41389\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-41389 size-medium\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/08\/Banner_Web-300x186.png\" alt=\"\" width=\"300\" height=\"186\" \/><\/a> postulaciones para participar del <\/span><b>Congreso Regional de Investigaci\u00f3n e Innovaci\u00f3n Escolar, que este 2021 se realizar\u00e1 de manera virtual. <\/b><span style=\"font-weight: 400\">Para revisar las bases y todos los detalles,<\/span><a href=\"https:\/\/dev.explora.cl\/valparaiso\/abiertas-las-postulaciones-al-congreso-regional-de-investigacion-e-innovacion-escolar-de-la-region-de-valparaiso\/\"> <span style=\"font-weight: 400\">puedes hacer click aqu\u00ed.<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Si quieres conocer m\u00e1s sobre la Investigaci\u00f3n e Investigaci\u00f3n Escolar y sobre el trabajo que realiza Explora Valpara\u00edso, visita <\/span><a href=\"http:\/\/www.academiasdev.explora.cl\/\"><span style=\"font-weight: 400\">www.academiasdev.explora.cl<\/span><\/a><span style=\"font-weight: 400\"> o sigue a @exploravalpo en Facebook, Twitter e Instagram.\u00a0<\/span><\/p>\n<p><em><span style=\"font-weight: 400\">**Es importante destacar, que el Cupo Explora es una v\u00eda de acceso especial que busca ofrecerles a estudiantes con trayectoria y compromiso por la investigaci\u00f3n y la innovaci\u00f3n, la posibilidad de acceder a la educaci\u00f3n superior en diversas carreras relacionadas a las ciencias b\u00e1sicas, ingenier\u00edas, ciencias sociales y muchas otras disciplinas.\u00a0<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para algunos\/as estudiantes de la regi\u00f3n, realizar investigaci\u00f3n e innovaci\u00f3n escolar dentro de sus establecimientos educacionales ha significado un camino sin retorno al fascinante mundo de las ciencias y para muchos y muchas, el pase fundamental para llegar a la carrera de sus sue\u00f1os.<\/p>\n","protected":false},"author":22,"featured_media":37988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[522,339,101,1062,392,110,23,210,986,946,580,1061,166],"class_list":["post-41432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-academias-explora","tag-ciencia-regional","tag-congreso-regional","tag-congreso-regional-explora","tag-congresos","tag-cultura-cientifica","tag-explora","tag-exposiciones","tag-iie","tag-investigacion-e-innovacion-escolar","tag-investigacion-escolar","tag-ponencias","tag-proyecto-asociativo-regional-explora-valparaiso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias - Valpara\u00edso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias - Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Para algunos\/as estudiantes de la regi\u00f3n, realizar investigaci\u00f3n e innovaci\u00f3n escolar dentro de sus establecimientos educacionales ha significado un camino sin retorno al fascinante mundo de las ciencias y para muchos y muchas, el pase fundamental para llegar a la carrera de sus sue\u00f1os.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-26T18:09:24+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-04T17:00:23+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1992\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1328\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"jcastaneda\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"jcastaneda\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\"},\"author\":{\"name\":\"jcastaneda\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d\"},\"headline\":\"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias\",\"datePublished\":\"2021-08-26T18:09:24+00:00\",\"dateModified\":\"2021-10-04T17:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\"},\"wordCount\":1322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg\",\"keywords\":[\"Academias EXPLORA\",\"ciencia regional\",\"Congreso Regional\",\"Congreso Regional Explora\",\"CONGRESOS\",\"cultura cientifica\",\"EXPLORA\",\"exposiciones\",\"IIE\",\"investigaci\u00f3n e innovaci\u00f3n escolar\",\"investigaci\u00f3n escolar\",\"ponencias\",\"Proyecto Asociativo Regional EXPLORA Valparaiso\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\",\"name\":\"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias - Valpara\u00edso\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg\",\"datePublished\":\"2021-08-26T18:09:24+00:00\",\"dateModified\":\"2021-10-04T17:00:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg\",\"width\":1992,\"height\":1328},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/valparaiso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"name\":\"Valpara\u00edso\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\",\"name\":\"Valpara\u00edso\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"width\":2035,\"height\":584,\"caption\":\"Valpara\u00edso\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d\",\"name\":\"jcastaneda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g\",\"caption\":\"jcastaneda\"},\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/author\/jcastaneda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias - Valpara\u00edso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/","og_locale":"es_ES","og_type":"article","og_title":"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias - Valpara\u00edso","og_description":"Para algunos\/as estudiantes de la regi\u00f3n, realizar investigaci\u00f3n e innovaci\u00f3n escolar dentro de sus establecimientos educacionales ha significado un camino sin retorno al fascinante mundo de las ciencias y para muchos y muchas, el pase fundamental para llegar a la carrera de sus sue\u00f1os.","og_url":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/","og_site_name":"Valpara\u00edso","article_published_time":"2021-08-26T18:09:24+00:00","article_modified_time":"2021-10-04T17:00:23+00:00","og_image":[{"width":1992,"height":1328,"url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg","type":"image\/jpeg"}],"author":"jcastaneda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jcastaneda","Tiempo estimado de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/"},"author":{"name":"jcastaneda","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d"},"headline":"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias","datePublished":"2021-08-26T18:09:24+00:00","dateModified":"2021-10-04T17:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/"},"wordCount":1322,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg","keywords":["Academias EXPLORA","ciencia regional","Congreso Regional","Congreso Regional Explora","CONGRESOS","cultura cientifica","EXPLORA","exposiciones","IIE","investigaci\u00f3n e innovaci\u00f3n escolar","investigaci\u00f3n escolar","ponencias","Proyecto Asociativo Regional EXPLORA Valparaiso"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/","url":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/","name":"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias - Valpara\u00edso","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg","datePublished":"2021-08-26T18:09:24+00:00","dateModified":"2021-10-04T17:00:23+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#primaryimage","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/04\/IMG_2216-1.jpg","width":1992,"height":1328},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/valparaiso\/congresos-y-proyectos-de-iie-un-fructifero-camino-para-perseguir-una-carrera-en-las-ciencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/valparaiso\/"},{"@type":"ListItem","position":2,"name":"Congresos y proyectos de IIE: un fruct\u00edfero camino para perseguir una carrera en las ciencias"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/valparaiso\/#website","url":"https:\/\/dev.explora.cl\/valparaiso\/","name":"Valpara\u00edso","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization","name":"Valpara\u00edso","url":"https:\/\/dev.explora.cl\/valparaiso\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","width":2035,"height":584,"caption":"Valpara\u00edso"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d","name":"jcastaneda","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g","caption":"jcastaneda"},"url":"https:\/\/dev.explora.cl\/valparaiso\/author\/jcastaneda\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/comments?post=41432"}],"version-history":[{"count":7,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41432\/revisions"}],"predecessor-version":[{"id":41440,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41432\/revisions\/41440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media\/37988"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media?parent=41432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/categories?post=41432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/tags?post=41432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}