{"id":41234,"date":"2021-07-02T13:08:36","date_gmt":"2021-07-02T17:08:36","guid":{"rendered":"https:\/\/dev.explora.cl\/valparaiso\/?p=41234"},"modified":"2021-08-02T16:57:06","modified_gmt":"2021-08-02T20:57:06","slug":"transformando-realidades-a-traves-de-las-ciencias","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/","title":{"rendered":"Reportaje: Transformando realidades a trav\u00e9s de las ciencias"},"content":{"rendered":"<h3><span style=\"font-weight: 400\">Desde el 2014, m\u00e1s de 6 mil escolares de la Regi\u00f3n de Valpara\u00edso han sido parte de las Academias Explora, espacios en que ni\u00f1os, ni\u00f1as y j\u00f3venes, con la gu\u00eda de sus docentes y el apoyo de la comunidad cient\u00edfica, realizan proyectos a partir de sus propios intereses e inquietudes.\u00a0 <\/span><\/h3>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400\">La inequidad de G\u00e9nero, el bullying, la creaci\u00f3n de distintos dispositivos para mejorar la calidad de vida y much\u00edsimas otras ideas han sido parte de los cientos de proyectos que ni\u00f1os, ni\u00f1as y j\u00f3venes de toda la Regi\u00f3n de Valpara\u00edso, han realizado desde el 2014 a trav\u00e9s de las Academias Explora, impulsadas por el Proyecto Explora Valpara\u00edso del Ministerio de Ciencia, Tecnolog\u00eda, Conocimiento e Innovaci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">La idea principal de este espacio, es que los y las escolares echen a volar su curiosidad, y a trav\u00e9s de un trabajo en equipo, que involucra a un\/a docente gu\u00eda, y el apoyo de la comunidad cient\u00edfica; realicen proyectos de investigaci\u00f3n e innovaci\u00f3n, mirando a su alrededor; y poniendo en marcha sus ideas e intereses.<\/span><a href=\"https:\/\/dev.explora.cl\/valparaiso\/mas-de-cien-proyectos-participaron-de-los-congresos-provinciales-de-las-ciencias-y-la-tecnologia-explora-2019\/img_5469\/\" rel=\"attachment wp-att-39642\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39642 size-medium alignleft\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-300x200.jpg\" alt=\"CRECyT 2019\" width=\"300\" height=\"200\" srcset=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-300x200.jpg 300w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-768x512.jpg 768w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/10\/IMG_5469-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400\">\u201cLo que pretendemos con las Academias Explora es aportar un grano de arena en la formaci\u00f3n de futuras generaciones m\u00e1s conscientes con su entorno; capaces de ejercer juicio cr\u00edtico, con pensamiento reflexivo y que puedan tomar decisiones basadas en evidencias. Para lograrlo, trabajamos a trav\u00e9s de una ruta metodol\u00f3gica con el apoyo de todas las Universidades del Consejo de Rectores de Valpara\u00edso, con cientos de escuelas de cordillera a costa, y con escolares motivados y motivadas con sus ideas, las distintas disciplinas de las ciencias y el conocimiento\u201d, cuenta Mabel Keller, Directora de Explora Valpara\u00edso.\u00a0<\/span><\/p>\n<p><b>Investigaci\u00f3n e innovaci\u00f3n escolar de cordillera a mar\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">El Cerro Mercacha, ubicado en la comuna de Los Andes, fue el punto de partida para que ni\u00f1os y j\u00f3venes de la Escuela El Sauce, se preguntaran por sus petroglifos y la relaci\u00f3n con las culturas originarias que habitaban este territorio hace miles de a\u00f1os atr\u00e1s. \u201cLa idea surge a trav\u00e9s de las actividades en celebraci\u00f3n del We Tripantu, que se organizaba en nuestro establecimiento. Fue en aquella instancia que el Baile Chino adoratorio cerro Mercacha realiza el ascenso al cerro del mismo nombre (\u2026) ah\u00ed que estudiantes me hicieron preguntas como \u2018profe profe: \u00bfQu\u00e9 hay o tiene el cerro?, \u00bfCu\u00e1les son sus secretos o misterios? \u00bfPor qu\u00e9 hay piedras con figuras o escritos en ellas? \u00bfPor qu\u00e9 se ve todo el Valle desde ese lugar y el monte Aconcagua?\u2019\u201d, cuenta el docente Carlos Montenegro, quien junto a sus estudiantes comenzaron entonces el camino de la investigaci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">As\u00ed naci\u00f3 \u201cCerro Mercachas, Observatorio Pre-Incaico: El Machupichu de Aconcagua\u201d, proyecto que por m\u00e1s de ocho a\u00f1os tuvo a estudiantes recorriendo este cerro y realizando observaci\u00f3n astron\u00f3mica, para descubrir el v\u00ednculo de estos milenarios dibujos con las constelaciones.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">La investigaci\u00f3n, que ha sido destacada en instancias nacionales e internacionales, como Congresos Explora, el Congreso Latinoamericano de Ciencias en M\u00e9xico y el Congreso Iberoamericano en Brasil, ha provocado tambi\u00e9n que escolares y sus familias, cuiden y valoren su entorno desde otras miradas, agreg\u00e1ndole un valor cultural, patrimonial y astron\u00f3mico al sector.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cEl impacto de los estudiantes ha cruzado y\u00a0 roto varias fronteras, desde lo emocional como as\u00ed tambi\u00e9n desde el punto de vista de su identidad. D\u00eda a d\u00eda los estudiantes cuidan m\u00e1s su legado, patrimonio, su inter\u00e9s por sus ra\u00edces y por la arqueoastronom\u00eda. Hoy despu\u00e9s de a\u00f1os, nos encontramos con ex alumnos que siguen realizando el ascenso al cerro\u201d, cuenta el profesor Montenegro, quien hasta el 2020 fue parte de las Academias Explora.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al igual que la Escuela El Sauce de Los Andes; las escolares Abigail Ram\u00edrez y Noemi Casanova del Liceo T\u00e9cnico Profesional de Papudo, en la costa de la Regi\u00f3n de Valpara\u00edso, se hicieron una pregunta, esta vez mirando el bosque que tienen en su comuna. \u201cUn d\u00eda nos hicieron una charla sobre el bosque escler\u00f3filo, y nos gust\u00f3 tanto que decidimos investigar que flora se encontraba ah\u00ed, para posteriormente dar a conocer su importancia. Nos llam\u00f3 la atenci\u00f3n lo hermoso que es, que siempre est\u00e1 verde, que est\u00e1 rodeado por tanta flora y fauna y finalmente el poco resguardo que se le tiene\u201d, se\u00f1alaron ambas estudiantes, quienes el 2019 pusieron manos a la obra y realizaron esta investigaci\u00f3n que posteriormente presentaron al Congreso Regional de ese a\u00f1o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Seg\u00fan ambas j\u00f3venes, lo que m\u00e1s rescatan de la experiencia fue \u201caprender y conocer un ecosistema que se encuentra tan cerca, lo desconocido que era el tema y ahora tan valioso que es para nosotras\u201d se\u00f1alaron.\u00a0<\/span><\/p>\n<p><b>Generaciones investigando\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400\">En la misma sinton\u00eda que sus pares, j\u00f3venes de la Academia \u201cYecos del Inco\u201d del Instituto Comercial Mar\u00edtimo <a href=\"https:\/\/dev.explora.cl\/valparaiso\/abierta-la-convocatoria-2020-para-que-postules-y-conformes-tu-academia-explora\/img_1843\/\" rel=\"attachment wp-att-39576\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-39576 alignright\" src=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/09\/IMG_1843-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/09\/IMG_1843-300x225.jpg 300w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/09\/IMG_1843-768x576.jpg 768w, https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/09\/IMG_1843-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> Pac\u00edfico Sur de San Antonio, han realizado en los \u00faltimos cinco a\u00f1os proyectos relacionados a las aves y en el Humedal del R\u00edo Maipo de la zona, entre otros.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Fernanda Osorio, egresada el a\u00f1o pasado y quien fue parte de esta Academia, cree que la importancia de estas instancias es \u201cpoder conocer m\u00e1s sobre el entorno y poder expresarlo a las dem\u00e1s personas de la comunidad, para concientizar de posibles problemas\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Asimismo, la ahora estudiante de pedagog\u00eda en Biolog\u00eda cuenta que el impacto de sus investigaciones \u201cha sido positivo, ya que las personas de la comuna le han dado importancia a lugares que estaban siendo \u2018olvidados\u2019\u201d. Similar opini\u00f3n tiene el tambi\u00e9n egresado y ex participante de las Academias Explora, Alan Oliveros, para quien al \u201chacer investigaci\u00f3n de lo que nos rodea, podemos apreciar y valorar m\u00e1s lo que tenemos a nuestro alrededor y as\u00ed mismo motivar a la comunidad a hacer un cambio\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Adem\u00e1s de la huella que han dejado en la comunidad, la Academia Explora Yecos del Inco liderada por el profesor Pablo Malhue, es un grupo de escolares comprometidos con el trabajo en equipo y con el conocimiento. Uno de sus integrantes actuales, Manuel Pinochet, de 4to medio, cuenta que \u201cson incontables las experiencias que he tenido siendo parte de la Academia, investigando, aprendiendo, pas\u00e1ndolo bien. He mejorado como persona y mi forma de pensar. Han sido unos a\u00f1os geniales siendo parte de la Academia Yecos del Inco&#8221;.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Si quieres conocer m\u00e1s sobre la Investigaci\u00f3n e Investigaci\u00f3n Escolar y sobre el trabajo que realiza Explora Valpara\u00edso en Investigaci\u00f3n e Innovaci\u00f3n Escolar, visita <\/span><a href=\"http:\/\/www.academiasdev.explora.cl\"><span style=\"font-weight: 400\">www.academiasdev.explora.cl<\/span><\/a><span style=\"font-weight: 400\"> o sigue a @exploravalpo en Facebook, Twitter e Instagram.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el 2014, m\u00e1s de 6 mil escolares de la Regi\u00f3n de Valpara\u00edso han sido parte de las Academias Explora, espacios en que ni\u00f1os, ni\u00f1as y j\u00f3venes, con la gu\u00eda de sus docentes y el apoyo de la comunidad cient\u00edfica, realizan proyectos a partir de sus propios intereses e inquietudes.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":41272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[522,1030,339,685,694,652,110,23,986,14,946,166,174,204],"class_list":["post-41234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-academias-explora","tag-alcance-territorial","tag-ciencia-regional","tag-competencias-cientificas","tag-competencias-transversales","tag-congresos-explora","tag-cultura-cientifica","tag-explora","tag-iie","tag-investigacion-cientifica-escolar","tag-investigacion-e-innovacion-escolar","tag-proyecto-asociativo-regional-explora-valparaiso","tag-region-de-valparaiso","tag-valparaiso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reportaje: Transformando realidades a trav\u00e9s de las ciencias - Valpara\u00edso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Reportaje: Transformando realidades a trav\u00e9s de las ciencias - Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Desde el 2014, m\u00e1s de 6 mil escolares de la Regi\u00f3n de Valpara\u00edso han sido parte de las Academias Explora, espacios en que ni\u00f1os, ni\u00f1as y j\u00f3venes, con la gu\u00eda de sus docentes y el apoyo de la comunidad cient\u00edfica, realizan proyectos a partir de sus propios intereses e inquietudes.\u00a0\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T17:08:36+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T20:57:06+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45-1024x555.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"jcastaneda\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"jcastaneda\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\"},\"author\":{\"name\":\"jcastaneda\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d\"},\"headline\":\"Reportaje: Transformando realidades a trav\u00e9s de las ciencias\",\"datePublished\":\"2021-07-02T17:08:36+00:00\",\"dateModified\":\"2021-08-02T20:57:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\"},\"wordCount\":1150,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png\",\"keywords\":[\"Academias EXPLORA\",\"alcance territorial\",\"ciencia regional\",\"Competencias Cient\u00edficas\",\"Competencias transversales\",\"Congresos Explora\",\"cultura cientifica\",\"EXPLORA\",\"IIE\",\"investigaci\u00f3n cient\u00edfica escolar\",\"investigaci\u00f3n e innovaci\u00f3n escolar\",\"Proyecto Asociativo Regional EXPLORA Valparaiso\",\"Regi\u00f3n de Valpara\u00edso\",\"valparaiso\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\",\"name\":\"Reportaje: Transformando realidades a trav\u00e9s de las ciencias - Valpara\u00edso\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png\",\"datePublished\":\"2021-07-02T17:08:36+00:00\",\"dateModified\":\"2021-08-02T20:57:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png\",\"width\":1921,\"height\":1041},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/valparaiso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reportaje: Transformando realidades a trav\u00e9s de las ciencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"name\":\"Valpara\u00edso\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\",\"name\":\"Valpara\u00edso\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"width\":2035,\"height\":584,\"caption\":\"Valpara\u00edso\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d\",\"name\":\"jcastaneda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g\",\"caption\":\"jcastaneda\"},\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/author\/jcastaneda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reportaje: Transformando realidades a trav\u00e9s de las ciencias - Valpara\u00edso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/","og_locale":"es_ES","og_type":"article","og_title":"Reportaje: Transformando realidades a trav\u00e9s de las ciencias - Valpara\u00edso","og_description":"Desde el 2014, m\u00e1s de 6 mil escolares de la Regi\u00f3n de Valpara\u00edso han sido parte de las Academias Explora, espacios en que ni\u00f1os, ni\u00f1as y j\u00f3venes, con la gu\u00eda de sus docentes y el apoyo de la comunidad cient\u00edfica, realizan proyectos a partir de sus propios intereses e inquietudes.\u00a0","og_url":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/","og_site_name":"Valpara\u00edso","article_published_time":"2021-07-02T17:08:36+00:00","article_modified_time":"2021-08-02T20:57:06+00:00","og_image":[{"width":1024,"height":555,"url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45-1024x555.png","type":"image\/png"}],"author":"jcastaneda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jcastaneda","Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/"},"author":{"name":"jcastaneda","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d"},"headline":"Reportaje: Transformando realidades a trav\u00e9s de las ciencias","datePublished":"2021-07-02T17:08:36+00:00","dateModified":"2021-08-02T20:57:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/"},"wordCount":1150,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png","keywords":["Academias EXPLORA","alcance territorial","ciencia regional","Competencias Cient\u00edficas","Competencias transversales","Congresos Explora","cultura cientifica","EXPLORA","IIE","investigaci\u00f3n cient\u00edfica escolar","investigaci\u00f3n e innovaci\u00f3n escolar","Proyecto Asociativo Regional EXPLORA Valparaiso","Regi\u00f3n de Valpara\u00edso","valparaiso"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/","url":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/","name":"Reportaje: Transformando realidades a trav\u00e9s de las ciencias - Valpara\u00edso","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png","datePublished":"2021-07-02T17:08:36+00:00","dateModified":"2021-08-02T20:57:06+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#primaryimage","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2021\/07\/web45.png","width":1921,"height":1041},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/valparaiso\/transformando-realidades-a-traves-de-las-ciencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/valparaiso\/"},{"@type":"ListItem","position":2,"name":"Reportaje: Transformando realidades a trav\u00e9s de las ciencias"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/valparaiso\/#website","url":"https:\/\/dev.explora.cl\/valparaiso\/","name":"Valpara\u00edso","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization","name":"Valpara\u00edso","url":"https:\/\/dev.explora.cl\/valparaiso\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","width":2035,"height":584,"caption":"Valpara\u00edso"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/c15e69495b8dbe0af0102f6bca43ba5d","name":"jcastaneda","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f26661a8eef2f6444d9633928ef0219fd69e41c5be1ef5ef16afeee7cd4df675?s=96&d=mm&r=g","caption":"jcastaneda"},"url":"https:\/\/dev.explora.cl\/valparaiso\/author\/jcastaneda\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/comments?post=41234"}],"version-history":[{"count":6,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41234\/revisions"}],"predecessor-version":[{"id":41275,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/41234\/revisions\/41275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media\/41272"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media?parent=41234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/categories?post=41234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/tags?post=41234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}