{"id":38266,"date":"2015-09-01T00:00:00","date_gmt":"2015-09-01T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/valparaiso\/blog\/2015\/09\/01\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota\/"},"modified":"2019-05-20T17:00:37","modified_gmt":"2019-05-20T17:00:37","slug":"visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/","title":{"rendered":"Visita, explora, observa, escucha y siente en el Valle de Quillota"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14464\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/09\/b7b3056cab41130e24a54167e4a60151.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<address>&nbsp;<\/address>\n<address>La exposici\u00f3n itinerante e interactiva \u201cExplorando tus Sentidos\u201d del PAR EXPLORA Valpara\u00edso contin\u00faa su recorrido instal\u00e1ndose hasta el 14 de septiembre en el Colegio Valle de Quillota.<\/p>\n<hr \/>\n<\/address>\n<p style=\"text-align: justify\"><span style=\"font-size: 8.5pt;font-family: Arial, sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-14465\" style=\"margin-bottom: 5px;margin-left: 15px;float: right\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/09\/Sentidos-1.jpg\" alt=\"Sentidos-1\" width=\"400\" height=\"300\" \/><\/span>Durante la primera quincena de septiembre &#8220;Explorando tus sentidos&#8221; visitar\u00e1 a los m\u00e1s peque\u00f1os de la Provincia de Quillota, invit\u00e1ndolos a una experiencia interactiva de aprendizaje que les ayudar\u00e1 conocer y valorar las principales formas en que nuestro cuerpo percibe el mundo. La exposici\u00f3n est\u00e1 dise\u00f1ada para estudiantes de K\u00ednder a Cuarto B\u00e1sico y durante 2015 ya visit\u00f3 a peque\u00f1os curiosos de San Felipe, Los Andes y Calle Larga.<\/p>\n<p>La exhibici\u00f3n cuenta de 7 m\u00f3dulos con experiencias l\u00fadicas inspiradas en los cinco sentidos que apuntan a reforzar lo aprendido en el aula: c\u00e1mara oscura, loter\u00eda de aromas, dilatador de pupilas, cilindros oscuros, loter\u00eda de sonidos, relaci\u00f3n tono-frecuencia y experiencias de degustaci\u00f3n. La interacci\u00f3n se complementa con paneles informativos y gu\u00edas capacitadas que acompa\u00f1an a los ni\u00f1os y ni\u00f1as mientras disfrutan conociendo un poco m\u00e1s de la vista, el tacto, el gusto, la audici\u00f3n y el olfato.<\/p>\n<p>La exposici\u00f3n se encontrar\u00e1 disponible para visitas hasta el 14 de septiembre en el <span style=\"text-decoration: underline\"><strong>Colegio Valle de Quillota<\/strong><\/span> (Merced 111, Quillota). Para visitas programadas es necesario contactarse con <span style=\"text-decoration: underline\"><strong>Carolin P\u00e9rez Catal\u00e1n<\/strong><\/span>, coordinadora del Programa de Desarrollo Extracurricular DAEM Red Q, tel\u00e9fono: (033) 229 6609 y celular 5414 2840.<\/p>\n<p>&#8220;Explorando tus sentidos&#8221; forma parte de un cat\u00e1logo de contenidos cient\u00edficos que el Proyecto Asociativo Regional, PAR EXPLORA Valpara\u00edso mantiene en recorrido por la regi\u00f3n, contribuyendo a la apropiaci\u00f3n y valoraci\u00f3n del conocimiento cient\u00edfico en la comunidad. Su itinerancia se debe al trabajo conjunto entre el PAR EXPLORA y la Red Territorial de Coordinadores Comunales e Institucional, que re\u00fane a colaboradores de municipios de todas las comunas de la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La exposici\u00f3n itinerante e interactiva \u201cExplorando tus Sentidos\u201d del PAR EXPLORA Valpara\u00edso contin\u00faa su recorrido instal\u00e1ndose hasta el 14 de septiembre en el Colegio Valle de Quillota. Durante la primera quincena de septiembre &#8220;Explorando tus sentidos&#8221; visitar\u00e1 a los m\u00e1s peque\u00f1os de la Provincia de Quillota, invit\u00e1ndolos a una experiencia interactiva de aprendizaje que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[247,156,401,166,402],"class_list":["post-38266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-explorando-tus-sentidos","tag-exposicion","tag-interactivo","tag-proyecto-asociativo-regional-explora-valparaiso","tag-sentidos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Visita, explora, observa, escucha y siente en el Valle de Quillota - Valpara\u00edso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Visita, explora, observa, escucha y siente en el Valle de Quillota - Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"&nbsp; La exposici\u00f3n itinerante e interactiva \u201cExplorando tus Sentidos\u201d del PAR EXPLORA Valpara\u00edso contin\u00faa su recorrido instal\u00e1ndose hasta el 14 de septiembre en el Colegio Valle de Quillota. Durante la primera quincena de septiembre &#8220;Explorando tus sentidos&#8221; visitar\u00e1 a los m\u00e1s peque\u00f1os de la Provincia de Quillota, invit\u00e1ndolos a una experiencia interactiva de aprendizaje que [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-01T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:00:37+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Visita, explora, observa, escucha y siente en el Valle de Quillota\",\"datePublished\":\"2015-09-01T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg\",\"keywords\":[\"explorando tus sentidos\",\"exposici\u00f3n\",\"interactivo\",\"Proyecto Asociativo Regional EXPLORA Valparaiso\",\"sentidos\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\",\"name\":\"Visita, explora, observa, escucha y siente en el Valle de Quillota - Valpara\u00edso\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg\",\"datePublished\":\"2015-09-01T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:00:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/valparaiso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visita, explora, observa, escucha y siente en el Valle de Quillota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"name\":\"Valpara\u00edso\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\",\"name\":\"Valpara\u00edso\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"width\":2035,\"height\":584,\"caption\":\"Valpara\u00edso\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita, explora, observa, escucha y siente en el Valle de Quillota - Valpara\u00edso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/","og_locale":"es_ES","og_type":"article","og_title":"Visita, explora, observa, escucha y siente en el Valle de Quillota - Valpara\u00edso","og_description":"&nbsp; La exposici\u00f3n itinerante e interactiva \u201cExplorando tus Sentidos\u201d del PAR EXPLORA Valpara\u00edso contin\u00faa su recorrido instal\u00e1ndose hasta el 14 de septiembre en el Colegio Valle de Quillota. Durante la primera quincena de septiembre &#8220;Explorando tus sentidos&#8221; visitar\u00e1 a los m\u00e1s peque\u00f1os de la Provincia de Quillota, invit\u00e1ndolos a una experiencia interactiva de aprendizaje que [&hellip;]","og_url":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/","og_site_name":"Valpara\u00edso","article_published_time":"2015-09-01T04:00:00+00:00","article_modified_time":"2019-05-20T17:00:37+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Visita, explora, observa, escucha y siente en el Valle de Quillota","datePublished":"2015-09-01T04:00:00+00:00","dateModified":"2019-05-20T17:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg","keywords":["explorando tus sentidos","exposici\u00f3n","interactivo","Proyecto Asociativo Regional EXPLORA Valparaiso","sentidos"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/","url":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/","name":"Visita, explora, observa, escucha y siente en el Valle de Quillota - Valpara\u00edso","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg","datePublished":"2015-09-01T04:00:00+00:00","dateModified":"2019-05-20T17:00:37+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#primaryimage","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/b7b3056cab41130e24a54167e4a60151-1.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/valparaiso\/visita-explora-observa-escucha-y-siente-en-el-valle-de-quillota-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/valparaiso\/"},{"@type":"ListItem","position":2,"name":"Visita, explora, observa, escucha y siente en el Valle de Quillota"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/valparaiso\/#website","url":"https:\/\/dev.explora.cl\/valparaiso\/","name":"Valpara\u00edso","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization","name":"Valpara\u00edso","url":"https:\/\/dev.explora.cl\/valparaiso\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","width":2035,"height":584,"caption":"Valpara\u00edso"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/valparaiso\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/comments?post=38266"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38266\/revisions"}],"predecessor-version":[{"id":38725,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38266\/revisions\/38725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media\/34191"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media?parent=38266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/categories?post=38266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/tags?post=38266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}