{"id":38239,"date":"2015-08-05T00:00:00","date_gmt":"2015-08-05T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/valparaiso\/blog\/2015\/08\/05\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/"},"modified":"2019-05-20T17:00:47","modified_gmt":"2019-05-20T17:00:47","slug":"hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/","title":{"rendered":"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-11386\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/08\/d14f11d7d37eaa2ecd678ad120c11d72.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<address>La nueva exposici\u00f3n interactiva del PAR EXPLORA Valpara\u00edso est\u00e1 abierta a todo p\u00fablico en Hijuelas hasta el 21 de agosto.<\/address>\n<div>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-11387\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/08\/HolaOla1.jpg\" style=\"margin-left: 15px;margin-bottom: 5px;float: right\" alt=\"HolaOla1\" width=\"400\" height=\"300\" \/>Nuestras exposiciones interactivas, al igual que el oc\u00e9ano, est\u00e1n en un constante y permanente movimiento. Invitamos a los hijuelenses a conocer los fen\u00f3menos detr\u00e1s de estas ondas que danzan d\u00eda a d\u00eda en el contorno de la bah\u00eda con&nbsp;\u201c<strong>Hola Ola: Navegando al comp\u00e1s del mar<\/strong>\u201d; la nueva exposici\u00f3n itinerante e interactiva de la colecci\u00f3n que el Proyecto Asociativo Regional,<strong> PAR EXPLORA Valpara\u00edso<\/strong> pone a disposici\u00f3n de la comunidad para facilitar su experiencia directa con el conocimiento cient\u00edfico y tecnol\u00f3gico en la regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">La exposici\u00f3n, dise\u00f1ada para encantar a todo p\u00fablico, cuenta con cinco m\u00f3dulos tem\u00e1ticos interactivos en los cuales el visitante podr\u00e1 aprender de forma l\u00fadica acerca de las olas y fen\u00f3menos: Qu\u00e9 son y c\u00f3mo se forman, sus tipos, por qu\u00e9 rompen, qu\u00e9 pasa cuando se encuentran con un obst\u00e1culo, y c\u00f3mo es que se mueven las part\u00edculas de agua en su interior. La interacci\u00f3n se complementa con paneles informativos y monitores capacitados, los que acompa\u00f1ar\u00e1n a los interesados en el recorrido.<\/p>\n<p style=\"text-align: justify\"><strong>\u201cHola Ola\u201d se podr\u00e1 visitar hasta el 21 de agosto en el&nbsp;Hall Municipal de la Ilustre Municipalidad de Hijuelas&nbsp;(Manuel Rodr\u00edguez 1665, Hijuelas). Para concertar visitas debe comunicarse con el Departamento de Educaci\u00f3n de la Municipalidad en los tel\u00e9fonos (33) 229 0120 y (33) 229 0135<\/strong><\/p>\n<p style=\"text-align: justify\">La itinerancia de estos contenidos es posible gracias al trabajo conjunto del<strong> PAR EXPLORA Valpara\u00edso<\/strong> y la Red Territorial de Coordinadores Comunales e Institucionales, que re\u00fane a colaboradores de municipios de todas las comunas de la regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">Para m\u00e1s informaci\u00f3n sobre la exposici\u00f3n y el contenido de sus m\u00f3dulos visita&nbsp;<span style=\"text-decoration: underline;color: #800080\"><strong><a href=\"valparaiso\/noticias-valparaiso\/4392-inauguracion-hola-ola-navegando-al-compas-del-mar\"><span style=\"color: #800080;text-decoration: underline\">este enlace<\/span><\/a><\/strong><\/span>.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nueva exposici\u00f3n interactiva del PAR EXPLORA Valpara\u00edso est\u00e1 abierta a todo p\u00fablico en Hijuelas hasta el 21 de agosto. Nuestras exposiciones interactivas, al igual que el oc\u00e9ano, est\u00e1n en un constante y permanente movimiento. Invitamos a los hijuelenses a conocer los fen\u00f3menos detr\u00e1s de estas ondas que danzan d\u00eda a d\u00eda en el contorno [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[248,166],"class_list":["post-38239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-hijuelas","tag-proyecto-asociativo-regional-explora-valparaiso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas! - Valpara\u00edso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas! - Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"La nueva exposici\u00f3n interactiva del PAR EXPLORA Valpara\u00edso est\u00e1 abierta a todo p\u00fablico en Hijuelas hasta el 21 de agosto. Nuestras exposiciones interactivas, al igual que el oc\u00e9ano, est\u00e1n en un constante y permanente movimiento. Invitamos a los hijuelenses a conocer los fen\u00f3menos detr\u00e1s de estas ondas que danzan d\u00eda a d\u00eda en el contorno [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-05T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:00:47+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas!\",\"datePublished\":\"2015-08-05T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg\",\"keywords\":[\"hijuelas\",\"Proyecto Asociativo Regional EXPLORA Valparaiso\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\",\"name\":\"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas! - Valpara\u00edso\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg\",\"datePublished\":\"2015-08-05T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:00:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/valparaiso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"name\":\"Valpara\u00edso\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\",\"name\":\"Valpara\u00edso\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"width\":2035,\"height\":584,\"caption\":\"Valpara\u00edso\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas! - Valpara\u00edso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas! - Valpara\u00edso","og_description":"La nueva exposici\u00f3n interactiva del PAR EXPLORA Valpara\u00edso est\u00e1 abierta a todo p\u00fablico en Hijuelas hasta el 21 de agosto. Nuestras exposiciones interactivas, al igual que el oc\u00e9ano, est\u00e1n en un constante y permanente movimiento. Invitamos a los hijuelenses a conocer los fen\u00f3menos detr\u00e1s de estas ondas que danzan d\u00eda a d\u00eda en el contorno [&hellip;]","og_url":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/","og_site_name":"Valpara\u00edso","article_published_time":"2015-08-05T04:00:00+00:00","article_modified_time":"2019-05-20T17:00:47+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas!","datePublished":"2015-08-05T04:00:00+00:00","dateModified":"2019-05-20T17:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg","keywords":["hijuelas","Proyecto Asociativo Regional EXPLORA Valparaiso"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/","url":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/","name":"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas! - Valpara\u00edso","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg","datePublished":"2015-08-05T04:00:00+00:00","dateModified":"2019-05-20T17:00:47+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#primaryimage","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/d14f11d7d37eaa2ecd678ad120c11d72-1.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/valparaiso\/hola-ola-navegando-al-compas-del-mar-esta-en-hijuelas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/valparaiso\/"},{"@type":"ListItem","position":2,"name":"\u00a1&quot;Hola Ola: Navegando al Comp\u00e1s del Mar&quot; alcanza Hijuelas!"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/valparaiso\/#website","url":"https:\/\/dev.explora.cl\/valparaiso\/","name":"Valpara\u00edso","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization","name":"Valpara\u00edso","url":"https:\/\/dev.explora.cl\/valparaiso\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","width":2035,"height":584,"caption":"Valpara\u00edso"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/valparaiso\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/comments?post=38239"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38239\/revisions"}],"predecessor-version":[{"id":38739,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38239\/revisions\/38739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media\/34024"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media?parent=38239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/categories?post=38239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/tags?post=38239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}