{"id":38135,"date":"2014-11-11T00:00:00","date_gmt":"2014-11-11T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/valparaiso\/blog\/2014\/11\/11\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso\/"},"modified":"2019-05-20T17:04:29","modified_gmt":"2019-05-20T17:04:29","slug":"todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/","title":{"rendered":"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-7138\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/11\/5e946d5acbffa84333deca767bb5d244.jpg\" alt=\"\" width=\"152\" height=\"152\" \/><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.exploraquinta.ucv.cl\/imag\/2014\/chileva_valparaiso01.jpg\" border=\"0\" alt=\"Chile Va Valparaiso\" title=\"Chile Va Valparaiso\" width=\"350\" height=\"233\" style=\"float: right\" \/>J\u00f3venes compartir\u00e1n seis d\u00edas de acercamiento al trabajo cient\u00edfico en Chile a trav\u00e9s de pr\u00e1cticas emprendedoras, vinculando ciencia, tecnolog\u00eda e innovaci\u00f3n.<\/em><\/p>\n<p>Con el arribo de estudiantes de toda la regi\u00f3n de Valpara\u00edso este domingo 16 de noviembre se inicia una nueva edici\u00f3n del Campamento EXPLORA Chile Va!. La iniciativa es realizada por la Fundaci\u00f3n Facultad de Ciencias Veterinarias y Pecuarias de la Universidad de Chile (FAVET), en el marco del I Concurso de Campamentos de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n Explora Chile Va! 2014.<\/p>\n<p>Los campamento EXPLORA Chile Va! est\u00e1n enfocados en promover el desarrollo de capital humano y mostrar a los estudiantes la nueva configuraci\u00f3n social y econ\u00f3mica del siglo XXI para que ellos, a trav\u00e9s de las pr\u00e1cticas emprendedoras, dise\u00f1en un proyecto de vida y se vinculen con la Ciencia y la Tecnolog\u00eda.<\/p>\n<p>Los j\u00f3venes asistentes de segundo y tercero medio, provenientes de distintos establecimientos educacionales, disfrutar\u00e1n, durante esta semana, de actividades como Conversaciones con Maestr@s de las ciencias, encuentros cercanos con instituciones o empresas donde se aplican procesos cient\u00edficos, actividades experimentales de ciencia y tecnolog\u00eda, emprendimiento, la presentaci\u00f3n de la exposici\u00f3n &#8220;Impresi\u00f3nate con la presi\u00f3n atmosf\u00e9rica&#8221; y charlas con j\u00f3venes emprendedores.<span style=\"line-height: 1.3em\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.exploraquinta.ucv.cl\/imag\/2014\/chileva_valparaiso03.jpg\" border=\"0\" alt=\"Chile Va Valparaiso\" title=\"Chile Va Valparaiso\" width=\"350\" height=\"233\" style=\"float: right\" \/>Cabe recalcar que el Programa EXPLORA a la fecha ha llevado a cabo 27 campamentos Chile Va! en nuestro pa\u00eds, beneficiando a aproximadamente 3 mil 500 estudiantes, muchos de los cuales siguen participando de la iniciativa apoyando a nuevos participantes y contando su experiencia.<\/p>\n<p><strong>Campamento Regi\u00f3n Valpara\u00edso<\/strong><\/p>\n<p>Fecha: 16 al 21 de noviembre<br \/>Lugar: Hacienda Picarqu\u00edn, Regi\u00f3n de O\u2019Higgins<br \/>150 j\u00f3venes asistentes<span style=\"line-height: 1.3em\"> <br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00f3venes compartir\u00e1n seis d\u00edas de acercamiento al trabajo cient\u00edfico en Chile a trav\u00e9s de pr\u00e1cticas emprendedoras, vinculando ciencia, tecnolog\u00eda e innovaci\u00f3n. Con el arribo de estudiantes de toda la regi\u00f3n de Valpara\u00edso este domingo 16 de noviembre se inicia una nueva edici\u00f3n del Campamento EXPLORA Chile Va!. La iniciativa es realizada por la Fundaci\u00f3n Facultad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[252,254,255,107,26,257,210,258,260,230,166,204],"class_list":["post-38135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-campamento","tag-chile-va","tag-chileva","tag-ciencia","tag-conicyt","tag-emprendimiento","tag-exposiciones","tag-innovacion","tag-jovenes","tag-ninos","tag-proyecto-asociativo-regional-explora-valparaiso","tag-valparaiso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso - Valpara\u00edso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso - Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"J\u00f3venes compartir\u00e1n seis d\u00edas de acercamiento al trabajo cient\u00edfico en Chile a trav\u00e9s de pr\u00e1cticas emprendedoras, vinculando ciencia, tecnolog\u00eda e innovaci\u00f3n. Con el arribo de estudiantes de toda la regi\u00f3n de Valpara\u00edso este domingo 16 de noviembre se inicia una nueva edici\u00f3n del Campamento EXPLORA Chile Va!. La iniciativa es realizada por la Fundaci\u00f3n Facultad [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Valpara\u00edso\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-11T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:04:29+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"152\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"152\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso\",\"datePublished\":\"2014-11-11T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:04:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\"},\"wordCount\":296,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg\",\"keywords\":[\"campamento\",\"chile va\",\"chileva\",\"ciencia\",\"Conicyt\",\"emprendimiento\",\"exposiciones\",\"innovacion\",\"jovenes\",\"ni\u00f1os\",\"Proyecto Asociativo Regional EXPLORA Valparaiso\",\"valparaiso\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\",\"name\":\"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso - Valpara\u00edso\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg\",\"datePublished\":\"2014-11-11T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:04:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg\",\"width\":152,\"height\":152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/valparaiso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#website\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"name\":\"Valpara\u00edso\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#organization\",\"name\":\"Valpara\u00edso\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg\",\"width\":2035,\"height\":584,\"caption\":\"Valpara\u00edso\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/valparaiso\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso - Valpara\u00edso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/","og_locale":"es_ES","og_type":"article","og_title":"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso - Valpara\u00edso","og_description":"J\u00f3venes compartir\u00e1n seis d\u00edas de acercamiento al trabajo cient\u00edfico en Chile a trav\u00e9s de pr\u00e1cticas emprendedoras, vinculando ciencia, tecnolog\u00eda e innovaci\u00f3n. Con el arribo de estudiantes de toda la regi\u00f3n de Valpara\u00edso este domingo 16 de noviembre se inicia una nueva edici\u00f3n del Campamento EXPLORA Chile Va!. La iniciativa es realizada por la Fundaci\u00f3n Facultad [&hellip;]","og_url":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/","og_site_name":"Valpara\u00edso","article_published_time":"2014-11-11T04:00:00+00:00","article_modified_time":"2019-05-20T17:04:29+00:00","og_image":[{"width":152,"height":152,"url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso","datePublished":"2014-11-11T04:00:00+00:00","dateModified":"2019-05-20T17:04:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/"},"wordCount":296,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg","keywords":["campamento","chile va","chileva","ciencia","Conicyt","emprendimiento","exposiciones","innovacion","jovenes","ni\u00f1os","Proyecto Asociativo Regional EXPLORA Valparaiso","valparaiso"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/","url":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/","name":"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso - Valpara\u00edso","isPartOf":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg","datePublished":"2014-11-11T04:00:00+00:00","dateModified":"2019-05-20T17:04:29+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#primaryimage","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2018\/06\/5e946d5acbffa84333deca767bb5d244.jpg","width":152,"height":152},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/valparaiso\/todo-listo-para-campamento-chile-va-2014-region-de-valparaiso-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/valparaiso\/"},{"@type":"ListItem","position":2,"name":"Todo listo para Campamento Chile Va! 2014 Regi\u00f3n de Valpara\u00edso"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/valparaiso\/#website","url":"https:\/\/dev.explora.cl\/valparaiso\/","name":"Valpara\u00edso","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/valparaiso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/valparaiso\/#organization","name":"Valpara\u00edso","url":"https:\/\/dev.explora.cl\/valparaiso\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","contentUrl":"https:\/\/dev.explora.cl\/valparaiso\/wp-content\/uploads\/sites\/7\/2019\/06\/cropped-logo-explora-color.jpg","width":2035,"height":584,"caption":"Valpara\u00edso"},"image":{"@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/valparaiso\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/valparaiso\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/comments?post=38135"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38135\/revisions"}],"predecessor-version":[{"id":38871,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/posts\/38135\/revisions\/38871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media\/33856"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/media?parent=38135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/categories?post=38135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/valparaiso\/wp-json\/wp\/v2\/tags?post=38135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}