{"id":32796,"date":"2017-05-15T00:00:00","date_gmt":"2017-05-15T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rmnorte\/blog\/2017\/05\/15\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/"},"modified":"2019-05-20T17:15:08","modified_gmt":"2019-05-20T17:15:08","slug":"la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/","title":{"rendered":"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares"},"content":{"rendered":"<p style=\"text-align: justify\">Construir una mirada dial\u00f3gica de la argumentaci\u00f3n e incentivar el desarrollo de t\u00e9cnicas de refutaci\u00f3n basadas en el conocimiento, es lo que se busc\u00f3 ense\u00f1ar y aplicar en las capacitaciones del 5\u00b0 Torneo de Debates Cient\u00edficos Estudiantiles, iniciativa generada por el PAR Explora de\u00a0CONICYT RM Norte.\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0<a href=\"https:\/\/www.facebook.com\/pg\/ExploraRMNorte\/photos\/?tab=album&amp;album_id=776442425852084\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-24056\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/03\/Mira-las-fotos-aqui-2.jpg\" alt=\"\" width=\"222\" height=\"92\" srcset=\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2017\/03\/Mira-las-fotos-aqui-2.jpg 306w, https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2017\/03\/Mira-las-fotos-aqui-2-300x125.jpg 300w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">En miras a las pr\u00f3ximas jornadas de debates, que se desarrollar\u00e1n desde el 29 de mayo hasta el 14 de septiembre, se comienzan a preparar los 20 equipos de estudiantes que participar\u00e1n en esta nueva instancia del Torneo de Debates, iniciativa que busca mejorar las habilidades<img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-25218\" style=\"float: right\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/05\/Torneo-2.jpg\" alt=\"\" width=\"549\" height=\"320\" \/>\u00a0argumentales de las y los j\u00f3venes.\u00a0<\/p>\n<p style=\"text-align: justify\">\u201cFomentar la ciencia y el pensamiento cr\u00edtico, buscar el porqu\u00e9 de las cosas a partir de la construcci\u00f3n de conocimientos y mejorar las habilidades de las y los estudiantes a nivel oral y corporal mediante la puesta en escena, es lo que busca esta capacitaci\u00f3n\u201d, agreg\u00f3 V\u00edctor Vergara, coordinador de la actividad y abogado licenciado de la Universidad de Chile.\u00a0<\/p>\n<p style=\"text-align: justify\">Durante el desarrollo de la primera sesi\u00f3n de capacitaci\u00f3n, que tuvo lugar el 11 de mayo en la Biblioteca de Santiago, se ense\u00f1aron, tanto a profesores como estudiantes, conceptos b\u00e1sicos de argumentaci\u00f3n y contra argumentaci\u00f3n, estrategias elementales y pr\u00e1cticas para enfrentar un debate, adem\u00e1s de la preparaci\u00f3n mental que se deber\u00eda alcanzar para fundamentar correctamente a favor o en contra de una idea en discusi\u00f3n.\u00a0<\/p>\n<p style=\"text-align: justify\">V\u00edctor adem\u00e1s explic\u00f3 que, durante un debate, siempre hay al menos tres factores clave; un punto de vista a partir de una idea controversial, la negociaci\u00f3n y la propuesta de una eventual soluci\u00f3n de la controversia o, si se quiere, etapa de cierre.\u00a0<\/p>\n<p style=\"text-align: justify\">En el transcurso de la jornada, tambi\u00e9n se realiz\u00f3 un simulacro de debate en donde las y los participantes se dividieron en tres grupos: bancada a favor, en contra y el equipo investigador. La misi\u00f3n de este \u00faltimo estar\u00e1 enfocada en mantener una mirada neutral durante el desarrollo de las etapas.\u00a0<\/p>\n<p style=\"text-align: justify\">Los equipos ser\u00e1n distribuidos de la misma manera en el espacio f\u00edsico y deber\u00e1n realizar un trabajo exhaustivo en diferentes \u00e1reas durante los siguientes meses, que contemplar\u00e1, entre otras cosas, la creaci\u00f3n de notas pr\u00e1cticas, res\u00famenes, investigaci\u00f3n, proyecci\u00f3n de la voz y lenguaje kin\u00e9sico.\u00a0<\/p>\n<p style=\"text-align: justify\">Respecto al refuerzo en estas materias, B\u00e1rbara Reffer, estudiante de tercero medio del Liceo Miguel Rafael Prado de Independencia, cont\u00f3 su experiencia: \u201cEs la primera vez que vengo y esta preparaci\u00f3n me pareci\u00f3 bastante completa. Sobre todo, porque la capacitaci\u00f3n nos nivela. Ten\u00edamos miedo de la desventaja a nivel educacional con otros colegios, pero con esto, ahora todos parecemos iguales\u201d.\u00a0<\/p>\n<p style=\"text-align: justify\">Sobre la invitaci\u00f3n del PAR Explora de CONICYT RM Norte a esta experiencia, Cristhy Gonz\u00e1lez, profesora gu\u00eda de B\u00e1rbara y de sus compa\u00f1eras y compa\u00f1eros, coment\u00f3: \u201cMe llam\u00f3 la atenci\u00f3n, porque es algo novedoso. A nuestro colegio no llegan este tipo de invitaciones externas. Asimismo, la informaci\u00f3n que deber\u00e1n manejar los ni\u00f1os es harta, pero esta preparaci\u00f3n logra que puedan interiorizarla correctamente\u201d.\u00a0<\/p>\n<p style=\"text-align: justify\">La segunda sesi\u00f3n, desarrollada el 12 de mayo en el auditorio Ninoslav Bralic, de la Facultad de Matem\u00e1ticas de la Universidad Cat\u00f3lica, se enfoc\u00f3 en el rol que asumir\u00e1n el o los profesores gu\u00eda durante la preparaci\u00f3n de sus equipos respectivos, as\u00ed como la misi\u00f3n que tendr\u00e1n los jueces. De esta forma, la motivaci\u00f3n, la adaptaci\u00f3n bibliogr\u00e1fica, la revisi\u00f3n en conjunto de los criterios de evaluaci\u00f3n y el mantenerse informado, ser\u00e1n los principales desaf\u00edos que deber\u00e1n afrontar.\u00a0<\/p>\n<p style=\"text-align: justify\">La primera jornada de debate tendr\u00e1 lugar en el auditorio Ninoslav Bralic, los d\u00edas 29 y 30 de mayo, a partir de las 9:00 horas. Mientras, los equipos que participar\u00e1n en esta convocatoria corresponden a los siguientes establecimientos:\u00a0<\/p>\n<p style=\"text-align: justify\">Colegio Jos\u00e9 Manuel Irarr\u00e1zabal de Santiago<br \/>Colegio Tajamar de Providencia<br \/>Liceo Abd\u00f3n Cifuentes de Conchal\u00ed<br \/>Colegio San Jos\u00e9 de Renca de Renca<br \/>Colegio Universitario ingles de Providencia<br \/>Liceo 1 Javiera Carrera de Santiago<br \/>Colegio Santa b\u00e1rbara de Quilicura<br \/>Colegio Liahona de El Bosque<br \/>Colegio Palmares Oriente de Quilicura<br \/>Colegio Jos\u00e9 Victorino Lastarria de Providencia<br \/>Colegio Carmela Carvajal de Providencia<br \/>Liceo Manuel Barros Borgo\u00f1o de Santiago<br \/>Liceo Gabriela Mistral de Independencia<br \/>Colegio Echaurren de Maip\u00fa<br \/>Centro Educacional H\u00e9roe Arturo P\u00e9rez del Canto de Recoleta<br \/>Colegio Confederaci\u00f3n Suiza de la Reina<br \/>Instituto de Humanidades Luis Campino de Providencia<br \/>Colegio Southem Cross School de Las Condes<br \/>Liceo Miguel Rafael Prado de Independencia<br \/>Complejo Educacional Juanita Fern\u00e1ndez del Solar de Recoleta<\/p>\n<p>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-25219\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/05\/Torneo-3.jpg\" alt=\"\" width=\"793\" height=\"308\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construir una mirada dial\u00f3gica de la argumentaci\u00f3n e incentivar el desarrollo de t\u00e9cnicas de refutaci\u00f3n basadas en el conocimiento, es lo que se busc\u00f3 ense\u00f1ar y aplicar en las capacitaciones del 5\u00b0 Torneo de Debates Cient\u00edficos Estudiantiles, iniciativa generada por el PAR Explora de\u00a0CONICYT RM Norte.\u00a0 \u00a0 En miras a las pr\u00f3ximas jornadas de debates, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-32796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares - RM Norte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares - RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Construir una mirada dial\u00f3gica de la argumentaci\u00f3n e incentivar el desarrollo de t\u00e9cnicas de refutaci\u00f3n basadas en el conocimiento, es lo que se busc\u00f3 ense\u00f1ar y aplicar en las capacitaciones del 5\u00b0 Torneo de Debates Cient\u00edficos Estudiantiles, iniciativa generada por el PAR Explora de\u00a0CONICYT RM Norte.\u00a0 \u00a0 En miras a las pr\u00f3ximas jornadas de debates, [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-15T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:15:08+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"110\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares\",\"datePublished\":\"2017-05-15T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:15:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\"},\"wordCount\":784,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\",\"name\":\"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares - RM Norte\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg\",\"datePublished\":\"2017-05-15T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:15:08+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg\",\"width\":220,\"height\":110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rmnorte\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/\",\"name\":\"RM Norte\",\"description\":\"RM Norte dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rmnorte\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares - RM Norte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/","og_locale":"es_ES","og_type":"article","og_title":"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares - RM Norte","og_description":"Construir una mirada dial\u00f3gica de la argumentaci\u00f3n e incentivar el desarrollo de t\u00e9cnicas de refutaci\u00f3n basadas en el conocimiento, es lo que se busc\u00f3 ense\u00f1ar y aplicar en las capacitaciones del 5\u00b0 Torneo de Debates Cient\u00edficos Estudiantiles, iniciativa generada por el PAR Explora de\u00a0CONICYT RM Norte.\u00a0 \u00a0 En miras a las pr\u00f3ximas jornadas de debates, [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/","og_site_name":"RM Norte","article_published_time":"2017-05-15T04:00:00+00:00","article_modified_time":"2019-05-20T17:15:08+00:00","og_image":[{"width":220,"height":110,"url":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares","datePublished":"2017-05-15T04:00:00+00:00","dateModified":"2019-05-20T17:15:08+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/"},"wordCount":784,"image":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/","url":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/","name":"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares - RM Norte","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg","datePublished":"2017-05-15T04:00:00+00:00","dateModified":"2019-05-20T17:15:08+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#primaryimage","url":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg","contentUrl":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/Torneo-1.jpg","width":220,"height":110},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rmnorte\/la-buena-argumentacion-sera-clave-en-el-5-torneo-de-debates-cientificos-escolares-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rmnorte\/"},{"@type":"ListItem","position":2,"name":"La buena argumentaci\u00f3n ser\u00e1 clave en el 5\u00b0 Torneo de Debates Cient\u00edficos Escolares"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rmnorte\/#website","url":"https:\/\/dev.explora.cl\/rmnorte\/","name":"RM Norte","description":"RM Norte dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rmnorte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rmnorte\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/comments?post=32796"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32796\/revisions"}],"predecessor-version":[{"id":38064,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32796\/revisions\/38064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/media\/32797"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/media?parent=32796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/categories?post=32796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/tags?post=32796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}