{"id":32781,"date":"2017-04-27T00:00:00","date_gmt":"2017-04-27T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rmnorte\/blog\/2017\/04\/27\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/"},"modified":"2019-05-20T17:15:14","modified_gmt":"2019-05-20T17:15:14","slug":"ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/","title":{"rendered":"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones"},"content":{"rendered":"<p style=\"text-align: justify\">La instancia, organizada por el PAR Explora RM Norte y la Facultad de Matem\u00e1ticas de la UC, est\u00e1 orientada a profesores y estudiantes de s\u00e9ptimo b\u00e1sico a tercero medio, fij\u00e1ndose como objetivo entrenar a las y los asistentes en el uso de herramientas para la resoluci\u00f3n de problemas matem\u00e1ticos en contextos cient\u00edficos.\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"pull-right size-full wp-image-24841\" style=\"font-size: 12.16px\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg\" alt=\"\" width=\"579\" height=\"791\" \/>Dos ser\u00e1n las tem\u00e1ticas que se abordar\u00e1n en \u201cLa Ciencia de las Matem\u00e1ticas\u201d, ciclo que entregar\u00e1 a las y los participantes herramientas t\u00e9cnicas y metodol\u00f3gicas para el estudio y comprensi\u00f3n de esta disciplina como ciencia.\u00a0<\/p>\n<p style=\"text-align: justify\">El taller de \u201c<strong>Iniciaci\u00f3n a la Investigaci\u00f3n Matem\u00e1tica<\/strong>\u201d permitir\u00e1 conocer fundamentos matem\u00e1ticos b\u00e1sicos para el desarrollo de investigaciones en las diferentes \u00e1reas y l\u00edneas que aborda esta disciplina. Se mostrar\u00e1n diferentes aplicaciones matem\u00e1ticas y se entrenar\u00e1 en el uso de t\u00e9cnicas y m\u00e9todos que permitan a estudiantes de Educaci\u00f3n Media iniciar un proyecto de investigaci\u00f3n matem\u00e1tica a nivel escolar, con miras al Congreso Explora.<\/p>\n<p style=\"text-align: justify\">Por su parte, \u201c<strong>Estad\u00edstica aplicada a la investigaci\u00f3n cient\u00edfica<\/strong>\u201d entregar\u00e1 a los participantes herramientas t\u00e9cnicas y metodol\u00f3gicas b\u00e1sicas de estad\u00edstica, para desarrollar proyectos de investigaci\u00f3n cient\u00edfica en las diferentes disciplinas que requieran de recolecci\u00f3n, an\u00e1lisis y uso de datos para identificar variables de car\u00e1cter cualitativas y\/o cuantitativas, que permitan obtener conclusiones relevantes con mayor rigurosidad cient\u00edfica. Este taller busca fortalecer las capacidades de an\u00e1lisis de datos en equipos de escolares que deseen desarrollar una investigaci\u00f3n para postular al Congreso Regional.<\/p>\n<p style=\"text-align: justify\">Para inscribirse en los talleres s\u00f3lo se debe completar el siguiente <a href=\"https:\/\/docs.google.com\/a\/mat.uc.cl\/forms\/d\/e\/1FAIpQLScpb3amqju0B5wkRSLM1yVIdBKPYImIx7BiKbJfcV7aG818Aw\/viewform\" target=\"_blank\" rel=\"noopener noreferrer\">Formulario Virtual<\/a><\/p>\n<p style=\"text-align: justify\">\u201cLa Ciencia de las Matem\u00e1ticas\u201d est\u00e1 dirigido a Estudiantes y docentes de establecimientos de las 17 comunas incluidas en el PAR Explora RM Norte*.<\/p>\n<p style=\"text-align: justify\">Todos los talleres se desarrollar\u00e1n en la Facultad de Matem\u00e1ticas de la UC, ubicada en el Campus San Joaqu\u00edn, entre las 9 y las 13 hrs. Las fechas de cada taller y el p\u00fablico al cual est\u00e1 dirigido son las siguientes:<\/p>\n<p style=\"text-align: justify\"><strong>Estad\u00edstica aplicada a la investigaci\u00f3n cient\u00edfica escolar<\/strong>\u00a0<br \/>Viernes 19 de mayo. Profesores<br \/>Viernes 26 de mayo. Estudiantes<\/p>\n<p style=\"text-align: justify\"><strong>Iniciaci\u00f3n en investigaci\u00f3n matem\u00e1tica<br \/><\/strong>Viernes 9 de junio. Profesores<br \/>Viernes 16 de junio. Estudiantes<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<span style=\"font-size: 9.5pt;font-family: Arial, sans-serif;color: #222222\">Contacto: <\/span><a style=\"font-size: 12.16px\" href=\"mailto:valoracion.explorarmnorte@gmail.com\"><span style=\"font-size: 9.5pt;font-family: 'Arial',sans-serif\">valoracion.explorarmnorte@gmail.com<\/span><\/a><\/p>\n<p class=\"MsoNormal\" style=\"line-height: normal;background-image: initial;background-position: initial\">\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>*Comunas incluidas en el PAR EXPLORA RM Norte: Colina, Conchal\u00ed, Huechuraba, Independencia, La Reina, Las Condes, Lo Barnechea, Lampa, \u00d1u\u00f1oa, Providencia, Pudahuel, Quilicura, Recoleta, Renca, Santiago, Tiltil y Vitacura.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: right\">\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La instancia, organizada por el PAR Explora RM Norte y la Facultad de Matem\u00e1ticas de la UC, est\u00e1 orientada a profesores y estudiantes de s\u00e9ptimo b\u00e1sico a tercero medio, fij\u00e1ndose como objetivo entrenar a las y los asistentes en el uso de herramientas para la resoluci\u00f3n de problemas matem\u00e1ticos en contextos cient\u00edficos.\u00a0 \u00a0 Dos ser\u00e1n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-32781","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones - RM Norte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones - RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"La instancia, organizada por el PAR Explora RM Norte y la Facultad de Matem\u00e1ticas de la UC, est\u00e1 orientada a profesores y estudiantes de s\u00e9ptimo b\u00e1sico a tercero medio, fij\u00e1ndose como objetivo entrenar a las y los asistentes en el uso de herramientas para la resoluci\u00f3n de problemas matem\u00e1ticos en contextos cient\u00edficos.\u00a0 \u00a0 Dos ser\u00e1n [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-27T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:15:14+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones\",\"datePublished\":\"2017-04-27T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:15:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\"},\"wordCount\":433,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\",\"name\":\"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones - RM Norte\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg\",\"datePublished\":\"2017-04-27T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:15:14+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage\",\"url\":\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg\",\"contentUrl\":\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rmnorte\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/\",\"name\":\"RM Norte\",\"description\":\"RM Norte dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rmnorte\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones - RM Norte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/","og_locale":"es_ES","og_type":"article","og_title":"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones - RM Norte","og_description":"La instancia, organizada por el PAR Explora RM Norte y la Facultad de Matem\u00e1ticas de la UC, est\u00e1 orientada a profesores y estudiantes de s\u00e9ptimo b\u00e1sico a tercero medio, fij\u00e1ndose como objetivo entrenar a las y los asistentes en el uso de herramientas para la resoluci\u00f3n de problemas matem\u00e1ticos en contextos cient\u00edficos.\u00a0 \u00a0 Dos ser\u00e1n [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/","og_site_name":"RM Norte","article_published_time":"2017-04-27T04:00:00+00:00","article_modified_time":"2019-05-20T17:15:14+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones","datePublished":"2017-04-27T04:00:00+00:00","dateModified":"2019-05-20T17:15:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/"},"wordCount":433,"image":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage"},"thumbnailUrl":"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/","url":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/","name":"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones - RM Norte","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage"},"thumbnailUrl":"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg","datePublished":"2017-04-27T04:00:00+00:00","dateModified":"2019-05-20T17:15:14+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#primaryimage","url":"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg","contentUrl":"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Convocatoria-Taller-matemticas-02.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rmnorte\/ciclo-de-talleres-la-ciencia-de-las-matematicas-abre-sus-inscripciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rmnorte\/"},{"@type":"ListItem","position":2,"name":"Ciclo de Talleres \u201cLa Ciencia de las Matem\u00e1ticas\u201d abre sus inscripciones"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rmnorte\/#website","url":"https:\/\/dev.explora.cl\/rmnorte\/","name":"RM Norte","description":"RM Norte dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rmnorte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rmnorte\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/comments?post=32781"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32781\/revisions"}],"predecessor-version":[{"id":38072,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32781\/revisions\/38072"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/media?parent=32781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/categories?post=32781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/tags?post=32781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}