{"id":32231,"date":"2014-11-25T00:00:00","date_gmt":"2014-11-25T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rmnorte\/blog\/2014\/11\/25\/final-de-la-olimpiada-de-ciencias\/"},"modified":"2019-05-20T17:22:30","modified_gmt":"2019-05-20T17:22:30","slug":"final-de-la-olimpiada-de-ciencias","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/","title":{"rendered":"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-7547\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/11\/7e4af79054d89939b65425ed69570c4f.jpg\" alt=\"\" width=\"1000\" height=\"793\" \/><\/p>\n<p style=\"text-align: justify\">48 estudiantes entre segundo y cuarto b\u00e1sico protagonizaron la etapa final de la I Olimpiada de Ciencias para Primer Ciclo B\u00e1sico, la que contempl\u00f3 para esta instancia el desarrollo de un trabajo pr\u00e1ctico dise\u00f1ado especialmente para cada nivel.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">El s\u00e1bado 22 de noviembre, en el laboratorio del Departamento de Qu\u00edmica de la Universidad Metropolitana de Ciencias de la Educaci\u00f3n (UMCE), se realiz\u00f3 la \u00faltima de las pruebas del certamen que por primera vez se organiz\u00f3 en la Regi\u00f3n Metropolitana.<\/p>\n<p style=\"text-align: justify\">En la actividad, organizada por la mencionada casa de estudios y el PAR EXPLORA RM Norte, participaron representantes de las 17 comunas con las que trabaja este \u00faltimo, con un total de 48 estudiantes; 16 de Segundo, Tercero y Cuarto B\u00e1sico respectivamente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-7548\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/11\/Final-Olimpiada-02.jpg\" border=\"0\" width=\"367\" height=\"244\" style=\"float: left;margin: 5px;border: 5px solid black\" \/>A las 11 de la ma\u00f1ana se inici\u00f3 la prueba experimental, la cual fue dise\u00f1ada acorde a los programas oficiales del MINEDUC: Ciencias de la Vida, Ciencias F\u00edsicas y Qu\u00edmicas, y Ciencias de la Tierra y el Universo.<\/p>\n<p style=\"text-align: justify\">Juan Vargas, Decano de la Facultad de Ciencias de la UMCE y miembro del comit\u00e9 organizador de la Olimpiada, se\u00f1al\u00f3 respecto a la culminaci\u00f3n de esta iniciativa: \u201cPara ser nuestra primera experiencia pude observar que la gran mayor\u00eda de las y los estudiantes son aut\u00f3nomos, pens\u00e1bamos que nos \u00edbamos a encontrar con estudiantes m\u00e1s dependientes, puesto que en general no est\u00e1n acostumbrados a hacer actividades en laboratorio, ya que por lo general la ciencia en los colegios se ense\u00f1a en la pizarra, cuando debiera ser todo lo contrario, o sea trabajar con la naturaleza de las cosas para ah\u00ed descubrir la ciencia\u201d.<\/p>\n<p style=\"text-align: justify\">Por su parte, Guillermo Paniagua, profesor de Ciencias Naturales de la Escuela Reyes Cat\u00f3licos de Santiago, coment\u00f3: \u201cCualquier instancia que promueva el desarrollo de las ciencias y sobretodo el pensamiento cient\u00edfico en nuestros estudiantes es s\u00faper importante, no solamente para que ellos puedan razonar de mejor manera sus vidas basados en la evidencia y que tengan mejores herramientas, sino que tambi\u00e9n para desarrollar una sociedad progresista como la que queremos\u201d.<\/p>\n<p style=\"text-align: justify\">Previo al inicio de la prueba final, las y los apoderados tuvieron la posibilidad de ingresar al laboratorio para ver en acci\u00f3n a sus hijos e hijas y as\u00ed entregarles las \u00faltimas palabras de aliento antes de enfrentarse al desaf\u00edo propuesto, el cual consisti\u00f3 en actividades de observaci\u00f3n, manipulaci\u00f3n y registro de datos, con distintos conceptos y niveles de dificultad, dependiendo del nivel.<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-7549\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/11\/Final-Olimpiada-03.jpg\" border=\"0\" title=\"final\" width=\"478\" height=\"310\" style=\"float: right;margin: 5px;border: 5px solid black\" \/>Guy Nissen, apoderado del Colegio Alem\u00e1n de Vitacura, coment\u00f3: \u201cEn la primera etapa nos sentimos m\u00e1s relajados, porque era una cosa s\u00faper inocente y hab\u00eda mucha gente participando, luego en la segunda etapa dijimos \u2018esta cosa va en serio\u2019 y lo encuentro notable, adem\u00e1s el hecho de que sea la materia del a\u00f1o pasado significa que le qued\u00f3, as\u00ed es que estamos muy contentos\u201d.<\/p>\n<p style=\"text-align: justify\">La profesora del Colegio Monte Tabor y Nazaret de Lo Barnechea, Magdalena P\u00e9rez se\u00f1al\u00f3 al t\u00e9rmino del pr\u00e1ctico: \u201cFue una Olimpiada muy entretenida, con un proceso muy interesante porque como era la primera vez que se hac\u00eda los ni\u00f1os estaban muy motivados, tambi\u00e9n hab\u00eda mucho misterio de c\u00f3mo iba a ser esto y lo que iba a pasar, pero fue una muy buena experiencia para ellos, fueron s\u00faper provechosas cada una de las instancias\u201d.<\/p>\n<p style=\"text-align: justify\">El 25 de octubre m\u00e1s de 400 ni\u00f1os y ni\u00f1as de las 17 comunas pertenecientes al PAR EXPLORA RM Norte, participaron en la etapa Interescolar de la Olimpiada, que por su convocatoria, se dividi\u00f3 en tres sedes UMCE, Colegio Salvador Sanfuentes de Santiago y Escuela B\u00e1sica Integral Enlaces de Lampa. Posterior a esta etapa, el 15 de noviembre se desarroll\u00f3 la Semifinal, fase a la que accedieron 154 participantes de los tres niveles en competencia y de la que resultaron los 48 finalistas.<\/p>\n<p style=\"text-align: justify\">El Decano de la Facultad de Ciencias de la UMCE, Juan Vargas, concluy\u00f3: \u201cSi motivamos la ciencia desde los primeros a\u00f1os de formaci\u00f3n podemos obtener resultados hac\u00eda arriba, o sea atacamos la ra\u00edz del problema y no en tercero o cuarto medio. Estamos tratando entonces de que la gente se entusiasme por cultivar la ciencia desde la primera etapa de la educaci\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify\"><strong><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.375710652591932.1073742018.180288868800779&amp;type=3\"><span style=\"color: #ff6600\">Revisa aqu\u00ed las fotos de la Final<\/span><\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-7550\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2014\/11\/Final-Olimpiada-04.jpg\" border=\"0\" width=\"655\" height=\"377\" style=\"margin: 5px auto;border: 5px solid black\" \/><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>48 estudiantes entre segundo y cuarto b\u00e1sico protagonizaron la etapa final de la I Olimpiada de Ciencias para Primer Ciclo B\u00e1sico, la que contempl\u00f3 para esta instancia el desarrollo de un trabajo pr\u00e1ctico dise\u00f1ado especialmente para cada nivel. \u00a0 El s\u00e1bado 22 de noviembre, en el laboratorio del Departamento de Qu\u00edmica de la Universidad Metropolitana [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33859,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-32231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario - RM Norte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario - RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"48 estudiantes entre segundo y cuarto b\u00e1sico protagonizaron la etapa final de la I Olimpiada de Ciencias para Primer Ciclo B\u00e1sico, la que contempl\u00f3 para esta instancia el desarrollo de un trabajo pr\u00e1ctico dise\u00f1ado especialmente para cada nivel. \u00a0 El s\u00e1bado 22 de noviembre, en el laboratorio del Departamento de Qu\u00edmica de la Universidad Metropolitana [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"RM Norte\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-25T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T17:22:30+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"793\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario\",\"datePublished\":\"2014-11-25T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:22:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\"},\"wordCount\":740,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\",\"name\":\"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario - RM Norte\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg\",\"datePublished\":\"2014-11-25T04:00:00+00:00\",\"dateModified\":\"2019-05-20T17:22:30+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg\",\"width\":1000,\"height\":793},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rmnorte\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/\",\"name\":\"RM Norte\",\"description\":\"RM Norte dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rmnorte\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rmnorte\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario - RM Norte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/","og_locale":"es_ES","og_type":"article","og_title":"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario - RM Norte","og_description":"48 estudiantes entre segundo y cuarto b\u00e1sico protagonizaron la etapa final de la I Olimpiada de Ciencias para Primer Ciclo B\u00e1sico, la que contempl\u00f3 para esta instancia el desarrollo de un trabajo pr\u00e1ctico dise\u00f1ado especialmente para cada nivel. \u00a0 El s\u00e1bado 22 de noviembre, en el laboratorio del Departamento de Qu\u00edmica de la Universidad Metropolitana [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/","og_site_name":"RM Norte","article_published_time":"2014-11-25T04:00:00+00:00","article_modified_time":"2019-05-20T17:22:30+00:00","og_image":[{"width":1000,"height":793,"url":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario","datePublished":"2014-11-25T04:00:00+00:00","dateModified":"2019-05-20T17:22:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/"},"wordCount":740,"image":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/","url":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/","name":"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario - RM Norte","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg","datePublished":"2014-11-25T04:00:00+00:00","dateModified":"2019-05-20T17:22:30+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#primaryimage","url":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg","contentUrl":"https:\/\/dev.explora.cl\/rmnorte\/wp-content\/uploads\/sites\/11\/2018\/06\/7e4af79054d89939b65425ed69570c4f.jpg","width":1000,"height":793},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rmnorte\/final-de-la-olimpiada-de-ciencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rmnorte\/"},{"@type":"ListItem","position":2,"name":"Final de la Olimpiada de Ciencias tuvo a laboratorio de la UMCE como escenario"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rmnorte\/#website","url":"https:\/\/dev.explora.cl\/rmnorte\/","name":"RM Norte","description":"RM Norte dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rmnorte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rmnorte\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rmnorte\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/comments?post=32231"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32231\/revisions"}],"predecessor-version":[{"id":38489,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/posts\/32231\/revisions\/38489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/media\/33859"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/media?parent=32231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/categories?post=32231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rmnorte\/wp-json\/wp\/v2\/tags?post=32231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}