{"id":838,"date":"2017-04-11T00:00:00","date_gmt":"2017-04-11T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rios\/blog\/2017\/04\/11\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/"},"modified":"2019-05-20T19:28:38","modified_gmt":"2019-05-20T19:28:38","slug":"conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/","title":{"rendered":"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-24508\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Foto-3.jpg\" alt=\"\" width=\"800\" height=\"533\" \/><\/p>\n<p class=\"MsoNormal\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24508\" style=\"float: left\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/04\/Foto-3.jpg\" alt=\"\" width=\"281\" height=\"213\" \/>Un nuevo Taller de Indagaci\u00f3n en Ciencias Naturales implementar\u00e1 el PAR Explora de CONICYT Los R\u00edos el pr\u00f3ximo 26 y 27 de abril, el que est\u00e1 dirigido a profesores de toda la regi\u00f3n. Esto bajo el marco de la Academia Docente Explora esta iniciativa busca entregar herramientas a los profesionales de la educaci\u00f3n que se desempe\u00f1an en \u00e1reas de las ciencias naturales.<\/p>\n<p class=\"MsoNormal\">El ciclo de indagaci\u00f3n es una herramienta educativa que integra y aplica los pasos del m\u00e9todo cient\u00edfico de una manera simplificada pero rigurosa, mediante la formulaci\u00f3n de preguntas que se responden a trav\u00e9s de la acci\u00f3n, donde las respuestas y sus implicaciones se reflejan sobre un contexto m\u00e1s amplio. El taller entregar\u00e1 las herramientas para que los participantes puedan aplicar el ciclo de la indagaci\u00f3n en sus propias aulas, y abordar\u00e1 la manera en la cual \u00e9sta se vincula a los contenidos del curr\u00edculum escolar.<\/p>\n<p>\u00a0<\/p>\n<p class=\"MsoNormal\">Cabe se\u00f1alar que pr\u00f3ximamente se realizar\u00e1 un taller dirigido a los profesores de las ciencias sociales con el fin que puedan desarrollar una investigaci\u00f3n cient\u00edfica, en su \u00e1rea, junto a estudiantes de sus establecimientos.<\/p>\n<p class=\"MsoNormal\">Se adjunta la ficha de inscripci\u00f3n con todos los detalles para la participaci\u00f3n en el taller.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo Taller de Indagaci\u00f3n en Ciencias Naturales implementar\u00e1 el PAR Explora de CONICYT Los R\u00edos el pr\u00f3ximo 26 y 27 de abril, el que est\u00e1 dirigido a profesores de toda la regi\u00f3n. Esto bajo el marco de la Academia Docente Explora esta iniciativa busca entregar herramientas a los profesionales de la educaci\u00f3n que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia - Los R\u00edos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia - Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Un nuevo Taller de Indagaci\u00f3n en Ciencias Naturales implementar\u00e1 el PAR Explora de CONICYT Los R\u00edos el pr\u00f3ximo 26 y 27 de abril, el que est\u00e1 dirigido a profesores de toda la regi\u00f3n. Esto bajo el marco de la Academia Docente Explora esta iniciativa busca entregar herramientas a los profesionales de la educaci\u00f3n que se [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-11T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T19:28:38+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia\",\"datePublished\":\"2017-04-11T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:28:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\"},\"wordCount\":229,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\",\"url\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\",\"name\":\"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia - Los R\u00edos\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg\",\"datePublished\":\"2017-04-11T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:28:38+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rios\/\",\"name\":\"Los R\u00edos\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rios\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia - Los R\u00edos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia - Los R\u00edos","og_description":"Un nuevo Taller de Indagaci\u00f3n en Ciencias Naturales implementar\u00e1 el PAR Explora de CONICYT Los R\u00edos el pr\u00f3ximo 26 y 27 de abril, el que est\u00e1 dirigido a profesores de toda la regi\u00f3n. Esto bajo el marco de la Academia Docente Explora esta iniciativa busca entregar herramientas a los profesionales de la educaci\u00f3n que se [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/","og_site_name":"Los R\u00edos","article_published_time":"2017-04-11T04:00:00+00:00","article_modified_time":"2019-05-20T19:28:38+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia","datePublished":"2017-04-11T04:00:00+00:00","dateModified":"2019-05-20T19:28:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/"},"wordCount":229,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/","url":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/","name":"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia - Los R\u00edos","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg","datePublished":"2017-04-11T04:00:00+00:00","dateModified":"2019-05-20T19:28:38+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#primaryimage","url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg","contentUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/Foto-3.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rios\/conoce-el-ciclo-de-indagacion-una-nueva-forma-de-ensenar-ciencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rios\/"},{"@type":"ListItem","position":2,"name":"Conoce el ciclo de indagaci\u00f3n, una nueva forma de ense\u00f1ar ciencia"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rios\/#website","url":"https:\/\/dev.explora.cl\/rios\/","name":"Los R\u00edos","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rios\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/comments?post=838"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/838\/revisions"}],"predecessor-version":[{"id":37793,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/838\/revisions\/37793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media\/839"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media?parent=838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/categories?post=838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/tags?post=838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}