{"id":741,"date":"2017-01-09T00:00:00","date_gmt":"2017-01-09T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rios\/blog\/2017\/01\/09\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/"},"modified":"2019-05-20T19:28:53","modified_gmt":"2019-05-20T19:28:53","slug":"chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/","title":{"rendered":"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas"},"content":{"rendered":"<p><em><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23237\" style=\"margin-left: auto;margin-right: auto\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2017\/01\/chilevaprofes2017.jpg\" alt=\"\" width=\"800\" height=\"533\" \/><\/em><\/p>\n<p><em>M\u00e1s de 200 profesionales de la educaci\u00f3n llegar\u00e1n hasta la Hacienda Picarqu\u00edn, ubicada en la Regi\u00f3n de O\u2019Higgins, para potenciar la ense\u00f1anza de las ciencias y convertirse en los protagonistas del cambio educativo en diferentes regiones de Chile. La regi\u00f3n tendr\u00e1 15 representantes.<\/em><\/p>\n<p>Son los docentes m\u00e1s motivados de sus comunidades escolares y, durante cuatro d\u00edas, se reunir\u00e1n para ser parte de una experiencia \u00fanica donde podr\u00e1n mejorar sus habilidades de liderazgo y desarrollar actividades innovadoras para favorecer la curiosidad y el pensamiento cient\u00edfico en sus estudiantes.<\/p>\n<p>Se trata del campamento Chile VA! Profes, una iniciativa que se desarrollar\u00e1 en el excepcional entorno natural de la comuna de Mostazal, desde el lunes 9 hasta el jueves 12 de enero. Ser\u00e1n dos campamentos que se realizar\u00e1n de forma simult\u00e1nea, en el primero participar\u00e1n docentes que imparten clases desde educaci\u00f3n parvularia hasta 6\u00ba b\u00e1sico, mientras que en el segundo, quienes se desempe\u00f1an desde 7\u00b0 b\u00e1sico a 4\u00b0 medio.<\/p>\n<p>\u201cLa reciente Encuesta Nacional de Percepci\u00f3n Social de la Ciencia y la Tecnolog\u00eda en Chile, realizada por CONICYT, nos mostr\u00f3 que el 51,3% de la poblaci\u00f3n considera que el nivel de educaci\u00f3n cient\u00edfica y t\u00e9cnica que han recibido es bajo o muy bajo. De ah\u00ed la importancia de implementar este tipo de iniciativas, donde los docentes pueden reforzar sus m\u00e9todos de ense\u00f1anza y lograr que ni\u00f1os, ni\u00f1as y j\u00f3venes puedan encantarse con la ciencia desde sus entornos educativos\u201d, dijo Natalia Mackenzie, directora del Programa Explora de CONICYT.<\/p>\n<p>\u00bfC\u00f3mo aprendemos ciencia? \u00bfCu\u00e1l es el desaf\u00edo de aprender desde el error? \u00bfPor qu\u00e9 las preguntas son tan importantes para el proceso de aprendizaje?, son algunas de las interrogantes que podr\u00e1n resolver estos profesionales, de la mano de relatores expertos y acad\u00e9micos de diversas universidades, junto al apoyo de instituciones como The Hollingworth Center, Teachers College, de la Universidad de Columbia y el Programa de Educaci\u00f3n en Ciencias Basado en la Indagaci\u00f3n (ECBI) Chile.<\/p>\n<p>Adem\u00e1s de talleres pr\u00e1cticos, podr\u00e1n participar de di\u00e1logos con destacados cient\u00edficos como el Dr. Fernando Valiente, especialista en microbiolog\u00eda, que estudia el comportamiento del VIH-1 y actual coordinador nacional de \u201cM\u00e1s Ciencia para Chile\u201d. Igualmente se presentar\u00e1 N\u00e9stor Espinoza, astr\u00f3nomo, que se especializa en la detecci\u00f3n y caracterizaci\u00f3n de planetas fuera del sistema solar, adem\u00e1s de divulgar la ciencia del cosmos en Radio Futuro. \u00a0<\/p>\n<p>As\u00ed tambi\u00e9n podr\u00e1n compartir vivencias con estudiantes que han optado por seguir el camino de las ciencias e intercambiar pr\u00e1cticas exitosas con l\u00edderes de la educaci\u00f3n de diferentes contextos educativos. Pero no todo ser\u00e1 ciencia y actividades de aprendizaje, los participantes disfrutar\u00e1n de espacios de recreaci\u00f3n al aire libre, los cuales han sido especialmente dise\u00f1ados para favorecer el trabajo en equipo.\u00a0<\/p>\n<p>Quienes participen del campamento, ser\u00e1n parte de una Exposici\u00f3n de Ciencia y Tecnolog\u00eda, donde importantes centros de investigaci\u00f3n mostrar\u00e1n actividades que promueven la cultura cient\u00edfica: el Instituto Milenio de Neurociencia Biom\u00e9dica (BNI), el Centro de Excelencia en Geotermia de Los Andes (CEGA) y el Programa 6 Sentidos del Instituto Milenio de Ecolog\u00eda y Biodiversidad (IEB), son algunos de los invitados.\u00a0<\/p>\n<p>Esta es una iniciativa del Programa Explora de CONICYT, que busca motivar a los profesores y profesoras a dise\u00f1ar actividades que les permitan convertirse en agentes de cambio, capaces de identificar las oportunidades y desaf\u00edos presentes en el mundo escolar y cient\u00edfico.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 200 profesionales de la educaci\u00f3n llegar\u00e1n hasta la Hacienda Picarqu\u00edn, ubicada en la Regi\u00f3n de O\u2019Higgins, para potenciar la ense\u00f1anza de las ciencias y convertirse en los protagonistas del cambio educativo en diferentes regiones de Chile. La regi\u00f3n tendr\u00e1 15 representantes. Son los docentes m\u00e1s motivados de sus comunidades escolares y, durante cuatro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas - Los R\u00edos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas - Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 200 profesionales de la educaci\u00f3n llegar\u00e1n hasta la Hacienda Picarqu\u00edn, ubicada en la Regi\u00f3n de O\u2019Higgins, para potenciar la ense\u00f1anza de las ciencias y convertirse en los protagonistas del cambio educativo en diferentes regiones de Chile. La regi\u00f3n tendr\u00e1 15 representantes. Son los docentes m\u00e1s motivados de sus comunidades escolares y, durante cuatro [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-09T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T19:28:53+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"110\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas\",\"datePublished\":\"2017-01-09T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:28:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\"},\"wordCount\":625,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\",\"url\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\",\"name\":\"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas - Los R\u00edos\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg\",\"datePublished\":\"2017-01-09T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:28:53+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg\",\"width\":220,\"height\":110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rios\/\",\"name\":\"Los R\u00edos\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rios\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas - Los R\u00edos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/","og_locale":"es_ES","og_type":"article","og_title":"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas - Los R\u00edos","og_description":"M\u00e1s de 200 profesionales de la educaci\u00f3n llegar\u00e1n hasta la Hacienda Picarqu\u00edn, ubicada en la Regi\u00f3n de O\u2019Higgins, para potenciar la ense\u00f1anza de las ciencias y convertirse en los protagonistas del cambio educativo en diferentes regiones de Chile. La regi\u00f3n tendr\u00e1 15 representantes. Son los docentes m\u00e1s motivados de sus comunidades escolares y, durante cuatro [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/","og_site_name":"Los R\u00edos","article_published_time":"2017-01-09T04:00:00+00:00","article_modified_time":"2019-05-20T19:28:53+00:00","og_image":[{"width":220,"height":110,"url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas","datePublished":"2017-01-09T04:00:00+00:00","dateModified":"2019-05-20T19:28:53+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/"},"wordCount":625,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/","url":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/","name":"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas - Los R\u00edos","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg","datePublished":"2017-01-09T04:00:00+00:00","dateModified":"2019-05-20T19:28:53+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#primaryimage","url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg","contentUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/chilevaprofes2017_220.jpg","width":220,"height":110},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rios\/chile-va-profes-docentes-de-los-rios-se-aventuran-a-cambiar-la-educacion-cientifica-en-sus-escuelas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rios\/"},{"@type":"ListItem","position":2,"name":"Chile VA! Profes: Docentes de Los R\u00edos se aventuran a cambiar la educaci\u00f3n cient\u00edfica en sus escuelas"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rios\/#website","url":"https:\/\/dev.explora.cl\/rios\/","name":"Los R\u00edos","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rios\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/comments?post=741"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/741\/revisions"}],"predecessor-version":[{"id":37818,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/741\/revisions\/37818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media\/742"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media?parent=741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/categories?post=741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/tags?post=741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}