{"id":720,"date":"2016-12-07T00:00:00","date_gmt":"2016-12-07T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rios\/blog\/2016\/12\/07\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/"},"modified":"2019-05-20T19:28:55","modified_gmt":"2019-05-20T19:28:55","slug":"participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/","title":{"rendered":"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-22779\" style=\"float: right;margin: 10px\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2016\/12\/olimpiadaastronomia.jpg\" alt=\"\" width=\"370\" height=\"479\" \/><em>Desde el 2017 la Sociedad Chilena de Astronom\u00eda, en colaboraci\u00f3n con el Programa Explora de CONICYT, invita a estudiantes del pa\u00eds a participar de las nuevas Olimpiadas Regionales de Astronom\u00eda y Astron\u00e1utica.<\/em><\/p>\n<p>\u00bfLa Tierra gira alrededor del Sol o el Sol gira alrededor de la Tierra? Si sabes la respuesta est\u00e1s un paso m\u00e1s cerca de ser un experto\/a en astronom\u00eda y astron\u00e1utica, y podr\u00e1s prep\u00e1rate para las primeras Olimpiadas Regionales de Astronom\u00eda y Astron\u00e1utica que se desarrollar\u00e1n en marzo de 2017. Podr\u00e1s participar por uno de los cupos a la Olimpiada Nacional que se llevar\u00e1 a cabo en julio de 2017 en la isla Quiriquina, Regi\u00f3n del Biob\u00edo.<\/p>\n<p>Esta iniciativa se desarrollar\u00e1 el 17 de marzo del 2017 a la par del D\u00eda Nacional de la Astronom\u00eda y consta de una prueba escrita con un puntaje m\u00e1ximo de 100. El\/la estudiante que logre el puntaje m\u00e1s alto de la regi\u00f3n clasificar\u00e1 al nivel nacional en el que podr\u00e1 competir con estudiantes de cada regi\u00f3n del pa\u00eds.<\/p>\n<p>Esta actividad est\u00e1 dirigida a estudiantes que al 2017 est\u00e9n cursando entre 6\u00b0 y 8\u00b0 b\u00e1sico de educaci\u00f3n b\u00e1sica o entre 1\u00b0 y 3\u00b0 de educaci\u00f3n media. Los participantes deben inscribirse en el siguiente <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSft6-j8DQ7dLkAlWgvFNRYFC3IxwggIMKng9GmhJ2CRMCj0kA\/viewform\">formulario en l\u00ednea<\/a>, pagar la <a href=\"http:\/\/www.sochias.cl\/olimpiadas\/contenidos\/\">cuota de inscripci\u00f3n<\/a> y esperar la publicaci\u00f3n de la lista de confirmados. Este proceso cerrar\u00e1 el 3 de marzo de 2017.<\/p>\n<p>M\u00e1s informaci\u00f3n en la web: <a href=\"http:\/\/www.sochias.cl\/olimpiadas\">www.sochias.cl\/olimpiadas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el 2017 la Sociedad Chilena de Astronom\u00eda, en colaboraci\u00f3n con el Programa Explora de CONICYT, invita a estudiantes del pa\u00eds a participar de las nuevas Olimpiadas Regionales de Astronom\u00eda y Astron\u00e1utica. \u00bfLa Tierra gira alrededor del Sol o el Sol gira alrededor de la Tierra? Si sabes la respuesta est\u00e1s un paso m\u00e1s cerca [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017 - Los R\u00edos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017 - Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Desde el 2017 la Sociedad Chilena de Astronom\u00eda, en colaboraci\u00f3n con el Programa Explora de CONICYT, invita a estudiantes del pa\u00eds a participar de las nuevas Olimpiadas Regionales de Astronom\u00eda y Astron\u00e1utica. \u00bfLa Tierra gira alrededor del Sol o el Sol gira alrededor de la Tierra? Si sabes la respuesta est\u00e1s un paso m\u00e1s cerca [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-07T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T19:28:55+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"110\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017\",\"datePublished\":\"2016-12-07T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:28:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\"},\"wordCount\":270,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\",\"url\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\",\"name\":\"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017 - Los R\u00edos\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg\",\"datePublished\":\"2016-12-07T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:28:55+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg\",\"width\":220,\"height\":110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rios\/\",\"name\":\"Los R\u00edos\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rios\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017 - Los R\u00edos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/","og_locale":"es_ES","og_type":"article","og_title":"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017 - Los R\u00edos","og_description":"Desde el 2017 la Sociedad Chilena de Astronom\u00eda, en colaboraci\u00f3n con el Programa Explora de CONICYT, invita a estudiantes del pa\u00eds a participar de las nuevas Olimpiadas Regionales de Astronom\u00eda y Astron\u00e1utica. \u00bfLa Tierra gira alrededor del Sol o el Sol gira alrededor de la Tierra? Si sabes la respuesta est\u00e1s un paso m\u00e1s cerca [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/","og_site_name":"Los R\u00edos","article_published_time":"2016-12-07T04:00:00+00:00","article_modified_time":"2019-05-20T19:28:55+00:00","og_image":[{"width":220,"height":110,"url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017","datePublished":"2016-12-07T04:00:00+00:00","dateModified":"2019-05-20T19:28:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/"},"wordCount":270,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/","url":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/","name":"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017 - Los R\u00edos","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg","datePublished":"2016-12-07T04:00:00+00:00","dateModified":"2019-05-20T19:28:55+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#primaryimage","url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg","contentUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/olimpiadaastronomia220.jpg","width":220,"height":110},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rios\/participa-de-las-olimpiadas-nacionales-de-astronomia-y-astronautica-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rios\/"},{"@type":"ListItem","position":2,"name":"Participa de las Olimpiadas Nacionales de Astronom\u00eda y Astron\u00e1utica 2017"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rios\/#website","url":"https:\/\/dev.explora.cl\/rios\/","name":"Los R\u00edos","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rios\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/720\/revisions"}],"predecessor-version":[{"id":37824,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/720\/revisions\/37824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media\/721"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media?parent=720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/categories?post=720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/tags?post=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}