{"id":399,"date":"2015-07-23T00:00:00","date_gmt":"2015-07-23T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/rios\/blog\/2015\/07\/23\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/"},"modified":"2019-05-20T19:30:59","modified_gmt":"2019-05-20T19:30:59","slug":"ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/","title":{"rendered":"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-13222\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/07\/d0fa607db380896126161092024a2860.jpg\" alt=\"\" width=\"2000\" height=\"1243\" \/><\/p>\n<p>Con una exhibici\u00f3n de material audiovisual en la Carpa de la Ciencia del CECs los ni\u00f1os y ni\u00f1as de Valdivia celebrar\u00e1n su d\u00eda. La muestra lleva por t\u00edtulo &#8220;El Medio Ambiente&#8221; y es parte de la programaci\u00f3n infantil de Novasur, la televisi\u00f3n cultural y educativa del Consejo Nacional de Televisi\u00f3n. Esta actividad ser\u00e1 desarrollada el jueves 6 de agosto desde las 10:00 horas.<\/p>\n<p>&#8220;La Ciencia Te Ve en el D\u00eda del Ni\u00f1o&#8221; es organizado por Novasur del Consejo Nacional de Televisi\u00f3n, el Proyecto Asociativo Regional, PAR, EXPLORA Los R\u00edos y el Centro de Estudios Cient\u00edficos, CECs.<\/p>\n<p>Los contenidos de la muestra tienen directa relaci\u00f3n al cuidado del medio ambiente y a conocer la fauna nacional. El material est\u00e1 dirigido para todas las edades, pero especialmente desarrollados para estudiantes de 7 a 12 a\u00f1os. Parte de las series exhibidas ser\u00e1n &#8220;Animales chilenos&#8221;, &#8220;Contrase\u00f1a verde&#8221; y &#8220;La plaza imaginaria&#8221;, cap\u00edtulos escogidos por el equipo de Novasur para celebrar este D\u00eda del Ni\u00f1o en todo el pa\u00eds.<\/p>\n<p>La participaci\u00f3n de delegaciones se concretar\u00e1 mediante la inscripci\u00f3n del curso en el sitio web <a href=\"http:\/\/www.cecs.cl\/lacienciateve\">www.cecs.cl\/lacienciateve<\/a>. Los horarios de exhibici\u00f3n son las 10 y 11:15 horas, con una duraci\u00f3n de 45 minutos. Los cupos son limitados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una exhibici\u00f3n de material audiovisual en la Carpa de la Ciencia del CECs los ni\u00f1os y ni\u00f1as de Valdivia celebrar\u00e1n su d\u00eda. La muestra lleva por t\u00edtulo &#8220;El Medio Ambiente&#8221; y es parte de la programaci\u00f3n infantil de Novasur, la televisi\u00f3n cultural y educativa del Consejo Nacional de Televisi\u00f3n. Esta actividad ser\u00e1 desarrollada el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente - Los R\u00edos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente - Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Con una exhibici\u00f3n de material audiovisual en la Carpa de la Ciencia del CECs los ni\u00f1os y ni\u00f1as de Valdivia celebrar\u00e1n su d\u00eda. La muestra lleva por t\u00edtulo &#8220;El Medio Ambiente&#8221; y es parte de la programaci\u00f3n infantil de Novasur, la televisi\u00f3n cultural y educativa del Consejo Nacional de Televisi\u00f3n. Esta actividad ser\u00e1 desarrollada el [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-23T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T19:30:59+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1243\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente\",\"datePublished\":\"2015-07-23T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:30:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\"},\"wordCount\":233,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\",\"url\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\",\"name\":\"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente - Los R\u00edos\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg\",\"datePublished\":\"2015-07-23T04:00:00+00:00\",\"dateModified\":\"2019-05-20T19:30:59+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg\",\"width\":2000,\"height\":1243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rios\/\",\"name\":\"Los R\u00edos\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rios\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente - Los R\u00edos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/","og_locale":"es_ES","og_type":"article","og_title":"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente - Los R\u00edos","og_description":"Con una exhibici\u00f3n de material audiovisual en la Carpa de la Ciencia del CECs los ni\u00f1os y ni\u00f1as de Valdivia celebrar\u00e1n su d\u00eda. La muestra lleva por t\u00edtulo &#8220;El Medio Ambiente&#8221; y es parte de la programaci\u00f3n infantil de Novasur, la televisi\u00f3n cultural y educativa del Consejo Nacional de Televisi\u00f3n. Esta actividad ser\u00e1 desarrollada el [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/","og_site_name":"Los R\u00edos","article_published_time":"2015-07-23T04:00:00+00:00","article_modified_time":"2019-05-20T19:30:59+00:00","og_image":[{"width":2000,"height":1243,"url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente","datePublished":"2015-07-23T04:00:00+00:00","dateModified":"2019-05-20T19:30:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/"},"wordCount":233,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/","url":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/","name":"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente - Los R\u00edos","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg","datePublished":"2015-07-23T04:00:00+00:00","dateModified":"2019-05-20T19:30:59+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#primaryimage","url":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg","contentUrl":"https:\/\/dev.explora.cl\/rios\/wp-content\/uploads\/sites\/16\/2018\/06\/d0fa607db380896126161092024a2860.jpg","width":2000,"height":1243},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rios\/ninos-y-ninas-celebraran-aprendiendo-sobre-medio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rios\/"},{"@type":"ListItem","position":2,"name":"Ni\u00f1os y ni\u00f1as celebrar\u00e1n aprendiendo sobre medio ambiente"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rios\/#website","url":"https:\/\/dev.explora.cl\/rios\/","name":"Los R\u00edos","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rios\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/comments?post=399"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/399\/revisions"}],"predecessor-version":[{"id":37932,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/399\/revisions\/37932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media\/400"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media?parent=399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/categories?post=399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/tags?post=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}