{"id":36413,"date":"2018-09-03T21:11:09","date_gmt":"2018-09-04T01:11:09","guid":{"rendered":"https:\/\/dev.explora.cl\/blog\/2018\/09\/03\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/"},"modified":"2019-05-20T19:35:41","modified_gmt":"2019-05-20T19:35:41","slug":"investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/","title":{"rendered":"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-36319\" src=\"https:\/\/dev.explora.cl\/wp-content\/uploads\/2018\/08\/afiche-crecyt2018-low.jpg\" alt=\"afiche crecyt2018 low\" width=\"300\" height=\"425\" style=\"margin: 5px;float: right\" \/>El pr\u00f3ximo 26, 27 y 28 de septiembre m\u00e1s de 170 estudiantes presentar\u00e1n sus investigaciones cient\u00edficas en el XV Congreso Regional Escolar de la Ciencia y la Tecnolog\u00eda Explora de CONICYT para la Regi\u00f3n de Los R\u00edos. Como ya es tradici\u00f3n los stands abrir\u00e1n en el Centro de Ferias del Parque Saval los d\u00edas 26 y 27 de septiembre de 09:00 a 13:00 horas, con entrada liberada.<\/p>\n<p>Cabe destacar que ser\u00e1n 52 equipos desde educaci\u00f3n parvularia hasta 3\u00b0 medio, entre ellos ser\u00e1n 47 trabajos que competir\u00e1n por un cupo al Congreso Nacional Explora. Los cinco equipos de educaci\u00f3n parvularia y educaci\u00f3n b\u00e1sica primer ciclo ser\u00e1n destacados en su categor\u00eda como exhibici\u00f3n.<\/p>\n<p><strong>Adem\u00e1s, invitamos a toda la comunidad escolar de la regi\u00f3n a visitar el Congreso. Para agendar tu visita env\u00eda el <a href=\"https:\/\/dev.explora.cl\/wp-content\/uploads\/2018\/09\/Ficha-de-Inscripci%C3%B3n-visitas-Congreso-2018.docx\">formulario de inscripci\u00f3n<\/a> al correo electr\u00f3nico <a href=\"mailto:explora14.enlaces@uach.cl\">explora14.enlaces@uach.cl<\/a>&nbsp;hasta 24 horas antes de tu arribo. Una oportunidad para conocer la ciencia y la tecnolog\u00eda que se desarrolla en tu regi\u00f3n.&nbsp;En el Centro de Ferias podr\u00e1s visitar exposiciones y espacios interactivos el mi\u00e9rcoles&nbsp;26 y jueves 27 de septiembre de 09:00 a 13:00 horas.<\/strong><\/p>\n<p>A continuaci\u00f3n, revise los trabajos clasificados:<\/p>\n<table border=\"1\" style=\"width: 960px\">\n<tbody>\n<tr>\n<td style=\"width: 91px\"><strong>C\u00f3digo<\/strong><\/td>\n<td style=\"width: 147px\"><strong>Nivel<\/strong><\/td>\n<td style=\"width: 307px\"><strong>T\u00edtulo<\/strong><\/td>\n<td style=\"width: 220px\"><strong>Establecimiento<\/strong><\/td>\n<td style=\"width: 192px\"><strong>Docente<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-01<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Parvularia<\/td>\n<td style=\"width: 307px\">Hagamos un compost<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Alejandra Gonzalez Gallardo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-02<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Parvularia<\/td>\n<td style=\"width: 307px\">Flotabilidad de diversos materiales en diferentes medios l\u00edquidos<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Mar\u00eda Echenique Barril<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-03<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Parvularia<\/td>\n<td style=\"width: 307px\">La salud est\u00e1 en nuestras manos<\/td>\n<td style=\"width: 220px\">Escuela de Lenguaje Amancay<\/td>\n<td style=\"width: 192px\">Diana Baz\u00e1n Farf\u00e1n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-04<\/td>\n<td style=\"width: 147px\">Primer Ciclo<\/td>\n<td style=\"width: 307px\">Descubriendo las m\u00e1gicas ranitas del patio de mi escuela<\/td>\n<td style=\"width: 220px\">Escuela San Francisco de Llenehue<\/td>\n<td style=\"width: 192px\">Mirta Seguel Andrade<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-05<\/td>\n<td style=\"width: 147px\">Primer Ciclo<\/td>\n<td style=\"width: 307px\">Circuitos coloridos de agua en bombillas<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Constanza Fern\u00e1ndez Colpo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-06<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">&nbsp;\u00bfPor qu\u00e9 los f\u00f3siles pueden ser term\u00f3metros del pasado?<\/td>\n<td style=\"width: 220px\">Escuela Proyecto de Futuro<\/td>\n<td style=\"width: 192px\">Jorge C\u00e1rdenas Alarc\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-07<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">\u00bfPor qu\u00e9 las vacas pierden sus cr\u00edas antes de nacer?<\/td>\n<td style=\"width: 220px\">Instituto Salesiano<\/td>\n<td style=\"width: 192px\">Jos\u00e9 Angel Almonacid Angel<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-08<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">\u00bfC\u00f3mo preservar la carne para un asadito exquisito?<\/td>\n<td style=\"width: 220px\">Escuela Pampa R\u00edos<\/td>\n<td style=\"width: 192px\">Paola D\u00edaz Aguilar<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-09<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Plantas que curan plantas<\/td>\n<td style=\"width: 220px\">Colegio Santa Cruz<\/td>\n<td style=\"width: 192px\">Catherin Opitz Rojas<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-10<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">\u00bfSabemos qu\u00e9 tipo de mieles estamos consumiendo?<\/td>\n<td style=\"width: 220px\">Escuela Patricio Lynch<\/td>\n<td style=\"width: 192px\">Juan Morales Carrasco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-11<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">SURVIVAL bio-energ\u00eda fotosint\u00e9tica<\/td>\n<td style=\"width: 220px\">Colegio Bernardo Felmer Niklitschek<\/td>\n<td style=\"width: 192px\">Ronald Leal Montecinos<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-12<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Los Hongos: nuestros compa\u00f1eros invisibles<\/td>\n<td style=\"width: 220px\">Escuela Alberto C\u00f3rdova Latorre<\/td>\n<td style=\"width: 192px\">Marianyeli Poblete Aedo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-13<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Eficiencia del luchecillo para control de CO2 en espacios cerrados<\/td>\n<td style=\"width: 220px\">Escuela Leonardo Da Vinci<\/td>\n<td style=\"width: 192px\">Adriana Curilen Manquelipe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-14<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">\u00bfLos \u00e1rboles siempre crecen igual?<\/td>\n<td style=\"width: 220px\">Liceo Bicentenario Valdivia<\/td>\n<td style=\"width: 192px\">Nadia Huitrileo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-15<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Guardianes de la bah\u00eda_ Conociendo los par\u00e1sitos que habitan nuestras playas<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Romanett Lillo Navarro<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-16<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Somos territorio, somos historia: Nosotros pobladores de los Barrios Bajos<\/td>\n<td style=\"width: 220px\">Colegio Domus-Mater<\/td>\n<td style=\"width: 192px\">Gabriela Andrea Vel\u00e1squez D\u00edaz<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-17<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Los Animales Humanos y su convivir con los Animales No Humanos, dentro de mi Escuela.<\/td>\n<td style=\"width: 220px\">Escuela El Bosque<\/td>\n<td style=\"width: 192px\">Nataly Navarro Oyarzo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-18<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">El poder de la granada contra las bacterias&nbsp;<\/td>\n<td style=\"width: 220px\">Escuela N\u00b01 Chile<\/td>\n<td style=\"width: 192px\">Gabriela Reyes Mora<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-19<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">Diversidad de mam\u00edferos grandes y sus interacciones en distintos bosques precordilleranos de la Regi\u00f3n de los R\u00edos<\/td>\n<td style=\"width: 220px\">Escuela Enrique R\u00f6mer<\/td>\n<td style=\"width: 192px\">Rodrigo Zurita Aldea<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-20<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">La sangre del pez, un espejo del cambio ambiental<\/td>\n<td style=\"width: 220px\">Escuela Particular N\u00b07 Metodista<\/td>\n<td style=\"width: 192px\">Ra\u00fal Ochoa V\u00e1squez<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-21<\/td>\n<td style=\"width: 147px\">Segundo Ciclo<\/td>\n<td style=\"width: 307px\">\u00bfC\u00f3mo responden los picaflores frente a un atractivo visual en sus territorios?<\/td>\n<td style=\"width: 220px\">Escuela M\u00e9xico<\/td>\n<td style=\"width: 192px\">Esther Maliqueo Delgado<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-22<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Teselaciones Regulares del Cubo<\/td>\n<td style=\"width: 220px\">Colegio Santa Cruz<\/td>\n<td style=\"width: 192px\">Javier Rosas Bobadilla<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-23<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">ARDUINOS: Monitoreando los pulmones de las ciudades<\/td>\n<td style=\"width: 220px\">Liceo T\u00e9cnico Valdivia<\/td>\n<td style=\"width: 192px\">Natalia Paredes Leal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-24<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfD\u00f3nde est\u00e1n los Globos Voladores?<\/td>\n<td style=\"width: 220px\">Colegio Santa Marta Valdivia<\/td>\n<td style=\"width: 192px\">Luz Soto Vega<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-25<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">TITAN<\/td>\n<td style=\"width: 220px\">Liceo San Conrado<\/td>\n<td style=\"width: 192px\">Elvira Monsalve Barrientos<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-26<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Aprendizaje, Redes y Significado: Observando el observar de la experiencia de aprender<\/td>\n<td style=\"width: 220px\">Liceo Industrial Ingeniero Ricardo Fenner<\/td>\n<td style=\"width: 192px\">Maria Marlene Millap\u00e1n Aillap\u00e1n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-27<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfC\u00f3mo afecta el tipo de \u00e1cido en la degradaci\u00f3n de los pol\u00edmeros de Pinus radiata?<\/td>\n<td style=\"width: 220px\">Liceo Industrial Ingeniero Ricardo Fenner<\/td>\n<td style=\"width: 192px\">Maria Marlene Millap\u00e1n Aillap\u00e1n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-28<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Universo: Jugando con un trocito del infinito. Creando un modelo de Universo<\/td>\n<td style=\"width: 220px\">Liceo Vicente P\u00e9rez Rosales<\/td>\n<td style=\"width: 192px\">Carlos Zapata Alarc\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-29<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Canelo v\/s Eucalipto, \u00bfQui\u00e9n se enferma primero?<\/td>\n<td style=\"width: 220px\">Liceo San Conrado<\/td>\n<td style=\"width: 192px\">Carolina Poveda Fil\u00fan<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-30<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Las ni\u00f1xs del terremoto: memoria e historia<\/td>\n<td style=\"width: 220px\">Liceo Rodulfo Amando Philippi<\/td>\n<td style=\"width: 192px\">Mary Anne Fl\u00e1ndez Mu\u00f1oz<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-31<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">De cerveza a hueso: bioimprimiendo en 3D para lograr la regeneraci\u00f3n \u00f3sea<\/td>\n<td style=\"width: 220px\">Instituto Inmaculada Concepci\u00f3n Valdivia<\/td>\n<td style=\"width: 192px\">Mar\u00eda Francisca San Mart\u00edn Heise<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-32<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Convivencia Escolar, un llamado de atenci\u00f3n<\/td>\n<td style=\"width: 220px\">Colegio Jos\u00e9 Manuel Balmaceda<\/td>\n<td style=\"width: 192px\">Gabriela Barrios Riquelme<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-33<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Fuiste ceniza&#8230;ahora eres ballica<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Cristina Villaz\u00f3n Oyarzo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-34<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Paleodieta<\/td>\n<td style=\"width: 220px\">Complejo Educacional Tierra de Esperanza<\/td>\n<td style=\"width: 192px\">Yesenia Uribe V\u00e1ez<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-35<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Conociendo los humedales de nuestra ciudad y sus alrededores (Valdivia, Regi\u00f3n de los R\u00edos, Chile)<\/td>\n<td style=\"width: 220px\">Instituto Superior de Administraci\u00f3n y Turismo&nbsp;<\/td>\n<td style=\"width: 192px\">Jacqueline C\u00e1rdenas M\u00e1rquez<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-36<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">El color que desaparece del agua.<\/td>\n<td style=\"width: 220px\">Instituto Italia<\/td>\n<td style=\"width: 192px\">Marcia Matamala Jara<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-37<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">De lo artificial a lo real, buscando un balance para tu cultivo<\/td>\n<td style=\"width: 220px\">Colegio Bernardo Felmer Niklitschek<\/td>\n<td style=\"width: 192px\">Soledad Cisternas Navarro<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-38<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Ruedan raudas las ruedas<\/td>\n<td style=\"width: 220px\">Liceo Polit\u00e9cnico Werner Grob Stolzenbach<\/td>\n<td style=\"width: 192px\">Edgar Illanes Acu\u00f1a<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-39<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00a1La Regi\u00f3n de Los R\u00edos se mueve!<\/td>\n<td style=\"width: 220px\">Colegio Pufudi<\/td>\n<td style=\"width: 192px\">Elena Ximena Vicencio Andaur<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-40<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Caracterizaci\u00f3n de la calidad de los huevos de campo en la Regi\u00f3n de Los R\u00edos<\/td>\n<td style=\"width: 220px\">Liceo Agr\u00edcola San Javier<\/td>\n<td style=\"width: 192px\">Pablo Barr\u00eda Carrasco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-41<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfQu\u00e9 calidad tiene el agua que est\u00e1n bebiendo los habitantes del sector rural Crucero?<\/td>\n<td style=\"width: 220px\">Escuela Rural Crucero<\/td>\n<td style=\"width: 192px\">Cristina Lara Pacheco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-42<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Efecto antimicrobiano de la miel sobre microbiota bucal<\/td>\n<td style=\"width: 220px\">Liceo Polivalente Camilo Henr\u00edquez Gonz\u00e1lez<\/td>\n<td style=\"width: 192px\">Leslie Arancibia Casanova<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-43<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Los Humedales<\/td>\n<td style=\"width: 220px\">Instituto Cristiano Gracia y Paz<\/td>\n<td style=\"width: 192px\">Jessica &nbsp;Wiederhold Ulloa<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-44<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Matando el c\u00e1ncer a palos<\/td>\n<td style=\"width: 220px\">Liceo Bicentenario de Excelencia Altamira<\/td>\n<td style=\"width: 192px\">Carolina Leiva Y\u00e9venes<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-45<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Reflexiones en torno al discurso oral juvenil en situaciones formales y coloquiales por parte de estudiantes de segundo medio de un colegio de la comuna de Valdivia&nbsp;<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Claudia G\u00f3mez Hern\u00e1ndez<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-46<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfQue ocultan las enterobacterias presentes en los peces del R\u00edo Calle Calle?<\/td>\n<td style=\"width: 220px\">Masters College Valdivia<\/td>\n<td style=\"width: 192px\">Cristina Villaz\u00f3n Oyarzo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-47<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">Temperatura y Acidificaci\u00f3n de los Oc\u00e9anos,estresores de cambio clim\u00e1tico: su efecto sobre la Alimentaci\u00f3n y metabolismo de la ostra chilena.<\/td>\n<td style=\"width: 220px\">Liceo Bicentenario Valdivia<\/td>\n<td style=\"width: 192px\">Carolina Gabriela Verdugo Carre\u00f1o<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-48<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfEs capaz mi profesor de seguir el ritmo de los estudiantes en las salidas a terreno?<\/td>\n<td style=\"width: 220px\">Centro Educativo Fernando Santiv\u00e1n<\/td>\n<td style=\"width: 192px\">Jos\u00e9 Luis Schuwencke R\u00edos<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-49<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfLas papas nativas ser\u00e1n claves en la alimentaci\u00f3n en escenarios futuros de cambio clim\u00e1tico?<\/td>\n<td style=\"width: 220px\">Liceo Rural Llif\u00e9n<\/td>\n<td style=\"width: 192px\">Carlos Patricio Pe\u00f1a y Lillo Anacona<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-50<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">La vida detr\u00e1s de profesores y profesoras<\/td>\n<td style=\"width: 220px\">Colegio Mar\u00eda Auxiliadora<\/td>\n<td style=\"width: 192px\">Daniela Cosimo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-51<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfTodos los \u00e1rboles tienen un mismo tipo de suelo?<\/td>\n<td style=\"width: 220px\">Liceo Rodulfo Amando Philippi<\/td>\n<td style=\"width: 192px\">Gabriel Gonz\u00e1lez Reyes<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 91px\">CREXIV-15-52<\/td>\n<td style=\"width: 147px\">Educaci\u00f3n Media<\/td>\n<td style=\"width: 307px\">\u00bfEscuchas a tus musculos cuando ocupas celular?<\/td>\n<td style=\"width: 220px\">Liceo Alberto Blest&nbsp;Gana<\/td>\n<td style=\"width: 192px\">Enedina Ortiz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 26, 27 y 28 de septiembre m\u00e1s de 170 estudiantes presentar\u00e1n sus investigaciones cient\u00edficas en el XV Congreso Regional Escolar de la Ciencia y la Tecnolog\u00eda Explora de CONICYT para la Regi\u00f3n de Los R\u00edos. Como ya es tradici\u00f3n los stands abrir\u00e1n en el Centro de Ferias del Parque Saval los d\u00edas 26 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36411,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-36413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos - Los R\u00edos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos - Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 26, 27 y 28 de septiembre m\u00e1s de 170 estudiantes presentar\u00e1n sus investigaciones cient\u00edficas en el XV Congreso Regional Escolar de la Ciencia y la Tecnolog\u00eda Explora de CONICYT para la Regi\u00f3n de Los R\u00edos. Como ya es tradici\u00f3n los stands abrir\u00e1n en el Centro de Ferias del Parque Saval los d\u00edas 26 [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Los R\u00edos\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-04T01:11:09+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T19:35:41+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos\",\"datePublished\":\"2018-09-04T01:11:09+00:00\",\"dateModified\":\"2019-05-20T19:35:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\"},\"wordCount\":1393,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\",\"url\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\",\"name\":\"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos - Los R\u00edos\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2018-09-04T01:11:09+00:00\",\"dateModified\":\"2019-05-20T19:35:41+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/rios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#website\",\"url\":\"https:\/\/dev.explora.cl\/rios\/\",\"name\":\"Los R\u00edos\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/rios\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos - Los R\u00edos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/","og_locale":"es_ES","og_type":"article","og_title":"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos - Los R\u00edos","og_description":"El pr\u00f3ximo 26, 27 y 28 de septiembre m\u00e1s de 170 estudiantes presentar\u00e1n sus investigaciones cient\u00edficas en el XV Congreso Regional Escolar de la Ciencia y la Tecnolog\u00eda Explora de CONICYT para la Regi\u00f3n de Los R\u00edos. Como ya es tradici\u00f3n los stands abrir\u00e1n en el Centro de Ferias del Parque Saval los d\u00edas 26 [&hellip;]","og_url":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/","og_site_name":"Los R\u00edos","article_published_time":"2018-09-04T01:11:09+00:00","article_modified_time":"2019-05-20T19:35:41+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos","datePublished":"2018-09-04T01:11:09+00:00","dateModified":"2019-05-20T19:35:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/"},"wordCount":1393,"image":{"@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/","url":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/","name":"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos - Los R\u00edos","isPartOf":{"@id":"https:\/\/dev.explora.cl\/rios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage"},"thumbnailUrl":"","datePublished":"2018-09-04T01:11:09+00:00","dateModified":"2019-05-20T19:35:41+00:00","author":{"@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/rios\/investigaciones-clasificadas-al-xv-congreso-regional-escolar-region-de-los-rios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/rios\/"},{"@type":"ListItem","position":2,"name":"Investigaciones clasificadas al XV Congreso Regional Escolar Regi\u00f3n de Los R\u00edos"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/rios\/#website","url":"https:\/\/dev.explora.cl\/rios\/","name":"Los R\u00edos","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/rios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/rios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/rios\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/36413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/comments?post=36413"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/36413\/revisions"}],"predecessor-version":[{"id":37631,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/posts\/36413\/revisions\/37631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/media?parent=36413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/categories?post=36413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/rios\/wp-json\/wp\/v2\/tags?post=36413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}