{"id":202,"count":19,"description":"","link":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/","name":"TCC","slug":"tcc","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TCC archivos - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"TCC archivos - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/\",\"name\":\"TCC archivos - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/#breadcrumb\"},\"inLanguage\":\"es-CL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TCC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TCC archivos - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/","og_locale":"es_ES","og_type":"article","og_title":"TCC archivos - Coquimbo","og_url":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/","og_site_name":"Coquimbo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/","url":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/","name":"TCC archivos - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/#breadcrumb"},"inLanguage":"es-CL"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/tag\/tcc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"TCC"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts?tags=202"},{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/iniciativa?tags=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}