{"id":39916,"date":"2019-09-23T18:54:08","date_gmt":"2019-09-23T21:54:08","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/?p=39916"},"modified":"2024-02-17T05:59:35","modified_gmt":"2024-02-17T08:59:35","slug":"semanaexplora2019","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/","title":{"rendered":"Conoce todos los detalles de la Semana Explora 2019"},"content":{"rendered":"<h3><strong><em>El evento en la Regi\u00f3n de Coquimbo se desarrollar\u00e1 entre el 06 y el 12 de octubre, y espera reunir a miles de personas frente a la actividad cient\u00edfica y tecnol\u00f3gica.<\/em><\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>La Semana Explora ser\u00e1 el evento cient\u00edfico m\u00e1s importante que se desarrollar\u00e1 en Chile y en especial en la Regi\u00f3n de Coquimbo, reuniendo entre el 06 al 12 de octubre a miles de personas frente a diversas actividades de ciencia y tecnolog\u00eda, buscando acercar estas iniciativas y generando un espacio que promueva la apropiaci\u00f3n social de la ciencia y del conocimiento.<\/p>\n<p>Ciudades como La Serena, Coquimbo, Ovalle, Monte Patria e Illapel, ser\u00e1n el epicentro de estas jornadas, que permitir\u00e1n que investigadores, cient\u00edficos y centros especializados en esta disciplina, puedan mostrar su quehacer, mediante el desarrollo de experiencias de aprendizaje, entretenci\u00f3n y socializaci\u00f3n.<\/p>\n<p>A continuaci\u00f3n, le mostramos un adelanto de las principales actividades que se desarrollar\u00e1n en esta Semana.<\/p>\n<ul>\n<li><u>Domingo 06 de octubre, desde las 12:00 del d\u00eda en el Mall Vivo Coquimbo<\/u><\/li>\n<\/ul>\n<p>Inauguraci\u00f3n Semana Explora, en el marco del \u201cD\u00eda Nacional de la Ciencia, la Tecnolog\u00eda, el Conocimiento y la Innovaci\u00f3n\u201d<\/p>\n<ul>\n<li><u>Martes 08 de octubre, desde las 10:00 en el Centro Cultural de Monte Patria<\/u><\/li>\n<\/ul>\n<p>Jornada astron\u00f3mica que cuenta con charlas sobre el astro turismo que se realiza en la zona, adem\u00e1s de un taller de coheter\u00eda.<\/p>\n<ul>\n<li><u>Entre el martes 08 y el jueves 10 de octubre, en el colegio Amalia Err\u00e1zuriz comuna de Ovalle<\/u><\/li>\n<\/ul>\n<p>Se presentar\u00e1n al p\u00fablico 2 muestras o exhibiciones cient\u00edficas denominadas, Hormigas y Sociedad, adem\u00e1s de la muestra Oc\u00e9anos y Sociedad.<\/p>\n<ul>\n<li><u>Mi\u00e9rcoles 09 de octubre, 11:00, Colegio Andr\u00e9s Bello Centro, La Serena<\/u><\/li>\n<\/ul>\n<p>Charla enmarcada en los #1000C1000A de la Dra. Florencia Tevy, titulada \u201cLa era de la Gen\u00f3mica&#8221;<\/p>\n<ul>\n<li><u>Jueves 10 de octubre, desde las 10:00 en la Plaza de Armas de Illapel<\/u><\/li>\n<\/ul>\n<p>Jornada astron\u00f3mica que cuenta con charlas sobre el astro turismo que se realiza en la zona, adem\u00e1s de un taller de coheter\u00eda.<\/p>\n<ul>\n<li><u>S\u00e1bado 12 de octubre, desde las 11:00 am, en el sector de estacionamientos del Mall Plaza La Serena<\/u><\/li>\n<\/ul>\n<p>Fiesta de la Ciencia 2019, actividad de cierre de la Semana Explora y que reunir\u00e1 a m\u00e1s de veinte instituciones ligadas al quehacer cient\u00edfico de la zona. Pero tambi\u00e9n ser\u00e1 el momento que empresas locales, que muchas veces no est\u00e1n directamente ligadas a actividades de ciencia y tecnolog\u00eda, den cuenta a la comunidad c\u00f3mo en sus procesos, por ejemplo, de filtrado de agua, construcci\u00f3n de casas o de protecci\u00f3n solar, los experimentos son un pilar fundamental para su funcionamiento. Teniendo en cuenta esta informaci\u00f3n, debemos entender que los juegos gratis online ofrecidos por <a href=\"https:\/\/www.desura.com\/es\">Desura<\/a> no solo brindan una experiencia de juego emocionante, sino que tambi\u00e9n representan una excelente oportunidad para fortalecer relaciones y pasar tiempo de calidad con nuestros seres queridos. Uno de sus proyectos exitosos es un juego donde los jugadores colaboran para resolver rompecabezas complejos, desarrollar estrategias y luchar contra adversarios poderosos, destacando la importancia del trabajo en equipo y los logros compartidos.<\/p>\n<ul>\n<li><u>Entre el lunes 07 de octubre y el viernes 11 de octubre:<\/u><\/li>\n<\/ul>\n<p>D\u00eda de la Ciencia en mi Colegio:<a href=\"https:\/\/dev.explora.cl\/coquimbo\/events\/te-invitamos-a-participar-del-dia-de-la-ciencia-en-mi-colegio\/\"> https:\/\/dev.explora.cl\/coquimbo\/events\/te-invitamos-a-participar-del-dia-de-la-ciencia-en-mi-colegio\/<\/a><\/p>\n<p>Museos, Laboratorios y observatorios abiertos, puede conocer m\u00e1s detalle ac\u00e1: <a href=\"https:\/\/dev.explora.cl\/coquimbo\/museos-laboratorios-y-observatorios-abiertos-2019\/\">https:\/\/dev.explora.cl\/coquimbo\/museos-laboratorios-y-observatorios-abiertos-2019\/\u00a0<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-39917 size-large\" src=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/09\/Afiches-Semana-Explora_P\u00e1gina_3-819x1024.jpg\" alt=\"\" width=\"819\" height=\"1024\" srcset=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/09\/Afiches-Semana-Explora_P\u00e1gina_3-819x1024.jpg 819w, https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/09\/Afiches-Semana-Explora_P\u00e1gina_3-240x300.jpg 240w, https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/09\/Afiches-Semana-Explora_P\u00e1gina_3-768x960.jpg 768w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento en la Regi\u00f3n de Coquimbo se desarrollar\u00e1 entre el 06 y el 12 de octubre, y espera reunir a miles de personas frente a la actividad cient\u00edfica y tecnol\u00f3gica.<\/p>\n","protected":false},"author":21,"featured_media":39912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[358],"class_list":["post-39916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-semana-explora"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conoce todos los detalles de la Semana Explora 2019 - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Conoce todos los detalles de la Semana Explora 2019 - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El evento en la Regi\u00f3n de Coquimbo se desarrollar\u00e1 entre el 06 y el 12 de octubre, y espera reunir a miles de personas frente a la actividad cient\u00edfica y tecnol\u00f3gica.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-23T21:54:08+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-17T08:59:35+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1534\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"875\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"jimartin\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"jimartin\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\"},\"author\":{\"name\":\"jimartin\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/c171f405669e4e4f7e56a099200d2fe6\"},\"headline\":\"Conoce todos los detalles de la Semana Explora 2019\",\"datePublished\":\"2019-09-23T21:54:08+00:00\",\"dateModified\":\"2024-02-17T08:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png\",\"keywords\":[\"Semana Explora\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\",\"name\":\"Conoce todos los detalles de la Semana Explora 2019 - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png\",\"datePublished\":\"2019-09-23T21:54:08+00:00\",\"dateModified\":\"2024-02-17T08:59:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png\",\"width\":1534,\"height\":875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce todos los detalles de la Semana Explora 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/c171f405669e4e4f7e56a099200d2fe6\",\"name\":\"jimartin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8dfd7d14443934731a5aea629f40c1aceb42cc8b566a9926567e833c9d22b643?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8dfd7d14443934731a5aea629f40c1aceb42cc8b566a9926567e833c9d22b643?s=96&d=mm&r=g\",\"caption\":\"jimartin\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/jimartin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce todos los detalles de la Semana Explora 2019 - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce todos los detalles de la Semana Explora 2019 - Coquimbo","og_description":"El evento en la Regi\u00f3n de Coquimbo se desarrollar\u00e1 entre el 06 y el 12 de octubre, y espera reunir a miles de personas frente a la actividad cient\u00edfica y tecnol\u00f3gica.","og_url":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/","og_site_name":"Coquimbo","article_published_time":"2019-09-23T21:54:08+00:00","article_modified_time":"2024-02-17T08:59:35+00:00","og_image":[{"width":1534,"height":875,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png","type":"image\/png"}],"author":"jimartin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jimartin","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/"},"author":{"name":"jimartin","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/c171f405669e4e4f7e56a099200d2fe6"},"headline":"Conoce todos los detalles de la Semana Explora 2019","datePublished":"2019-09-23T21:54:08+00:00","dateModified":"2024-02-17T08:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png","keywords":["Semana Explora"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/","url":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/","name":"Conoce todos los detalles de la Semana Explora 2019 - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png","datePublished":"2019-09-23T21:54:08+00:00","dateModified":"2024-02-17T08:59:35+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2019\/04\/Semana-Explora.png","width":1534,"height":875},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/semanaexplora2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"Conoce todos los detalles de la Semana Explora 2019"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/c171f405669e4e4f7e56a099200d2fe6","name":"jimartin","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8dfd7d14443934731a5aea629f40c1aceb42cc8b566a9926567e833c9d22b643?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8dfd7d14443934731a5aea629f40c1aceb42cc8b566a9926567e833c9d22b643?s=96&d=mm&r=g","caption":"jimartin"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/jimartin\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/39916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=39916"}],"version-history":[{"count":11,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/39916\/revisions"}],"predecessor-version":[{"id":43365,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/39916\/revisions\/43365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/39912"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=39916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=39916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=39916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}