{"id":38051,"date":"2015-08-25T00:00:00","date_gmt":"2015-08-25T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/blog\/2015\/08\/25\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos\/"},"modified":"2019-05-16T06:36:00","modified_gmt":"2019-05-16T06:36:00","slug":"par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/","title":{"rendered":"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14123\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/08\/d054faa07a98715a7d1de7165210509b.jpg\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/p>\n<p><p>Las inclemencias clim\u00e1ticas que afectaron a la zona central hace algunas semanas, retrasaron la realizaci\u00f3n de este evento que busca celebrar a los m\u00e1s peque\u00f1os de la comuna de Coquimbo, pero a pesar de los contratiempos, m\u00e1s de 15.000 personas llegaron a la tradicional Pampilla de los Ni\u00f1os, realizada durante el domingo 23 de agosto.<\/p>\n<p>M\u00fasica y baile, muchos ni\u00f1os y ni\u00f1as con las caras pintadas, globos y sonrisas, fueron s\u00f3lo algunas de las caracter\u00edsticas que rodearon este evento, que reuni\u00f3 a las familias porte\u00f1as en torno a la fiesta y la alegr\u00eda.<\/p>\n<p>El PAR EXPLORA Coquimbo no se quiso quedar ajeno a esta fiesta y a trav\u00e9s de sus did\u00e1cticas muestras y exposiciones, pudo llevar un momento agradables a los cientos de personas que se acercaron al stand.<\/p>\n<p>Muestras de Biodiversidad, talleres para los m\u00e1s peque\u00f1os vinculados a actividades medioambientales y la difusi\u00f3n de las ciencias de forma entretenida, fueron la t\u00f3nica de la jornada.<\/p>\n<p>La actividad fue organizada por el Municipio de Coquimbo y cont\u00f3 con la participaci\u00f3n de diversos stand del orden institucional, como Carabineros, PDI, Gesti\u00f3n Ambienta, como tambi\u00e9n de ferias con juegos y golosinas para los m\u00e1s peque\u00f1os del hogar.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las inclemencias clim\u00e1ticas que afectaron a la zona central hace algunas semanas, retrasaron la realizaci\u00f3n de este evento que busca celebrar a los m\u00e1s peque\u00f1os de la comuna de Coquimbo, pero a pesar de los contratiempos, m\u00e1s de 15.000 personas llegaron a la tradicional Pampilla de los Ni\u00f1os, realizada durante el domingo 23 de agosto. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Las inclemencias clim\u00e1ticas que afectaron a la zona central hace algunas semanas, retrasaron la realizaci\u00f3n de este evento que busca celebrar a los m\u00e1s peque\u00f1os de la comuna de Coquimbo, pero a pesar de los contratiempos, m\u00e1s de 15.000 personas llegaron a la tradicional Pampilla de los Ni\u00f1os, realizada durante el domingo 23 de agosto. [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-25T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T06:36:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"222\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"110\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os\",\"datePublished\":\"2015-08-25T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\"},\"wordCount\":229,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\",\"name\":\"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg\",\"datePublished\":\"2015-08-25T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg\",\"width\":222,\"height\":110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/","og_locale":"es_ES","og_type":"article","og_title":"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os - Coquimbo","og_description":"Las inclemencias clim\u00e1ticas que afectaron a la zona central hace algunas semanas, retrasaron la realizaci\u00f3n de este evento que busca celebrar a los m\u00e1s peque\u00f1os de la comuna de Coquimbo, pero a pesar de los contratiempos, m\u00e1s de 15.000 personas llegaron a la tradicional Pampilla de los Ni\u00f1os, realizada durante el domingo 23 de agosto. [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/","og_site_name":"Coquimbo","article_published_time":"2015-08-25T04:00:00+00:00","article_modified_time":"2019-05-16T06:36:00+00:00","og_image":[{"width":222,"height":110,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os","datePublished":"2015-08-25T04:00:00+00:00","dateModified":"2019-05-16T06:36:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/"},"wordCount":229,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/","url":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/","name":"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg","datePublished":"2015-08-25T04:00:00+00:00","dateModified":"2019-05-16T06:36:00+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Lafoto.jpg","width":222,"height":110},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-la-tradicional-pampilla-de-los-ninos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"PAR EXPLORA Coquimbo particip\u00f3 de la tradicional Pampilla de los Ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=38051"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38051\/revisions"}],"predecessor-version":[{"id":39141,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38051\/revisions\/39141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/32204"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=38051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=38051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=38051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}