{"id":38049,"date":"2015-08-21T00:00:00","date_gmt":"2015-08-21T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/blog\/2015\/08\/21\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/"},"modified":"2019-05-16T06:36:01","modified_gmt":"2019-05-16T06:36:01","slug":"el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/","title":{"rendered":"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14057\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/08\/25f14b9d41ace6e75176d9a81e4377af.jpg\" alt=\"\" width=\"960\" height=\"640\" \/><\/p>\n<div class=\"WordSection1\">\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">La Comisi\u00f3n Nacional de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica, CONICYT, a trav\u00e9s de su Programa Explora, realiza un nuevo llamado a las regiones del pa\u00eds a presentar propuestas para el Concurso de Proyectos Asociativos Regionales (PAR) de Divulgaci\u00f3n y Valoraci\u00f3n Cient\u00edfica y Tecnol\u00f3gica.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">Desde 1995 el Programa Explora CONICYT convoca a personas naturales e instituciones acad\u00e9micas y de investigaci\u00f3n de todo el pa\u00eds a presentar propuestas integrales, que busquen desarrollar acciones orientadas a <\/span><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif';background: white none repeat scroll 0% 0%\">la creaci\u00f3n de una cultura cient\u00edfica y tecnol\u00f3gica en la comunidad<\/span><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">, a trav\u00e9s de equipos presentes en todo el pa\u00eds.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">\u201cNuestras regiones poseen un enorme potencial y competencias para desarrollar proyectos que colaboren en la transformaci\u00f3n de nuestra sociedad, para que ni\u00f1as, ni\u00f1os y j\u00f3venes vislumbren la ciencia como una actividad posible en su futuro profesional. El fortalecimiento de las capacidades regionales se consolida como una de las l\u00edneas de acci\u00f3n fundamentales para el Programa Explora\u201d, expres\u00f3 Francisco Brieva, presidente de CONICYT.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">Las personas naturales o instituciones que resulten beneficiadas con este concurso, cuya convocatoria se realiza cada tres a\u00f1os, tendr\u00e1n la misi\u00f3n de construir un Proyecto Asociativo Regional, que incorpore los lineamientos estrat\u00e9gicos propios de cada territorio, reconociendo as\u00ed la identidad, complejidad y desaf\u00edos de cada regi\u00f3n, y posibilitando de manera integradora y asociativa el fomento de una cultura cient\u00edfica y tecnol\u00f3gica en todo el territorio nacional.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\"> <\/p>\n<div class=\"WordSection1\">\n<p style=\"text-align: justify\"><strong><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">Para la IV Regi\u00f3n de Coquimbo, el Taller de Postulaci\u00f3n se realizar\u00e1 el lunes 24 de agosto a las 11:00 hrs. en el Sal\u00f3n CRDP, ubicado en Almagro 289, La Serena. <\/span><\/strong><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">El encuentro contar\u00e1 con la presencia de Nicol\u00e1s Schneider, Coordinador de Fortalecimiento Regional del Programa Explora CONICYT.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">Cabe recordar que el plazo para presentar las propuestas vence el viernes 16 de octubre de 2015, a las 15:01 horas, horario continental.<\/span><\/p>\n<\/p><\/div>\n<p> <span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\"><\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">Las bases del IV Concurso de Proyectos Asociativos Regionales de Divulgaci\u00f3n y Valoraci\u00f3n Cient\u00edfica y Tecnol\u00f3gica 2016, est\u00e1n disponibles en el sitio <\/span><span><a href=\"http:\/\/www.conicyt.cl\/explora\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">www.conicyt.cl\/explora<\/span><\/a><\/span><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">; <\/span><span><a href=\"https:\/\/dev.explora.cl\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">dev.explora.cl<\/span><\/a><\/span><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">Para m\u00e1s consultas puede dirigirse a <\/span><span><a href=\"http:\/\/www.conicyt.cl\/oirs\"><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">www.conicyt.cl\/oirs<\/span><\/a><\/span><span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\">.<\/span><\/p>\n<\/p><\/div>\n<p> <span style=\"font-size: 11pt;font-family: 'Verdana','sans-serif'\"><br \/> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Nacional de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica, CONICYT, a trav\u00e9s de su Programa Explora, realiza un nuevo llamado a las regiones del pa\u00eds a presentar propuestas para el Concurso de Proyectos Asociativos Regionales (PAR) de Divulgaci\u00f3n y Valoraci\u00f3n Cient\u00edfica y Tecnol\u00f3gica. Desde 1995 el Programa Explora CONICYT convoca a personas naturales e instituciones acad\u00e9micas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n Nacional de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica, CONICYT, a trav\u00e9s de su Programa Explora, realiza un nuevo llamado a las regiones del pa\u00eds a presentar propuestas para el Concurso de Proyectos Asociativos Regionales (PAR) de Divulgaci\u00f3n y Valoraci\u00f3n Cient\u00edfica y Tecnol\u00f3gica. Desde 1995 el Programa Explora CONICYT convoca a personas naturales e instituciones acad\u00e9micas [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-21T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T06:36:01+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones\",\"datePublished\":\"2015-08-21T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\",\"name\":\"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg\",\"datePublished\":\"2015-08-21T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/","og_locale":"es_ES","og_type":"article","og_title":"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones - Coquimbo","og_description":"La Comisi\u00f3n Nacional de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica, CONICYT, a trav\u00e9s de su Programa Explora, realiza un nuevo llamado a las regiones del pa\u00eds a presentar propuestas para el Concurso de Proyectos Asociativos Regionales (PAR) de Divulgaci\u00f3n y Valoraci\u00f3n Cient\u00edfica y Tecnol\u00f3gica. Desde 1995 el Programa Explora CONICYT convoca a personas naturales e instituciones acad\u00e9micas [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/","og_site_name":"Coquimbo","article_published_time":"2015-08-21T04:00:00+00:00","article_modified_time":"2019-05-16T06:36:01+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones","datePublished":"2015-08-21T04:00:00+00:00","dateModified":"2019-05-16T06:36:01+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/","url":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/","name":"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg","datePublished":"2015-08-21T04:00:00+00:00","dateModified":"2019-05-16T06:36:01+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/25f14b9d41ace6e75176d9a81e4377af.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-programa-explora-conicyt-abre-concurso-de-proyectos-de-divulgacion-para-todas-las-regiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"El Programa Explora CONICYT abre concurso de proyectos de divulgaci\u00f3n para todas las regiones"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=38049"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38049\/revisions"}],"predecessor-version":[{"id":39142,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38049\/revisions\/39142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/33910"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=38049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=38049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=38049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}