{"id":38031,"date":"2015-07-29T00:00:00","date_gmt":"2015-07-29T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/blog\/2015\/07\/29\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/"},"modified":"2019-05-16T06:36:13","modified_gmt":"2019-05-16T06:36:13","slug":"este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/","title":{"rendered":"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-13346\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/07\/31f5636df1285162acdc40a46cdef36a.jpg\" alt=\"\" width=\"556\" height=\"361\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">Aprender de forma entretenida. Esa es una de los t\u00f3picos principales que tiene la muestra \u201cExpoAzares\u201d, una exposici\u00f3n interactiva que el Proyecto Asociativo Regional, PAR EXPLORA Coquimbo de la UCN y el Museo del Limar\u00ed, tendr\u00e1n durante el mes de agosto para toda la comunidad de Ovalle y de los alrededores.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">La exposici\u00f3n se compone de dos muestras complementarias, la primera llamada Juegos, Estrategias y Azares y la segunda Los Azares de la Vida. A trav\u00e9s de 4 m\u00f3dulos y exhibiciones esta muestra presenta diversas situaciones de la vida diaria relacionadas con las matem\u00e1ticas como los juegos de azar, la arquitectura de un edificio, la pol\u00edtica monetaria de un pa\u00eds y el azar de la gen\u00e9tica.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">La propuesta de la exposici\u00f3n es descubrir la presencia de esta ciencia exacta y el azar en las m\u00e1s variadas situaciones cotidianas. Una elecci\u00f3n determinada genera un resultado, pero este es producto de un pensamiento profundo o la simple casualidad y en esta muestra se pueden responder las interrogantes.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">Para Yendery Cerda, Coordinadora Ejecutiva del PAR EXPLORA Coquimbo, esta actividad \u201ces un espacio a trav\u00e9s del cual los ni\u00f1os y adultos podr\u00e1n acercarse a la magia de las matem\u00e1ticas, muchas veces temida, desde una forma entretenida y l\u00fadica\u201d.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">\u201cLos Azares de la Vida\u201d, \u201cAzar y Certidumbre\u201d, \u201cUn riesgo calculado\u201d, \u201cAzar Domado\u201d, \u201cInnato o adquirido\u201d o \u201c\u00bfJuega dios a los dados?\u201d, son los nombres de algunas de las entretenidas muestras que est\u00e1n destinadas a ni\u00f1os y ni\u00f1as desde 7mo b\u00e1sico en adelante, pero los m\u00e1s peque\u00f1os igual pueden aprender con estas actividades.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">La Directora del Museo del Limar\u00ed, Daniela Serani, afirm\u00f3 que esta muestra permitir\u00e1 que el p\u00fablico de Ovalle pueda \u201cacercarse al Museo, al conocimiento y a la informaci\u00f3n, de una manera entretenida, para nosotros es muy importante esta exposici\u00f3n, pues con ella comenzamos a celebrar a nuestros ni\u00f1os y ni\u00f1as en su mes\u201d.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">La \u201cExpoAzares\u201d estar\u00e1 en el museo del Limar\u00ed desde este jueves 30 de Julio, a contar de las 10:00 am y su inauguraci\u00f3n ser\u00e1 el viernes 31 del presente, a contar de las 16:00.<\/p>\n<p style=\"margin-left: 18pt;text-align: justify\">La muestra se presentar\u00e1 hasta el 5 de septiembre en el siguiente horario:<\/p>\n<p style=\"text-align: justify;text-indent: -18pt\"><span><span>&#8211;<span style=\"font: 7pt 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><\/span>Martes a viernes : 10 a 18 horas<\/p>\n<p style=\"text-align: justify;text-indent: -18pt\"><span><span>&#8211;<span style=\"font: 7pt 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><\/span>S\u00e1bado y Domingo: 10 a 14 horas<\/p>\n<p style=\"text-align: justify\">Les recordamos adem\u00e1s, que la entrada al Museo del Limar\u00ed y a todas sus actividades es gratuita.<\/p>\n<p style=\"text-align: justify\">Para mayor informaci\u00f3n, contactarse a <a href=\"mailto:museolimaridibam@gmail.com\"><a>museolimaridibam@gmail.com<\/a><\/a><\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\">Por Juan Ignacio Martin<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Aprender de forma entretenida. Esa es una de los t\u00f3picos principales que tiene la muestra \u201cExpoAzares\u201d, una exposici\u00f3n interactiva que el Proyecto Asociativo Regional, PAR EXPLORA Coquimbo de la UCN y el Museo del Limar\u00ed, tendr\u00e1n durante el mes de agosto para toda la comunidad de Ovalle y de los alrededores. La exposici\u00f3n se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Aprender de forma entretenida. Esa es una de los t\u00f3picos principales que tiene la muestra \u201cExpoAzares\u201d, una exposici\u00f3n interactiva que el Proyecto Asociativo Regional, PAR EXPLORA Coquimbo de la UCN y el Museo del Limar\u00ed, tendr\u00e1n durante el mes de agosto para toda la comunidad de Ovalle y de los alrededores. La exposici\u00f3n se [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-29T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T06:36:13+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"556\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed\",\"datePublished\":\"2015-07-29T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\",\"name\":\"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg\",\"datePublished\":\"2015-07-29T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg\",\"width\":556,\"height\":361},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/","og_locale":"es_ES","og_type":"article","og_title":"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed - Coquimbo","og_description":"&nbsp; Aprender de forma entretenida. Esa es una de los t\u00f3picos principales que tiene la muestra \u201cExpoAzares\u201d, una exposici\u00f3n interactiva que el Proyecto Asociativo Regional, PAR EXPLORA Coquimbo de la UCN y el Museo del Limar\u00ed, tendr\u00e1n durante el mes de agosto para toda la comunidad de Ovalle y de los alrededores. La exposici\u00f3n se [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/","og_site_name":"Coquimbo","article_published_time":"2015-07-29T04:00:00+00:00","article_modified_time":"2019-05-16T06:36:13+00:00","og_image":[{"width":556,"height":361,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed","datePublished":"2015-07-29T04:00:00+00:00","dateModified":"2019-05-16T06:36:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/","url":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/","name":"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg","datePublished":"2015-07-29T04:00:00+00:00","dateModified":"2019-05-16T06:36:13+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/31f5636df1285162acdc40a46cdef36a.jpg","width":556,"height":361},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/este-viernes-se-inaugura-la-expoazares-en-el-museo-del-limari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"Este viernes se inaugura la \u201cExpoAzares\u201d en el Museo del Limar\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=38031"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38031\/revisions"}],"predecessor-version":[{"id":39160,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38031\/revisions\/39160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/33896"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=38031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=38031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=38031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}