{"id":38026,"date":"2015-07-22T00:00:00","date_gmt":"2015-07-22T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/blog\/2015\/07\/22\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/"},"modified":"2019-05-16T06:36:21","modified_gmt":"2019-05-16T06:36:21","slug":"el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/","title":{"rendered":"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-13211\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/07\/783186a33c3f0090659e10577e0624df.jpg\" alt=\"\" width=\"448\" height=\"300\" \/><\/p>\n<p><p><span>El instituto ant\u00e1rtico de Chile (INACH) ampl\u00eda el plazo de postulaci\u00f3n para enviar proyectos de investigaci\u00f3n escolar relacionados al continente ant\u00e1rtico hasta el 30 de Septiembre del 2015. <\/span><\/p>\n<p><span>Los establecimientos educacionales de la regi\u00f3n podr\u00e1n participar del Segundo Encuentro de Ciencia Escolar Ant\u00e1rtica a desarrollarse el 25 de Septiembre en la UCN de Coquimbo. <\/span><\/p>\n<p><span>Consultas dirigirlas a Daniel Pi\u00f1ones Tapia (<a href=\"mailto:dpionest@yahoo.es\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: blue\">dpionest@yahoo.es<\/span><\/a>) Encargado de Redes de Comunidades Educativas. &nbsp;<\/span><\/p>\n<p><span>Revisa m\u00e1s sobre este concurso <a target=\"_blank\" href=\"coquimbo\/noticias-coquimbo\/5762-atencion-jovenes-investigadores-ya-pueden-postular-a-la-fae-2015\" rel=\"noopener noreferrer\"><strong>en el siguiente link.<\/strong><\/a><\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El instituto ant\u00e1rtico de Chile (INACH) ampl\u00eda el plazo de postulaci\u00f3n para enviar proyectos de investigaci\u00f3n escolar relacionados al continente ant\u00e1rtico hasta el 30 de Septiembre del 2015. Los establecimientos educacionales de la regi\u00f3n podr\u00e1n participar del Segundo Encuentro de Ciencia Escolar Ant\u00e1rtica a desarrollarse el 25 de Septiembre en la UCN de Coquimbo. Consultas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015 - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015 - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El instituto ant\u00e1rtico de Chile (INACH) ampl\u00eda el plazo de postulaci\u00f3n para enviar proyectos de investigaci\u00f3n escolar relacionados al continente ant\u00e1rtico hasta el 30 de Septiembre del 2015. Los establecimientos educacionales de la regi\u00f3n podr\u00e1n participar del Segundo Encuentro de Ciencia Escolar Ant\u00e1rtica a desarrollarse el 25 de Septiembre en la UCN de Coquimbo. Consultas [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-22T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T06:36:21+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015\",\"datePublished\":\"2015-07-22T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\",\"name\":\"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015 - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-07-22T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015 - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/","og_locale":"es_ES","og_type":"article","og_title":"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015 - Coquimbo","og_description":"El instituto ant\u00e1rtico de Chile (INACH) ampl\u00eda el plazo de postulaci\u00f3n para enviar proyectos de investigaci\u00f3n escolar relacionados al continente ant\u00e1rtico hasta el 30 de Septiembre del 2015. Los establecimientos educacionales de la regi\u00f3n podr\u00e1n participar del Segundo Encuentro de Ciencia Escolar Ant\u00e1rtica a desarrollarse el 25 de Septiembre en la UCN de Coquimbo. Consultas [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/","og_site_name":"Coquimbo","article_published_time":"2015-07-22T04:00:00+00:00","article_modified_time":"2019-05-16T06:36:21+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015","datePublished":"2015-07-22T04:00:00+00:00","dateModified":"2019-05-16T06:36:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/","url":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/","name":"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015 - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-07-22T04:00:00+00:00","dateModified":"2019-05-16T06:36:21+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/el-instituto-antartico-de-chile-amplia-el-plazo-de-postulacion-de-la-fae-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"El Instituto Ant\u00e1rtico de Chile ampl\u00eda el plazo de postulaci\u00f3n de la FAE 2015"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=38026"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38026\/revisions"}],"predecessor-version":[{"id":39167,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38026\/revisions\/39167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/32165"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=38026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=38026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=38026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}