{"id":38023,"date":"2015-07-21T00:00:00","date_gmt":"2015-07-21T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/blog\/2015\/07\/21\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/"},"modified":"2019-05-16T06:36:21","modified_gmt":"2019-05-16T06:36:21","slug":"par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/","title":{"rendered":"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-13156\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/07\/1be7253ab9fc17043811a023b7d4a845.jpg\" alt=\"\" width=\"2816\" height=\"2112\" \/><\/p>\n<p><p>Una entretenida semana vivieron los m\u00e1s de 40 ni\u00f1os y j\u00f3venes que participaron de la segunda versi\u00f3n de los Talleres de Invierno \u201cCiencia Entretenida\u201d organizados por el Departamento de Comunicaciones, Extensi\u00f3n y Admisi\u00f3n (DECOEA) de la Universidad Cat\u00f3lica del Norte (UCN), sede Coquimbo; Telescopio Gemini, AURA; y PAR Explora Coquimbo.<\/p>\n<p>Los cursos estaban dirigidos a ni\u00f1os y j\u00f3venes de 12 a 17 a\u00f1os que deseen experimentar, de forma l\u00fadica y pr\u00e1ctica, los encantos de la rob\u00f3tica, la coheter\u00eda, la f\u00edsica y la astronom\u00eda, adem\u00e1s de conocer caracter\u00edsticas de la Ant\u00e1rtica y adquirir conocimientos sobre las ciencias relacionadas con el mar.<\/p>\n<p>El PAR EXPLORA Coquimbo realiz\u00f3 diversas actividades a los ni\u00f1os que se acercaron a esta instancia.<\/p>\n<p>Mejorar su pensamiento cr\u00edtico con las especies marinas, a trav\u00e9s de un Taller de la RAM y el trabajo con las ciencias del mar, fue lo que ellos pudieron disfrutar, todo en el marco de una actividad l\u00fadica y entretenida.<\/p>\n<p>Para, Jessica Vargas, encargada de valoraci\u00f3n de PAR Explora Coquimbo, valor\u00f3 la participaci\u00f3n del programa en los talleres de invierno UCN, \u201cha sido una experiencia muy bonita, estamos muy contentos de ser parte de estas actividades que nos permite dar a conocer las nuestras iniciativas y llevar nuestros talleres a la comunidad\u201d.<\/p>\n<p>Por: UCN\/Juan Ignacio Martin<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una entretenida semana vivieron los m\u00e1s de 40 ni\u00f1os y j\u00f3venes que participaron de la segunda versi\u00f3n de los Talleres de Invierno \u201cCiencia Entretenida\u201d organizados por el Departamento de Comunicaciones, Extensi\u00f3n y Admisi\u00f3n (DECOEA) de la Universidad Cat\u00f3lica del Norte (UCN), sede Coquimbo; Telescopio Gemini, AURA; y PAR Explora Coquimbo. Los cursos estaban dirigidos a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Una entretenida semana vivieron los m\u00e1s de 40 ni\u00f1os y j\u00f3venes que participaron de la segunda versi\u00f3n de los Talleres de Invierno \u201cCiencia Entretenida\u201d organizados por el Departamento de Comunicaciones, Extensi\u00f3n y Admisi\u00f3n (DECOEA) de la Universidad Cat\u00f3lica del Norte (UCN), sede Coquimbo; Telescopio Gemini, AURA; y PAR Explora Coquimbo. Los cursos estaban dirigidos a [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-21T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T06:36:21+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845-1024x768.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN\",\"datePublished\":\"2015-07-21T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\"},\"wordCount\":247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\",\"name\":\"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg\",\"datePublished\":\"2015-07-21T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg\",\"width\":2816,\"height\":2112},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/","og_locale":"es_ES","og_type":"article","og_title":"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN - Coquimbo","og_description":"Una entretenida semana vivieron los m\u00e1s de 40 ni\u00f1os y j\u00f3venes que participaron de la segunda versi\u00f3n de los Talleres de Invierno \u201cCiencia Entretenida\u201d organizados por el Departamento de Comunicaciones, Extensi\u00f3n y Admisi\u00f3n (DECOEA) de la Universidad Cat\u00f3lica del Norte (UCN), sede Coquimbo; Telescopio Gemini, AURA; y PAR Explora Coquimbo. Los cursos estaban dirigidos a [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/","og_site_name":"Coquimbo","article_published_time":"2015-07-21T04:00:00+00:00","article_modified_time":"2019-05-16T06:36:21+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845-1024x768.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN","datePublished":"2015-07-21T04:00:00+00:00","dateModified":"2019-05-16T06:36:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/"},"wordCount":247,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/","url":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/","name":"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg","datePublished":"2015-07-21T04:00:00+00:00","dateModified":"2019-05-16T06:36:21+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/1be7253ab9fc17043811a023b7d4a845.jpg","width":2816,"height":2112},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-participo-de-los-talleres-de-invierno-de-la-ucn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"PAR EXPLORA Coquimbo particip\u00f3 de los Talleres de Invierno de la UCN"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=38023"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38023\/revisions"}],"predecessor-version":[{"id":39168,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38023\/revisions\/39168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/33890"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=38023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=38023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=38023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}