{"id":38020,"date":"2015-07-15T00:00:00","date_gmt":"2015-07-15T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/blog\/2015\/07\/15\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle\/"},"modified":"2019-05-16T06:36:25","modified_gmt":"2019-05-16T06:36:25","slug":"par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/","title":{"rendered":"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-13069\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/07\/e61b2ad1b1d6a11e4904c66901921ce9.jpg\" alt=\"\" width=\"2816\" height=\"2112\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En el mall Open Plaza de la ciudad de Ovalle, se est\u00e1 presentando la muestra \u201cAcercando el Mar al Valle\u201d, una instancia que permite disfrutar de las ciencias y las actividades marinas en estas vacaciones de invierno.<\/p>\n<p>Las muestras est\u00e1n orientadas a los m\u00e1s peque\u00f1os, pero tanto adultos, como la comunidad en general, pueden disfrutar de lo que el PAR EXPLORA Coquimbo de la UCN y el DIBAM llevaron para el p\u00fablico ovallino.<\/p>\n<p>Es as\u00ed como en el patio del Centro Comercial se mont\u00f3 un stand con muestras del \u00e1rea marina, en este caso de ecolog\u00eda marina, como de la contaminaci\u00f3n del sector costero, sumado al proyecto Cient\u00edficos de la Basura, encargados de divulgar estos alcances. Adem\u00e1s el acuario de la UCN aport\u00f3 con muestras de animales vivos y disecados.<\/p>\n<p>Para Yendery Cerda, Coordinadora Ejecutiva del PAR EXPLORA Coquimbo, la actividad que se realiza en las vacaciones de invierno permite traer y llevar la ciencia y tecnolog\u00eda a la comunidad limarina, afirmando que \u201cLa gracia de estas actividades es el hecho de aprender de forma m\u00e1s entretenida, de forma l\u00fadica. La idea es que a partir de juegos, los m\u00e1s peque\u00f1os aprendan\u201d.<\/p>\n<p>Leonardo Rivera, uno de los asistentes a la muestra y padre de uno de los menores que disfrut\u00f3 con lo ofrecido, afirm\u00f3 que \u201cme parece bastante bien que lleguen estas actividades, para que los ni\u00f1os conozcan un poco m\u00e1s y aprovechen de otra forma el saber sobre el cuidado que se tiene que tener con el planeta\u201d.<\/p>\n<p>La muestra estar\u00e1 hasta el 17 de Julio en el Open Plaza, a contar de las 11 de la ma\u00f1ana y hasta las 18 de la tarde. Adem\u00e1s, los asistentes podr\u00e1n disfrutar de muestras culturales del DIBAM M\u00f3vil.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; En el mall Open Plaza de la ciudad de Ovalle, se est\u00e1 presentando la muestra \u201cAcercando el Mar al Valle\u201d, una instancia que permite disfrutar de las ciencias y las actividades marinas en estas vacaciones de invierno. Las muestras est\u00e1n orientadas a los m\u00e1s peque\u00f1os, pero tanto adultos, como la comunidad en general, pueden [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"&nbsp; En el mall Open Plaza de la ciudad de Ovalle, se est\u00e1 presentando la muestra \u201cAcercando el Mar al Valle\u201d, una instancia que permite disfrutar de las ciencias y las actividades marinas en estas vacaciones de invierno. Las muestras est\u00e1n orientadas a los m\u00e1s peque\u00f1os, pero tanto adultos, como la comunidad en general, pueden [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-15T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T06:36:25+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle\",\"datePublished\":\"2015-07-15T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\",\"name\":\"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg\",\"datePublished\":\"2015-07-15T04:00:00+00:00\",\"dateModified\":\"2019-05-16T06:36:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/","og_locale":"es_ES","og_type":"article","og_title":"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle - Coquimbo","og_description":"&nbsp; En el mall Open Plaza de la ciudad de Ovalle, se est\u00e1 presentando la muestra \u201cAcercando el Mar al Valle\u201d, una instancia que permite disfrutar de las ciencias y las actividades marinas en estas vacaciones de invierno. Las muestras est\u00e1n orientadas a los m\u00e1s peque\u00f1os, pero tanto adultos, como la comunidad en general, pueden [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/","og_site_name":"Coquimbo","article_published_time":"2015-07-15T04:00:00+00:00","article_modified_time":"2019-05-16T06:36:25+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle","datePublished":"2015-07-15T04:00:00+00:00","dateModified":"2019-05-16T06:36:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/","url":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/","name":"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg","datePublished":"2015-07-15T04:00:00+00:00","dateModified":"2019-05-16T06:36:25+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/06\/Pedro-lvarez.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/par-explora-coquimbo-de-la-ucn-lleva-el-mar-a-ovalle-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"PAR EXPLORA Coquimbo de la UCN lleva el mar a Ovalle"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=38020"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38020\/revisions"}],"predecessor-version":[{"id":39172,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/38020\/revisions\/39172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/32155"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=38020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=38020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=38020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}