{"id":37506,"date":"2018-12-28T08:00:10","date_gmt":"2018-12-28T12:00:10","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/?p=37506"},"modified":"2019-05-20T16:48:31","modified_gmt":"2019-05-20T16:48:31","slug":"vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/","title":{"rendered":"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena"},"content":{"rendered":"<p style=\"text-align: center\"><strong>\u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d, es el nombre de la jornada que se realizar\u00e1 en la Scuola Italiana.<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify\">Ya se encuentra disponible la lista de docentes seleccionado\/as para participar de la jornada de actualizaci\u00f3n docente, <strong>\u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d<\/strong> que se desarrollar\u00e1 entre el 2 y 3 de enero en la<strong> Scuola Italiana de La Serena.<\/strong><\/p>\n<p style=\"text-align: justify\">Cabe consignar que se recibieron <strong>85 postulaciones<\/strong> en total (38 La Serena, 26 Coquimbo, 5 Vicu\u00f1a, 3 Monte Patria, 3 Ovalle, 2 Punitaqui y 1 Paihuano) y que la iniciativa constaba de 30 cupos, pero en vista de la cantidad de postulantes, <strong>se ampli\u00f3 a de 40 cupos para la Regi\u00f3n de Coquimbo.<\/strong><\/p>\n<p style=\"text-align: justify\">Los criterios y requisitos de selecci\u00f3n, expuestos en las Bases de Postulaci\u00f3n que regulan el Proyecto <strong>PAR Explora de CONICYT Coquimbo<\/strong>, incluyen: 1) Cobertura territorial incluyendo el m\u00e1ximo de comunas y Establecimientos de la Regi\u00f3n de Coquimbo, 2) Consideraci\u00f3n a la vulnerabilidad y car\u00e1cter de ruralidad de los Establecimientos Educacionales participantes y 3) la fidelizaci\u00f3n de los participantes.<\/p>\n<p>Puede ver ac\u00e1 la lista de seleccionados:\u00a0<a href=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/8\/2018\/12\/Acta-Seleccionados-JAD-2019.pdf\">Acta Seleccionados JAD 2019<\/a><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37440 size-large\" src=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/8\/2018\/12\/Programa-Capacitaci\u00f3n-Docente-791x1024.jpg\" alt=\"\" width=\"791\" height=\"1024\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d, es el nombre de la jornada que se realizar\u00e1 en la Scuola Italiana. Ya se encuentra disponible la lista de docentes seleccionado\/as para participar de la jornada de actualizaci\u00f3n docente, \u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d que se desarrollar\u00e1 entre el 2 y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[198],"class_list":["post-37506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-capacitacion-docente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"\u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d, es el nombre de la jornada que se realizar\u00e1 en la Scuola Italiana. Ya se encuentra disponible la lista de docentes seleccionado\/as para participar de la jornada de actualizaci\u00f3n docente, \u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d que se desarrollar\u00e1 entre el 2 y [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-28T12:00:10+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T16:48:31+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena\",\"datePublished\":\"2018-12-28T12:00:10+00:00\",\"dateModified\":\"2019-05-20T16:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\"},\"wordCount\":203,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg\",\"keywords\":[\"Capacitaci\u00f3n Docente\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\",\"name\":\"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg\",\"datePublished\":\"2018-12-28T12:00:10+00:00\",\"dateModified\":\"2019-05-20T16:48:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg\",\"width\":952,\"height\":581},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/","og_locale":"es_ES","og_type":"article","og_title":"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena - Coquimbo","og_description":"\u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d, es el nombre de la jornada que se realizar\u00e1 en la Scuola Italiana. Ya se encuentra disponible la lista de docentes seleccionado\/as para participar de la jornada de actualizaci\u00f3n docente, \u201c\u00bfC\u00f3mo liderar y ense\u00f1ar a pensar a mis estudiantes?\u201d que se desarrollar\u00e1 entre el 2 y [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/","og_site_name":"Coquimbo","article_published_time":"2018-12-28T12:00:10+00:00","article_modified_time":"2019-05-20T16:48:31+00:00","og_image":[{"width":952,"height":581,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena","datePublished":"2018-12-28T12:00:10+00:00","dateModified":"2019-05-20T16:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/"},"wordCount":203,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg","keywords":["Capacitaci\u00f3n Docente"],"articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/","url":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/","name":"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg","datePublished":"2018-12-28T12:00:10+00:00","dateModified":"2019-05-20T16:48:31+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Afiche-Capacitaci\u00f3n-Docente-e1545998308137.jpg","width":952,"height":581},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/vea-aca-a-los-docentes-seleccionados-para-la-capacitacion-del-2-y-3-de-enero-en-la-serena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"Vea ac\u00e1 a los docentes seleccionados para la Capacitaci\u00f3n del 2 y 3 de enero en La Serena"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/37506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=37506"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/37506\/revisions"}],"predecessor-version":[{"id":38516,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/37506\/revisions\/38516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/37446"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=37506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=37506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=37506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}