{"id":37483,"date":"2018-12-21T14:49:39","date_gmt":"2018-12-21T18:49:39","guid":{"rendered":"https:\/\/dev.explora.cl\/coquimbo\/?p=37483"},"modified":"2019-05-20T16:48:32","modified_gmt":"2019-05-20T16:48:32","slug":"reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/","title":{"rendered":"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo"},"content":{"rendered":"<p style=\"text-align: center\"><strong><em>Un evento \u00fanico que nos tendr\u00e1 como protagonistas privilegiados. Lleg\u00f3 la hora de que la &#8220;Regi\u00f3n Estrella&#8221; se luzca preparando y esperando este fen\u00f3meno astron\u00f3mico, porque miles de turistas, cient\u00edficos y p\u00fablico en general, esperan con ansias este fen\u00f3meno.<\/em><\/strong><\/p>\n<p style=\"text-align: center\"><strong><em>Por: Carlos Martin<\/em><\/strong><\/p>\n<hr \/>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify\">Queda menos de un a\u00f1o para que la Regi\u00f3n de Coquimbo se transforme en el epicentro del turismo astron\u00f3mico mundial. El pr\u00f3ximo 2 de julio del 2019 seremos protagonistas privilegiados de un eclipse solar total, un fen\u00f3meno que no se registraba en la zona hace m\u00e1s de 400 a\u00f1os y en el que se espera la llegada de m\u00e1s de 250 mil turistas que tomar\u00e1n palco para ver como la luna se interpondr\u00e1 entre nosotros y el sol, haciendo que ese d\u00eda amanezca dos veces.<\/p>\n<p style=\"text-align: justify\">Este evento es sumamente relevante desde el punto de vista astron\u00f3mico, pero adem\u00e1s es una buena manera para que la &#8220;Regi\u00f3n Estrella&#8221;, le haga honor a su nombre y se trasforme en un importante polo tur\u00edstico. No por nada la zona tiene uno de los cielos m\u00e1s limpios para dichas observaciones y tanto el sector privado, como el p\u00fablico, trabaja desde hace meses para que todo salga a la perfecci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Durante las horas que dure el eclipse y los minutos que vivamos en la oscuridad total, los ojos del mundo entero estar\u00e1n puestos en la regi\u00f3n, por lo que nada puede fallar, no por nada ha sido denominado como el \u201cevento astron\u00f3mico del siglo\u201d.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37486 alignleft\" src=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/8\/2018\/12\/Eclipse-sol-1024x519.jpg\" alt=\"\" width=\"762\" height=\"386\" srcset=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Eclipse-sol-1024x519.jpg 1024w, https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Eclipse-sol-300x152.jpg 300w, https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Eclipse-sol-768x389.jpg 768w, https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Eclipse-sol.jpg 1151w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/p>\n<p style=\"text-align: justify\"><strong>\u00bfCu\u00e1nto dura y d\u00f3nde se podr\u00e1 ver?<\/strong><\/p>\n<p style=\"text-align: justify\">La oscuridad total comenzar\u00e1 pasada las 16:30 horas cuando la luna cubra la cara del sol, convirtiendo el d\u00eda en noche durante un eclipse solar total que cubrir\u00e1 una franja de 150 kil\u00f3metros de ancho sobre el norte de Chile.<\/p>\n<p style=\"text-align: justify\">Ser\u00e1n solamente 2 minutos y aproximadamente 35 segundos, pero este breve lapso de tiempo ha generado una expectaci\u00f3n mundial entre cient\u00edficos, turistas y residentes de la zona y <strong>EL EXPLORADOR<\/strong> quiso conocer un poco m\u00e1s de este evento.<\/p>\n<p style=\"text-align: justify\">La <strong>Dra. Fernanda Urrutia, Astr\u00f3noma del \u00e1rea de comunicaci\u00f3n y divulgaci\u00f3n del Observatorio Gemin<\/strong>i, explica que &#8220;<em>e<\/em><em>n s\u00ed lo que podremos ver el pr\u00f3ximo a\u00f1o es un eclipse solar, lo importante para nuestra regi\u00f3n es que registraremos un eclipse total de sol, es decir se va a oscurecer el d\u00eda. Para verlo de otro modo tendremos dos amaneceres durante el d\u00eda&#8221;.<\/em><\/p>\n<blockquote><p>Ser\u00e1n solamente 2 minutos y aproximadamente 35 segundos, pero este breve lapso de tiempo ha generado una expectaci\u00f3n mundial entre cient\u00edficos, turistas y residentes de la zona.<\/p><\/blockquote>\n<p style=\"text-align: justify\">Agrega que este tipo de eclipse se produce porque la luna se interpone entre nosotros y el sol, <em>&#8220;esta interposici\u00f3n no es muy frecuente, por ejemplo, la \u00faltima vez que se vio en la ciudad de La Serena propiamente tal fue hace m\u00e1s de 450 a\u00f1os, por eso es tan importante y llama tanto la atenci\u00f3n&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">La Astr\u00f3noma enfatiza que en s\u00ed no va a haber un lugar en que sea vea mejor, ya que ser\u00e1 en todos lados muy parecido en casi toda la Regi\u00f3n de Coquimbo<em>, &#8220;se nos va a oscurecer a todos por igual. Lo que hay que tener en consideraci\u00f3n es que este evento ser\u00e1 en el mes de julio, en invierno, por lo que hay que privilegiar los lugares en donde no haya tanta posibilidad que est\u00e9 nublado y hay que tener mucha consideraci\u00f3n que el sol estar\u00e1 cerca del horizonte&#8221;.<\/em><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify\">As\u00ed Urrutia recomienda ver el eclipse en <em>lugares &#8220;en donde no tengamos cerros cerca de nosotros porque eso puede perjudicar una buena visualizaci\u00f3n del eclipse<\/em>&#8220;, y a\u00f1ade que el sector de la regi\u00f3n en donde el eclipse durar\u00eda m\u00e1s &#8220;<em>ser\u00e1 La Higuera en donde la oscuridad total durar\u00eda aproximadamente 2 minutos 36 segundos&#8221;.<\/em><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify\">Dicha comuna ser\u00e1 el centro, y tanto hac\u00eda el norte, como al sur cada vez ser\u00e1n menos la cantidad de segundos y minutos que dure el eclipse hasta llegar a un punto en que la gente solo ver\u00e1 la parcialidad del sol cubierto por la luna.<\/p>\n<p style=\"text-align: justify\">En tanto <strong>Hern\u00e1n Julio, Director de Astronomy Valley,<\/strong> plataforma de Emarketing que trabaja en la promoci\u00f3n del eclipse total de sol, indic\u00f3 que &#8220;<em>en s\u00ed se puede ver desde cualquier parte de Chile, de Arica a Punta Arenas, lo que no se podr\u00e1 ver en cualquier parte ser\u00e1 la totalidad del eclipse, eso quiere decir que entre la Regi\u00f3n de Coquimbo y el sur de la de Atacama, ser\u00e1 el lugar en donde el d\u00eda se convertir\u00e1 en noche, espec\u00edficamente en la franja de Cachiyuyo por el norte, hasta Guanaqueros por el sur&#8221;.<\/em><\/p>\n<blockquote><p><em>&#8220;En La Higuera La oscuridad total durar\u00eda aproximadamente 2 minutos 36 segundos&#8221;, Dra. Fernanda Urrutia.<\/em><em>\u00a0<\/em><\/p><\/blockquote>\n<p style=\"text-align: justify\">Julio agrega como consejo para las personas que vengan a la regi\u00f3n que &#8220;<em>aunque est\u00e9n en la franja en donde ser\u00e1 total, deben estar en un lugar despejado y sin nubosidad, yo recomiendo que sean lugares lejos de la costa&#8221;.<\/em><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify\">Si bien, el eclipse comienza en la Polinesia Francesa, en medio del Oc\u00e9ano Pac\u00edfico, la sombra o umbra (banda de totalidad) de m\u00e1s 146 kil\u00f3metros de ancho y dejar\u00e1n bajo la oscuridad total a los sectores de Guanaqueros, Totoralillo, Coquimbo, La Serena, Vicu\u00f1a, Pisco Elqui, Samo Alto, La Higuera, Punta de Choros, Cachiyuyo y Domeyko, adem\u00e1s de los observatorios astron\u00f3micos Tololo, La Silla y Las Campanas.<\/p>\n<p style=\"text-align: justify\"><strong>Fuera de la zona de totalidad el eclipse ser\u00e1 visualizado como parcial en Vallenar (99% de oscuridad), Arica (65 %), Santiago (92%), Punta Arenas (46, %).<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Regi\u00f3n preparada e informada<\/strong><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Absolutamente todos est\u00e1n expectantes sobre la masiva llegada de turistas. Es que el eclipse ser\u00e1 a todas luces un evento que cruza la astronom\u00eda con el turismo en la Regi\u00f3n de Coquimbo.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37487 alignright\" src=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/8\/2018\/12\/Eclispe-1024x669.jpg\" alt=\"\" width=\"820\" height=\"536\" \/><\/p>\n<p style=\"text-align: justify\">Ante este panorama, <strong>Antonieta Neira, Gerente de la Corporaci\u00f3n Municipal de Turismo de Coquimbo<\/strong>, indic\u00f3 que con charlas gratuitas est\u00e1n informando, tanto a vecinos como a turistas sobre el evento astron\u00f3mico, indicando que <em>&#8220;<\/em><em>queremos que la gente sepa que la experiencia puede ser un panorama familiar, que se pueda ir con los ni\u00f1os, los adultos mayores y que nadie quede fuera&#8221;<\/em>, a\u00f1ade que &#8220;<em>es un evento astron\u00f3mico, pero muy relevante en el \u00e1mbito tur\u00edstico y por ello hemos realizado capacitaciones en ingl\u00e9s y atenci\u00f3n de p\u00fablico a trav\u00e9s de trabajadores de restaurantes y del rubro tur\u00edstico que lo estamos impartiendo a trav\u00e9s del Instituto de Desarrollo Humano de la municipalidad&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">Dichos cursos son impartidos a artesanos, suplementeros y conductores de taxis colectivos, porque para la <strong>Gerente de la Corporaci\u00f3n Municipal de Turismo<\/strong>, <em>&#8220;todos debemos estar informados y preparados&#8221;<\/em>, pero, adem\u00e1s, Neira pone sobre la mesa un tema relevante indicando que <em>&#8220;somos la \u2018Regi\u00f3n Estrella\u2019, por lo que ser\u00eda muy valioso que se declare feriado ese d\u00eda, pensando en que este fen\u00f3meno ocurrir\u00e1 en un horario en que gran parte de la comunidad estar\u00e1 trabajando o en recintos educacionales. Todos debemos estar alineados y coordinados, porque la Regi\u00f3n de Coquimbo completa saldr\u00e1 al mundo&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">Del mismo modo <strong>Laura Cerda, Presidenta de la C\u00e1mara de Turismo Regi\u00f3n de Coquimbo<\/strong>, indica que tanta es la expectativa por ver este fen\u00f3meno que\u00a0<strong>un 90% de los hostales y un 100% en los principales hoteles ya agotaron sus reservas para la fecha del eclipse.<\/strong><\/p>\n<p style=\"text-align: justify\">Cerda indic\u00f3 tambi\u00e9n que considera que este evento es una plataforma y una gran oportunidad que tenemos como regi\u00f3n y como territorio para promocionarnos y difundirnos a nivel mundial<em>, &#8220;por eso es que desde hace un tiempo nos estamos preocupando de que todo est\u00e9 coordinado y armonizado, porque estaremos en la vitrina y en los ojos de todo el mundo&#8221;,<\/em> a\u00f1adiendo que <em>&#8220;si bien es un evento corto en su duraci\u00f3n, pero eso no quiere decir que la gente va a llegar el mismo d\u00eda, por el contrario, lo har\u00e1n desde antes y se quedar\u00e1 m\u00e1s d\u00edas&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">Por tal motivo desde la C\u00e1mara de Turismo regional recalcaron que est\u00e1n abordando el eclipse total de sol <em>&#8220;a nivel macro con privados y lo mismo a nivel del sector p\u00fablico, pero no solo se incorpora el Gobierno, sino que organizaciones relacionadas con este fen\u00f3meno astron\u00f3mico, como son las municipalidades, las universidades y los colegios. Todos deben tener la informaci\u00f3n necesaria. Queremos sensibilizar a toda la comunidad de la regi\u00f3n, para que conozcan que esta es una gran oportunidad para todos&#8221;<\/em>.<strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a1No te olvides de tus lentes!<\/strong><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Los mejores compa\u00f1eros que tendr\u00e1s ese d\u00eda ser\u00e1n unos lentes especiales que te proteger\u00e1n de la radiaci\u00f3n solar, y que est\u00e1n hechos de un pol\u00edmero que filtra los rayos ultravioletas e infrarrojos y con ellos podr\u00e1s ver el eclipse en todas sus fases.<\/p>\n<p style=\"text-align: justify\">Dichos lentes deben estar certificados con la norma ISO 12312-2:2015, especialmente los recomendados por la Administraci\u00f3n Nacional de la Aeron\u00e1utica y del Espacio (NASA) y la Sociedad Astron\u00f3mica Estadounidense (AAS).<\/p>\n<p style=\"text-align: justify\"><strong>Hern\u00e1n Julio, Director de Astronomy Valley<\/strong>, se\u00f1al\u00f3 que <em>&#8220;los lentes ser\u00e1n fundamentales, porque observar un eclipse total de sol es lo mismo que mirar directamente al sol y puedes quemarte los ojos&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">A trav\u00e9s de www.astronomyvalley.cl, podr\u00e1s adquirir los lentes. Hern\u00e1n Julio indic\u00f3 que <em>&#8220;nuestro proveedor es el l\u00edder mundial y el m\u00e1s grande en la producci\u00f3n de estos lentes que es American Paper Optic. Le recomendamos a la gente que compre solo los lentes certificados y no imitaciones&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/issuu.com\/exploradormagazine\/docs\/el_explorador_n8\"><strong>*Reportaje aparecido en la Edici\u00f3n de Septiembre de la Revista El Explorador <\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un evento \u00fanico que nos tendr\u00e1 como protagonistas privilegiados. Lleg\u00f3 la hora de que la &#8220;Regi\u00f3n Estrella&#8221; se luzca preparando y esperando este fen\u00f3meno astron\u00f3mico, porque miles de turistas, cient\u00edficos y p\u00fablico en general, esperan con ansias este fen\u00f3meno. Por: Carlos Martin \u00a0 Queda menos de un a\u00f1o para que la Regi\u00f3n de Coquimbo se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37484,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[168,331],"class_list":["post-37483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-astronomia","tag-eclipse-de-sol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo - Coquimbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo - Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Un evento \u00fanico que nos tendr\u00e1 como protagonistas privilegiados. Lleg\u00f3 la hora de que la &#8220;Regi\u00f3n Estrella&#8221; se luzca preparando y esperando este fen\u00f3meno astron\u00f3mico, porque miles de turistas, cient\u00edficos y p\u00fablico en general, esperan con ansias este fen\u00f3meno. Por: Carlos Martin \u00a0 Queda menos de un a\u00f1o para que la Regi\u00f3n de Coquimbo se [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Coquimbo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-21T18:49:39+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T16:48:32+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1166\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo\",\"datePublished\":\"2018-12-21T18:49:39+00:00\",\"dateModified\":\"2019-05-20T16:48:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\"},\"wordCount\":1669,\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg\",\"keywords\":[\"astronom\u00eda\",\"Eclipse de Sol\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\",\"name\":\"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo - Coquimbo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg\",\"datePublished\":\"2018-12-21T18:49:39+00:00\",\"dateModified\":\"2019-05-20T16:48:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg\",\"width\":1166,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/coquimbo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#website\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"name\":\"Coquimbo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"publisher\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#organization\",\"name\":\"Coquimbo\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg\",\"width\":615,\"height\":576,\"caption\":\"Coquimbo\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo - Coquimbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/","og_locale":"es_ES","og_type":"article","og_title":"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo - Coquimbo","og_description":"Un evento \u00fanico que nos tendr\u00e1 como protagonistas privilegiados. Lleg\u00f3 la hora de que la &#8220;Regi\u00f3n Estrella&#8221; se luzca preparando y esperando este fen\u00f3meno astron\u00f3mico, porque miles de turistas, cient\u00edficos y p\u00fablico en general, esperan con ansias este fen\u00f3meno. Por: Carlos Martin \u00a0 Queda menos de un a\u00f1o para que la Regi\u00f3n de Coquimbo se [&hellip;]","og_url":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/","og_site_name":"Coquimbo","article_published_time":"2018-12-21T18:49:39+00:00","article_modified_time":"2019-05-20T16:48:32+00:00","og_image":[{"width":1166,"height":730,"url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo","datePublished":"2018-12-21T18:49:39+00:00","dateModified":"2019-05-20T16:48:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/"},"wordCount":1669,"publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg","keywords":["astronom\u00eda","Eclipse de Sol"],"articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/","url":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/","name":"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo - Coquimbo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg","datePublished":"2018-12-21T18:49:39+00:00","dateModified":"2019-05-20T16:48:32+00:00","breadcrumb":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#primaryimage","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2018\/12\/Sin-t\u00edtulo-1.jpg","width":1166,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/coquimbo\/reportaje-eclipse-total-de-sol-del-2019-la-region-de-coquimbo-estara-en-los-ojos-del-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/coquimbo\/"},{"@type":"ListItem","position":2,"name":"Reportaje: Eclipse total de sol del 2019, La Regi\u00f3n de Coquimbo estar\u00e1 en los ojos del mundo"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/coquimbo\/#website","url":"https:\/\/dev.explora.cl\/coquimbo\/","name":"Coquimbo","description":"Otro sitio m\u00e1s de dev.explora.cl","publisher":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/coquimbo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/dev.explora.cl\/coquimbo\/#organization","name":"Coquimbo","url":"https:\/\/dev.explora.cl\/coquimbo\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/","url":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","contentUrl":"https:\/\/dev.explora.cl\/coquimbo\/wp-content\/uploads\/sites\/6\/2020\/08\/cropped-Mesa-de-trabajo-1-100.jpg","width":615,"height":576,"caption":"Coquimbo"},"image":{"@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/coquimbo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/coquimbo\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/37483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/comments?post=37483"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/37483\/revisions"}],"predecessor-version":[{"id":38519,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/posts\/37483\/revisions\/38519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media\/37484"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/media?parent=37483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/categories?post=37483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/coquimbo\/wp-json\/wp\/v2\/tags?post=37483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}