{"id":875,"date":"2015-10-02T00:00:00","date_gmt":"2015-10-02T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/biobio\/blog\/2015\/10\/02\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/"},"modified":"2019-05-20T18:32:06","modified_gmt":"2019-05-20T18:32:06","slug":"los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/","title":{"rendered":"Los integrantes de la Red Territorial se preparan para la SNCyT"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15287\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/9791803fdb3ffe7e1a726d24da66e9a9.jpg\" alt=\"\" width=\"750\" height=\"500\" \/><\/p>\n<p><p id=\"yui_3_17_2_1_1443794225940_18368\" style=\"margin: 0px 0px 22px;color: #3e3e3e;font-family: 'Gotham SSm A', 'Gotham SSm B', 'Gotham SSm', Gotham, 'Proxima Nova', 'Open Sans', 'Helvetica Neue', Helvetica, Arial, sans-serif;font-size: 12px;line-height: 22px\">Cuarenta y dos Coordinadores Comunales asistieron a la Red Territorial organizada por PAR EXPLORA Biob\u00edo en las dependencias del Centro Interactivo de Ciencias, Artes y Tecnolog\u00edas, CICAT. La instancia permiti\u00f3&nbsp;afianzar las actividades que &nbsp;se realizar\u00e1n en la XXI Semana Nacional de Ciencia y Tecnolog\u00eda.&nbsp;<\/p>\n<p style=\"margin: 22px 0px;color: #3e3e3e;font-family: 'Gotham SSm A', 'Gotham SSm B', 'Gotham SSm', Gotham, 'Proxima Nova', 'Open Sans', 'Helvetica Neue', Helvetica, Arial, sans-serif;font-size: 12px;line-height: 22px\">La jornada comenz\u00f3 con una charla titulada &#8220;Educaci\u00f3n en medios audiovisuales&#8221;, dictada por Constanza Guti\u00e9rrez, integrante del Consejo Nacional de Televisi\u00f3n Novasur. En esta oportunidad, se mostraron capsulas de diversos contenidos con el prop\u00f3sito de ser utilizados en las salas de clases.&nbsp;<\/p>\n<p id=\"yui_3_17_2_1_1443794225940_18903\" style=\"margin: 22px 0px;color: #3e3e3e;font-family: 'Gotham SSm A', 'Gotham SSm B', 'Gotham SSm', Gotham, 'Proxima Nova', 'Open Sans', 'Helvetica Neue', Helvetica, Arial, sans-serif;font-size: 12px;line-height: 22px\">Rocio Cruces, Coordinadora Ejecutiva del PAR EXPLORA Biob\u00edo,&nbsp;&nbsp;dio a conocer las actividades que se realizaron durante el mes de septiembre, entre ellas, los Congresos Provinciales y el Congreso de Astronom\u00eda.&nbsp;M\u00e1s tarde, se analizaron&nbsp;las actividades que se ejecutar\u00e1n&nbsp;durante los pr\u00f3ximas d\u00edas en el marco de la XXI Semana Nacional de Ciencia y Tecnolog\u00eda.&nbsp;<\/p>\n<p id=\"yui_3_17_2_1_1443794225940_20482\" style=\"margin: 22px 0px;color: #3e3e3e;font-family: 'Gotham SSm A', 'Gotham SSm B', 'Gotham SSm', Gotham, 'Proxima Nova', 'Open Sans', 'Helvetica Neue', Helvetica, Arial, sans-serif;font-size: 12px;line-height: 22px\">Adem\u00e1s, se dieron a conocer&nbsp;los plazos de &#8220;Video Asombra&#8221; y &#8220;Biob\u00edo, la energ\u00eda de Chile&#8221; con el fin de que los Coordinadores Explora Biob\u00edo comenten la informaci\u00f3n a sus pares. Tambi\u00e9n, se comunic\u00f3 acerca de la log\u00edstica en las actividades &#8220;Maestros de la Luz&#8221; y &#8220;1000 Cient\u00edficos, 1000 Aulas&#8221;.<\/p>\n<p id=\"yui_3_17_2_1_1443794225940_23462\" style=\"margin: 22px 0px 0px;color: #3e3e3e;font-family: 'Gotham SSm A', 'Gotham SSm B', 'Gotham SSm', Gotham, 'Proxima Nova', 'Open Sans', 'Helvetica Neue', Helvetica, Arial, sans-serif;font-size: 12px;line-height: 22px\">Para finalizar, a cada asistente se le entreg\u00f3 un kit de material para celebrar la ciencia durante octubre, en el cual se incluy\u00f3 revistas cient\u00edficas, libretas, afiches, entre otros recursos.&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuarenta y dos Coordinadores Comunales asistieron a la Red Territorial organizada por PAR EXPLORA Biob\u00edo en las dependencias del Centro Interactivo de Ciencias, Artes y Tecnolog\u00edas, CICAT. La instancia permiti\u00f3&nbsp;afianzar las actividades que &nbsp;se realizar\u00e1n en la XXI Semana Nacional de Ciencia y Tecnolog\u00eda.&nbsp; La jornada comenz\u00f3 con una charla titulada &#8220;Educaci\u00f3n en medios audiovisuales&#8221;, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[163,157,114],"class_list":["post-875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cicat","tag-explora-biobio","tag-sncyt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los integrantes de la Red Territorial se preparan para la SNCyT - Biob\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Los integrantes de la Red Territorial se preparan para la SNCyT - Biob\u00edo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Cuarenta y dos Coordinadores Comunales asistieron a la Red Territorial organizada por PAR EXPLORA Biob\u00edo en las dependencias del Centro Interactivo de Ciencias, Artes y Tecnolog\u00edas, CICAT. La instancia permiti\u00f3&nbsp;afianzar las actividades que &nbsp;se realizar\u00e1n en la XXI Semana Nacional de Ciencia y Tecnolog\u00eda.&nbsp; La jornada comenz\u00f3 con una charla titulada &#8220;Educaci\u00f3n en medios audiovisuales&#8221;, [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Biob\u00edo\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-02T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:32:06+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Los integrantes de la Red Territorial se preparan para la SNCyT\",\"datePublished\":\"2015-10-02T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\"},\"wordCount\":268,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg\",\"keywords\":[\"CiCAT\",\"EXPLORA Biob\u00edo\",\"sncyt\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\",\"url\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\",\"name\":\"Los integrantes de la Red Territorial se preparan para la SNCyT - Biob\u00edo\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg\",\"datePublished\":\"2015-10-02T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:32:06+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/biobio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los integrantes de la Red Territorial se preparan para la SNCyT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/#website\",\"url\":\"https:\/\/dev.explora.cl\/biobio\/\",\"name\":\"Biob\u00edo\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/biobio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/biobio\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los integrantes de la Red Territorial se preparan para la SNCyT - Biob\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/","og_locale":"es_ES","og_type":"article","og_title":"Los integrantes de la Red Territorial se preparan para la SNCyT - Biob\u00edo","og_description":"Cuarenta y dos Coordinadores Comunales asistieron a la Red Territorial organizada por PAR EXPLORA Biob\u00edo en las dependencias del Centro Interactivo de Ciencias, Artes y Tecnolog\u00edas, CICAT. La instancia permiti\u00f3&nbsp;afianzar las actividades que &nbsp;se realizar\u00e1n en la XXI Semana Nacional de Ciencia y Tecnolog\u00eda.&nbsp; La jornada comenz\u00f3 con una charla titulada &#8220;Educaci\u00f3n en medios audiovisuales&#8221;, [&hellip;]","og_url":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/","og_site_name":"Biob\u00edo","article_published_time":"2015-10-02T04:00:00+00:00","article_modified_time":"2019-05-20T18:32:06+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Los integrantes de la Red Territorial se preparan para la SNCyT","datePublished":"2015-10-02T04:00:00+00:00","dateModified":"2019-05-20T18:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/"},"wordCount":268,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg","keywords":["CiCAT","EXPLORA Biob\u00edo","sncyt"],"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/","url":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/","name":"Los integrantes de la Red Territorial se preparan para la SNCyT - Biob\u00edo","isPartOf":{"@id":"https:\/\/dev.explora.cl\/biobio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg","datePublished":"2015-10-02T04:00:00+00:00","dateModified":"2019-05-20T18:32:06+00:00","author":{"@id":"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#primaryimage","url":"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg","contentUrl":"https:\/\/dev.explora.cl\/biobio\/wp-content\/uploads\/sites\/14\/2018\/06\/9791803fdb3ffe7e1a726d24da66e9a9.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/biobio\/los-integrantes-de-la-red-territorial-se-preparan-para-la-sncyt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/biobio\/"},{"@type":"ListItem","position":2,"name":"Los integrantes de la Red Territorial se preparan para la SNCyT"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/biobio\/#website","url":"https:\/\/dev.explora.cl\/biobio\/","name":"Biob\u00edo","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/biobio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/biobio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/biobio\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/posts\/875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/comments?post=875"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/posts\/875\/revisions"}],"predecessor-version":[{"id":37831,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/posts\/875\/revisions\/37831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/media\/876"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/media?parent=875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/categories?post=875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/biobio\/wp-json\/wp\/v2\/tags?post=875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}