{"id":886,"date":"2015-05-19T00:00:00","date_gmt":"2015-05-19T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/05\/19\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/"},"modified":"2019-05-20T18:56:02","modified_gmt":"2019-05-20T18:56:02","slug":"par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/","title":{"rendered":"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-11157\" src=\"http:\/\/ec2-34-218-253-251.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/05\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg\" alt=\"\" width=\"3008\" height=\"2000\" \/><\/p>\n<p style=\"text-align: center\"><em>El evento est\u00e1 dirigido a estudiantes de quinto b\u00e1sico a tercero medio que sean curiosos, les guste experimentar para conocer distintos fen\u00f3menos y quieran vivir una experiencia cient\u00edfica inolvidable.<\/em><\/p>\n<p>Con el objetivo de incentivar el desarrollo de investigaciones cient\u00edficas por parte de estudiantes de la regi\u00f3n, el PAR EXPLORA Araucan\u00eda, coordinado por la Universidad de La Frontera, abri\u00f3 la convocatoria para participar en el XIII Congreso Regional Escolar de Ciencia y Tecnolog\u00eda, cuyo plazo de postulaci\u00f3n finaliza el 11 de septiembre.<\/p>\n<p>Este evento, uno de los m\u00e1s emblem\u00e1ticos del PAR EXPLORA Araucan\u00eda, est\u00e1 dirigido a estudiantes de quinto a\u00f1o b\u00e1sico a tercer a\u00f1o medio que sean curiosos y curiosas, les guste experimentar para conocer distintos fen\u00f3menos y, sobre todo, quieran vivir una experiencia cient\u00edfica y tecnol\u00f3gica inolvidable.<\/p>\n<p>Para participar, estudiantes deben elaborar investigaciones cient\u00edficas y\/o tecnol\u00f3gicas con la gu\u00eda de un profesor o profesora. Tras un proceso de selecci\u00f3n, estos trabajos se presentar\u00e1n en el Congreso Regional, que se desarrollar\u00e1 los d\u00edas 22 y 23 de octubre en el Gimnasio Ol\u00edmpico.<\/p>\n<p>De este modo, durante dos d\u00edas los estudiantes exhibir\u00e1n sus investigaciones a la comunidad regional y a un jurado compuesto por destacados cient\u00edficos y cient\u00edficas, quienes evaluar\u00e1n los proyectos escritos, los stands y las presentaciones orales de cada una de las propuestas.<\/p>\n<p>Los tres mejores trabajos de educaci\u00f3n b\u00e1sica y de educaci\u00f3n media ser\u00e1n premiados y, adem\u00e1s, los primeros lugares representar\u00e1n a la regi\u00f3n de La Araucan\u00eda en el XVI Congreso Nacional Escolar de Ciencia y Tecnolog\u00eda, que se celebrar\u00e1 en Valpara\u00edso.<\/p>\n<p><strong>\u00bfC\u00f3mo postular?<\/strong><\/p>\n<p>A diferencia de a\u00f1os anteriores, este 2015 ser\u00e1n tres las categor\u00edas en las que podr\u00e1n participar los equipos de escolares: Investigaciones Ciencias Naturales, Desarrollo en Ingenier\u00eda y Tecnolog\u00eda, e Investigaciones Ciencias Sociales.<\/p>\n<p>Para postular, debes completar el formulario de postulaci\u00f3n correspondiente a la categor\u00eda de participaci\u00f3n (que aparecen al final) y enviar el documento a exploraaraucania@gmail.com o explora@ufrontera.cl. El plazo de recepci\u00f3n finaliza el d\u00eda 11 de septiembre, a las 13:00 horas.<\/p>\n<p>Para mayor informaci\u00f3n, descarga las bases que aparecen al final. En caso de consultas, comun\u00edcate al tel\u00e9fono 2325428 o al correo electr\u00f3nico exploraaraucania@gmail.com.<\/p>\n<p>\u00a1Haz la investigaci\u00f3n que siempre quisiste y participa en esta aventura cient\u00edfica inolvidable!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento est\u00e1 dirigido a estudiantes de quinto b\u00e1sico a tercero medio que sean curiosos, les guste experimentar para conocer distintos fen\u00f3menos y quieran vivir una experiencia cient\u00edfica inolvidable. Con el objetivo de incentivar el desarrollo de investigaciones cient\u00edficas por parte de estudiantes de la regi\u00f3n, el PAR EXPLORA Araucan\u00eda, coordinado por la Universidad de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El evento est\u00e1 dirigido a estudiantes de quinto b\u00e1sico a tercero medio que sean curiosos, les guste experimentar para conocer distintos fen\u00f3menos y quieran vivir una experiencia cient\u00edfica inolvidable. Con el objetivo de incentivar el desarrollo de investigaciones cient\u00edficas por parte de estudiantes de la regi\u00f3n, el PAR EXPLORA Araucan\u00eda, coordinado por la Universidad de [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-19T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:56:02+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8-1024x681.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar\",\"datePublished\":\"2015-05-19T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:56:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\"},\"wordCount\":434,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\",\"name\":\"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg\",\"datePublished\":\"2015-05-19T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:56:02+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg\",\"width\":3008,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/","og_locale":"es_ES","og_type":"article","og_title":"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar - Araucan\u00eda","og_description":"El evento est\u00e1 dirigido a estudiantes de quinto b\u00e1sico a tercero medio que sean curiosos, les guste experimentar para conocer distintos fen\u00f3menos y quieran vivir una experiencia cient\u00edfica inolvidable. Con el objetivo de incentivar el desarrollo de investigaciones cient\u00edficas por parte de estudiantes de la regi\u00f3n, el PAR EXPLORA Araucan\u00eda, coordinado por la Universidad de [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-05-19T04:00:00+00:00","article_modified_time":"2019-05-20T18:56:02+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8-1024x681.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar","datePublished":"2015-05-19T04:00:00+00:00","dateModified":"2019-05-20T18:56:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/"},"wordCount":434,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/","url":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/","name":"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg","datePublished":"2015-05-19T04:00:00+00:00","dateModified":"2019-05-20T18:56:02+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#primaryimage","url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg","contentUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/fa04d2f3ddb8a2c011f3a38486dc81c8.jpg","width":3008,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/par-explora-araucania-abre-convocatoria-para-participar-en-el-xiii-congreso-regional-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"PAR EXPLORA Araucan\u00eda abre convocatoria para participar en el XIII Congreso Regional Escolar"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/886\/revisions"}],"predecessor-version":[{"id":38295,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/886\/revisions\/38295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media\/887"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}