{"id":844,"date":"2015-05-07T00:00:00","date_gmt":"2015-05-07T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/05\/07\/prueba-3\/"},"modified":"2019-05-20T18:56:12","modified_gmt":"2019-05-20T18:56:12","slug":"prueba-3","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/","title":{"rendered":"prueba"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-844","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>prueba - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"prueba - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-07T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:56:12+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"prueba\",\"datePublished\":\"2015-05-07T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:56:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\"},\"wordCount\":1,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\",\"name\":\"prueba - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"datePublished\":\"2015-05-07T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:56:12+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"prueba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"prueba - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/","og_locale":"es_ES","og_type":"article","og_title":"prueba - Araucan\u00eda","og_url":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-05-07T04:00:00+00:00","article_modified_time":"2019-05-20T18:56:12+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"prueba","datePublished":"2015-05-07T04:00:00+00:00","dateModified":"2019-05-20T18:56:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/"},"wordCount":1,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/prueba-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/","url":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/","name":"prueba - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"datePublished":"2015-05-07T04:00:00+00:00","dateModified":"2019-05-20T18:56:12+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/prueba-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/prueba-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"prueba"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=844"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/844\/revisions"}],"predecessor-version":[{"id":38306,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/844\/revisions\/38306"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}