{"id":1306,"date":"2015-11-10T00:00:00","date_gmt":"2015-11-10T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/11\/10\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/"},"modified":"2019-05-20T18:54:25","modified_gmt":"2019-05-20T18:54:25","slug":"explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/","title":{"rendered":"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><i><span style=\"font-size: 12pt;line-height: 107%;font-family: 'Trebuchet MS', sans-serif\">Crea cultura cient\u00edfica convirtiendo tu idea en un Proyecto Explora<\/span><\/i><i><\/i><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 107%;font-family: 'Trebuchet MS', sans-serif\">Las mejores propuestas que, usando nuevas metodolog\u00edas educativas y productos atractivos, permitan comunicar la ciencia a la comunidad, podr\u00e1n recibir hasta $30.000.000 de financiamiento, gracias al XX Concurso Nacional de Proyectos Explora de Valoraci\u00f3n y Divulgaci\u00f3n de la Ciencia y la Tecnolog\u00eda 2015-2016<strong>. <\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Desde el 22 de octubre y hasta el pr\u00f3ximo 2 de diciembre estar\u00e1n abiertas las postulaciones para esta iniciativa, que invita a participar a personas naturales o jur\u00eddicas, tanto p\u00fablicas como privadas<strong>, <\/strong>cuya labor est\u00e9 vinculada a la promoci\u00f3n y el desarrollo de la ciencia, la tecnolog\u00eda, la educaci\u00f3n, la cultura, las artes o las comunicaciones.<strong><\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">El concurso busca apoyar proyectos que contribuyan a crear una cultura cient\u00edfica y tecnol\u00f3gica en la comunidad escolar y p\u00fablico en general, para lo cual el Programa Explora CONICYT financiar\u00e1 hasta el 70% del costo total de la propuesta, en tanto que el 30% restante debe ser aportado por el postulante, instituciones asociadas o terceras. <\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Los proyectos deben contemplar un plazo m\u00e1ximo de ejecuci\u00f3n de 12 meses y<strong> <\/strong>entre las principales novedades se encuentra la ampliaci\u00f3n del llamado a personas naturales, la incorporaci\u00f3n de un asesor pedag\u00f3gico en el Eje Valoraci\u00f3n, coberturas diferenciadas por niveles en la L\u00ednea Estudiantes; reposici\u00f3n del tope de 50% para el \u00edtem honorarios y 10% para equipamiento, adem\u00e1s del aumento de la cobertura m\u00ednima para el Eje Divulgaci\u00f3n.<strong><\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Las postulaciones se reciben s\u00f3lo en l\u00ednea a trav\u00e9s de: <a href=\"http:\/\/spl.conicyt.cl\/\"><span style=\"color: windowtext;border: 1pt none windowtext;padding: 0cm\">http:\/\/spl.conicyt.cl\/<\/span><\/a><span><span style=\"color: windowtext;border: 1pt none windowtext;padding: 0cm\">, a partir del 22 de octubre.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Fechas y plazos<\/span><\/strong><\/p>\n<p style=\"text-align: justify;text-indent: -18pt\">$1<span style=\"font-size: 12pt;font-family: Symbol\">\u00b7<span style=\"font-size: 7pt;font-family: 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Presentaci\u00f3n de postulaciones: Hasta el 02 de Diciembre a las 17:01 horas.<\/span><\/p>\n<p style=\"text-align: justify;text-indent: -18pt\">$1<span style=\"font-size: 12pt;font-family: Symbol\">\u00b7<span style=\"font-size: 7pt;font-family: 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Consultas: Hasta el 24 de noviembre, s\u00f3lo por escrito a trav\u00e9s de <\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">la Oficina de Informaciones, Reclamos y Sugerencias (OIRS) de CONICYT (<\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\"><a href=\"http:\/\/www.conicyt.cl\/oirs\"><span style=\"color: windowtext\">http:\/\/www.conicyt.cl\/oirs<\/span><\/a><\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">).<\/span><\/p>\n<p style=\"text-align: justify;text-indent: -18pt\">$1<span style=\"font-size: 12pt;font-family: Symbol\">\u00b7<span style=\"font-size: 7pt;font-family: 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">La entrega de resultados, referencialmente, se realizar\u00eda durante el primer trimestre del 2016. <\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><strong><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm\">Pr\u00f3ximos talleres y videoconferencias<\/span><\/strong><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt 36pt;text-indent: -18pt;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\">$1<span style=\"font-family: Symbol\">\u00b7<span style=\"line-height: normal;font-family: 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">-Mi\u00e9rcoles 11 de noviembre, 15:00 horas, Sal\u00f3n Manso de Velasco, Municipalidad de&nbsp;<strong><span style=\"border: 1pt none windowtext;padding: 0cm\">Talca<\/span><\/strong>&nbsp;(1 Norte #797): Taller informativo.<\/span><\/span><\/p>\n<p style=\"margin: 11.25pt 0cm 11.25pt 36pt;text-indent: -18pt;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\">$1<span style=\"font-family: Symbol\">\u00b7<span style=\"line-height: normal;font-family: 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">-Lunes 16 de noviembre, 10:00 horas: Videoconferencia REUNA.<\/span><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt 36pt;text-indent: -18pt;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\">$1<span style=\"font-family: Symbol\">\u00b7<span style=\"line-height: normal;font-family: 'Times New Roman'\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">-Jueves 19 de noviembre, 10:00 horas, Biblioteca Regional&nbsp;<strong><span style=\"border: 1pt none windowtext;padding: 0cm\">Puerto Montt&nbsp;<\/span><\/strong>(Quillota 113, 2\u00b0 piso): Taller informativo.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif\">Encuentra las bases del concurso y toda la informaci\u00f3n en <\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\"><a href=\"https:\/\/dev.explora.cl\/\"><span style=\"color: windowtext\">dev.explora.cl<\/span><\/a><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Crea cultura cient\u00edfica convirtiendo tu idea en un Proyecto Explora Las mejores propuestas que, usando nuevas metodolog\u00edas educativas y productos atractivos, permitan comunicar la ciencia a la comunidad, podr\u00e1n recibir hasta $30.000.000 de financiamiento, gracias al XX Concurso Nacional de Proyectos Explora de Valoraci\u00f3n y Divulgaci\u00f3n de la Ciencia y la Tecnolog\u00eda 2015-2016. Desde [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1306","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Crea cultura cient\u00edfica convirtiendo tu idea en un Proyecto Explora Las mejores propuestas que, usando nuevas metodolog\u00edas educativas y productos atractivos, permitan comunicar la ciencia a la comunidad, podr\u00e1n recibir hasta $30.000.000 de financiamiento, gracias al XX Concurso Nacional de Proyectos Explora de Valoraci\u00f3n y Divulgaci\u00f3n de la Ciencia y la Tecnolog\u00eda 2015-2016. Desde [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-10T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:25+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos\",\"datePublished\":\"2015-11-10T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\"},\"wordCount\":445,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\",\"name\":\"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"datePublished\":\"2015-11-10T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:25+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/","og_locale":"es_ES","og_type":"article","og_title":"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos - Araucan\u00eda","og_description":"&nbsp; Crea cultura cient\u00edfica convirtiendo tu idea en un Proyecto Explora Las mejores propuestas que, usando nuevas metodolog\u00edas educativas y productos atractivos, permitan comunicar la ciencia a la comunidad, podr\u00e1n recibir hasta $30.000.000 de financiamiento, gracias al XX Concurso Nacional de Proyectos Explora de Valoraci\u00f3n y Divulgaci\u00f3n de la Ciencia y la Tecnolog\u00eda 2015-2016. Desde [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-11-10T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:25+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos","datePublished":"2015-11-10T04:00:00+00:00","dateModified":"2019-05-20T18:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/"},"wordCount":445,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/","url":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/","name":"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"datePublished":"2015-11-10T04:00:00+00:00","dateModified":"2019-05-20T18:54:25+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/explora-conicyt-financia-hasta-30-millones-en-concurso-nacional-de-proyectos-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"Explora CONICYT financia hasta 30 millones en Concurso Nacional de Proyectos"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1306"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1306\/revisions"}],"predecessor-version":[{"id":38176,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1306\/revisions\/38176"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}