{"id":1299,"date":"2015-11-04T00:00:00","date_gmt":"2015-11-04T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/11\/04\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/"},"modified":"2019-05-20T18:54:29","modified_gmt":"2019-05-20T18:54:29","slug":"mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/","title":{"rendered":"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d"},"content":{"rendered":"<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><i><span style=\"font-family: 'Trebuchet MS', sans-serif\">M\u00e1s de 1000 estudiantes de distintas comunas de la Araucan\u00eda recorrieron los &nbsp;laboratorios de la Universidad de La Frontera, la Universidad Cat\u00f3lica de Temuco, y Aguas Araucan\u00eda.<\/span><\/i><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;line-height: 115%\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;line-height: 115%\">\u201cLo que m\u00e1s me llamo la atenci\u00f3n fue la pasi\u00f3n con que cada uno de los exponentes nos explico las cosas\u201d. &nbsp;Con estas palabras Ayleen Pe\u00f1ailillo, estudiante de tercero medio del Colegio Santa Cruz de Temuco, nos comenta sobre su primera visita a esta interesante actividad, la cual precisamente busca generar una experiencia enriquecedora entre el acad\u00e9mico y el estudiante, que los j\u00f3venes se incentiven con el mundo de la investigaci\u00f3n y descubran toda la dedicaci\u00f3n y entrega que hay detr\u00e1s de cada laboratorio.<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;line-height: 115%\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">En el marco de la XXI Semana Nacional de la Ciencia y Tecnolog\u00eda <\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">del Programa EXPLORA CONICYT,<span style=\"border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\"> estudiantes de distintos puntos de nuestra regi\u00f3n, se trasladaron hasta Temuco para participar de la actividad, \u201cCasa Abierta\u201d. <\/span><\/span><\/span><\/p>\n<p style=\"margin: 11.25pt 0cm;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">El evento organizado por el PAR Explora Araucan\u00eda y ejecutado por la Universidad de La Frontera, busca que la <\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">comunidad regional vuelque su mirada a la ciencia a trav\u00e9s de iniciativas que evidencian que el quehacer cient\u00edfico no s\u00f3lo es entretenido y desafiante, sino que tambi\u00e9n contribuye a mejorar nuestra sociedad.<\/span><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;background-image: initial;background-position: initial\">Durante todo el d\u00eda, &nbsp;la Universidad Cat\u00f3lica de Temuco, Aguas Araucan\u00eda y la Universidad de La Frontera, les brindaron la oportunidad a cientos de estudiantes de descubrir c\u00f3mo se desarrolla el trabajo cient\u00edfico en la Araucan\u00eda. Continuando as\u00ed con el sinf\u00edn de actividades que se han llevado a cabo en esta, &nbsp;la fiesta de la ciencia. <\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">\u201cPara nosotros como establecimiento educacional, esta es una gran oportunidad, ya que les&nbsp; permite a los j\u00f3venes conocer el \u00e1mbito universitario, sus instalaciones, y ver el trabajo que existe en los laboratorios, que ellos conozcan todo este \u00e1mbito es muy importante\u201d. Afirm\u00f3, &nbsp;Orlando Torres, profesor del Liceo Juan Bosco de Cunco.<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">Por su parte, Marjorie Reyes, acad\u00e9mica del Instituto de Agroindustria, manifest\u00f3 su alegr\u00eda al ser parte de esta actividad. \u201cEsto es una gran oportunidad para nosotros &nbsp;ya que nos permite mostrar &nbsp;todo lo que realizamos en investigaci\u00f3n a los escolares que vienen a vernos, significando para ellos una primera aproximaci\u00f3n a la universidad y para nosotros una muestra del trabajo a la comunidad\u201d. <\/span><\/span><\/p>\n<p style=\"margin: 11.25pt 0cm;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">Lamentablemente el mundo cient\u00edfico muchas veces constituye un \u00e1rea desconocida para los ni\u00f1os, ni\u00f1as y j\u00f3venes, precisamente este tipo de convocatorias busca que ellos conozcan, interact\u00faen y se sorprendan con esta transcendental labor. &nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">Es as\u00ed como con esta &#8220;Casa Abierta&#8221;, son m\u00e1s de 1000 los estudiantes beneficiados, recordando que &nbsp;INIA Carillanca tambi\u00e9n abri\u00f3 sus puertas durante este mes, recibiendo <span class=\"apple-converted-space\"><span style=\"border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">a un centenar de escolares.<i> <\/i><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\"><span class=\"apple-converted-space\"><span style=\"border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">&nbsp;<img decoding=\"async\" src=\"images\/Documentos\/Casa Abierta 2015 0.jpg\" alt=\"\" style=\"margin-left: auto;margin-right: auto\" \/><\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><strong><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">&nbsp;<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><strong><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">Im<br \/>\npresiones<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\"><img decoding=\"async\" src=\"images\/Documentos\/Casa Abierta 2015 11.jpg\" alt=\"\" align=\"left\" \/>\u201cAprend\u00ed mucho de varias cosas, pero lo que m\u00e1s me llamo la atenci\u00f3n fue el tema de las algas marinas, tambi\u00e9n las mol\u00e9culas que pudimos ver con mis compa\u00f1eros en un microscopio, no me imaginaba que la universidad tuviera tantas cosas y tan entretenidas\u201d.<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">Jeison Torres, estudiante quinto b\u00e1sico, Escuela Coraz\u00f3n de Jes\u00fas, Lautaro<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">&nbsp;<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;line-height: 115%\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;line-height: 115%\"><img decoding=\"async\" src=\"images\/Documentos\/Casa Abierta 2015 03.jpg\" alt=\"\" align=\"left\" \/>&#8220;Recorr\u00ed varios laboratorios, y descubr\u00ed muchas cosas que no conoc\u00eda. Yo vivo en Melipeuco y me explicaron que en ese lugar se dan muchas de las variedades de hongos que pude observar en la visita, adem\u00e1s me ense\u00f1aron porque le sal\u00eda ese vapor tan habitual que vemos en los digue\u00f1es\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">Mar\u00eda Jos\u00e9 Suazo, estudiante cuarto medio, Colegio Adenauer, Melipeuco. &nbsp;<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">&nbsp;<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">&nbsp;<\/span><\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1672242786327100.1073742108.1388936647991050&amp;type=3\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">&nbsp;<span style=\"margin: 0px;padding: 0px;border: 0px;font-size: 12pt;line-height: 18.4px;font-family: 'Trebuchet MS', sans-serif\"><span style=\"margin: 0px;padding: 0px;border: 0px;color: #0000ff;line-height: 19px\">\u00a1Haz click aqu\u00ed para ver la galer\u00eda de im\u00e1genes!<\/span><\/span><\/span><\/span><\/a><\/p>\n<p style=\"text-align: center\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\"><span style=\"margin: 0px;padding: 0px;border: 0px;font-size: 12pt;line-height: 18.4px;font-family: 'Trebuchet MS', sans-serif\"><span style=\"margin: 0px;padding: 0px;border: 0px;color: #0000ff;line-height: 19px\">&nbsp;<\/span><\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\"><span class=\"apple-converted-space\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">Periodista: Viarly Salazar \/Fotograf\u00eda: Arturo Rubio Navarro<\/span><\/span><\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 1000 estudiantes de distintas comunas de la Araucan\u00eda recorrieron los &nbsp;laboratorios de la Universidad de La Frontera, la Universidad Cat\u00f3lica de Temuco, y Aguas Araucan\u00eda. &nbsp; \u201cLo que m\u00e1s me llamo la atenci\u00f3n fue la pasi\u00f3n con que cada uno de los exponentes nos explico las cosas\u201d. &nbsp;Con estas palabras Ayleen Pe\u00f1ailillo, estudiante [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1299","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 1000 estudiantes de distintas comunas de la Araucan\u00eda recorrieron los &nbsp;laboratorios de la Universidad de La Frontera, la Universidad Cat\u00f3lica de Temuco, y Aguas Araucan\u00eda. &nbsp; \u201cLo que m\u00e1s me llamo la atenci\u00f3n fue la pasi\u00f3n con que cada uno de los exponentes nos explico las cosas\u201d. &nbsp;Con estas palabras Ayleen Pe\u00f1ailillo, estudiante [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-04T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:29+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d\",\"datePublished\":\"2015-11-04T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\"},\"wordCount\":651,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\",\"name\":\"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"datePublished\":\"2015-11-04T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:29+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d - Araucan\u00eda","og_description":"M\u00e1s de 1000 estudiantes de distintas comunas de la Araucan\u00eda recorrieron los &nbsp;laboratorios de la Universidad de La Frontera, la Universidad Cat\u00f3lica de Temuco, y Aguas Araucan\u00eda. &nbsp; \u201cLo que m\u00e1s me llamo la atenci\u00f3n fue la pasi\u00f3n con que cada uno de los exponentes nos explico las cosas\u201d. &nbsp;Con estas palabras Ayleen Pe\u00f1ailillo, estudiante [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-11-04T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:29+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d","datePublished":"2015-11-04T04:00:00+00:00","dateModified":"2019-05-20T18:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/"},"wordCount":651,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/","url":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/","name":"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"datePublished":"2015-11-04T04:00:00+00:00","dateModified":"2019-05-20T18:54:29+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/mas-de-1000-estudiantes-conocieron-diversos-laboratorios-en-la-actividad-casa-abierta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 1000 estudiantes conocieron diversos laboratorios en la actividad \u201cCasa Abierta\u201d"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1299"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1299\/revisions"}],"predecessor-version":[{"id":38182,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1299\/revisions\/38182"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}