{"id":1292,"date":"2015-10-30T00:00:00","date_gmt":"2015-10-30T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/10\/30\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/"},"modified":"2019-05-20T18:54:31","modified_gmt":"2019-05-20T18:54:31","slug":"fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/","title":{"rendered":"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC"},"content":{"rendered":"<p style=\"text-align: justify\" align=\"center\"><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\"><em>En dependencias del Auditorio del Instituto de Agroindustria de la Universidad de La Frontera, se realiz\u00f3 la Segunda Reuni\u00f3n de Evaluaci\u00f3n del Proyecto Piloto Primer Ciclo Educaci\u00f3n B\u00e1sica de Tus Competencias en Ciencias (TCC) de nuestra regi\u00f3n.<\/em><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">Con el prop\u00f3sito de analizar los avances y revisar las actividades finales de la iniciativa, se llevo a cabo la \u00faltima reuni\u00f3n correspondiente a nuevos facilitadores TCC Araucan\u00eda 2015, que este a\u00f1o fue un proyecto piloto dise\u00f1ado para ni\u00f1os y ni\u00f1as de primero a cuarto a\u00f1o de educaci\u00f3n b\u00e1sica. <\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\">As\u00ed con la presencia de m\u00e1s de veinte profesoras\/es provenientes de doce comunas, los participantes junto a las Tutoras Regionales comentaron sus positivas experiencias en la actividad el \u201cD\u00eda de la Ciencia en Mi Colegio\u201d, iniciativa que finalmente congreg\u00f3 en el mes de octubre a m\u00e1s de treinta establecimientos en La Araucan\u00eda.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">En la oportunidad, el Director del PAR Explora Araucan\u00eda, Felipe Gallardo, entreg\u00f3 palabras de bienvenida junto con compartir un momento de conversaci\u00f3n y reflexi\u00f3n con los asistentes, cuyo fin fue responder inquietudes y conocer en detalle c\u00f3mo ha sido la experiencia TCC del Proyecto Piloto Primer Ciclo en sus respectivos establecimientos educacionales.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\">Por su parte, las y los facilitadores intercambiaron opiniones respecto al desarrollo de las actividades virtuales incluidas en la carpeta metodol\u00f3gica, cumplimiento de tareas como ingresar a la Plataforma TCC, entrega de informe de avance, entre otros aspectos. Asimismo, destacaron lo enriquecedoras, \u00fatiles e importantes para ellos y en la motivaci\u00f3n de sus estudiantes, que han sido las visitas en terreno efectuadas por las Tutoras Regionales. &nbsp;&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">La jornada concluy\u00f3 con la organizaci\u00f3n de la 5\u00b0 Feria Cient\u00edfica Tus Competencias en Ciencias, donde se expusieron algunos lineamientos m\u00e1s el sorteo de los experimentos que ser\u00e1n presentados por los cuarenta talleres cient\u00edficos que participan en dicho proyecto piloto, el pr\u00f3ximo 19 de noviembre en la ciudad de Temuco. <\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">Impresiones&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\"><img loading=\"lazy\" decoding=\"async\" src=\"images\/4cua2reunion.jpg\" style=\"float: left\" height=\"98\" width=\"74\" \/>&#8220;Lo que m\u00e1s me gust\u00f3 fue conocer la experiencia de los otros colegas en relaci\u00f3n a sus muestras cient\u00edficas, eso me sirvi\u00f3 para afinar algunos detalles a m\u00ed y a la organizaci\u00f3n con mi establecimiento. Adem\u00e1s, para saber que vamos hacer el pr\u00f3ximo a\u00f1o con respecto a TCC, y tambi\u00e9n en la Feria que tenemos en noviembre&#8221;.<\/span><\/p>\n<p><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\">Facilitador Mauricio Z\u00fa\u00f1iga, Escuela Epu-Klei, Lic\u00e1n Ray.<\/span><\/p>\n<p><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\"><img loading=\"lazy\" decoding=\"async\" src=\"images\/3cua2reunion.jpg\" style=\"float: left\" height=\"90\" width=\"74\" \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">\u201cEncontr\u00e9 s\u00faper buena la reuni\u00f3n, una instancia para poder compartir las experiencias que hemos estado viviendo, respecto a las ferias de ciencias que se han hecho, y tambi\u00e9n de las visitas de las Tutoras. En resumen, fue una reuni\u00f3n provechosa\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">Facilitadora Evelyn Quezada, Escuela Rep\u00fablica de Israel, Traigu\u00e9n.<\/span><\/p>\n<p><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.902580696485449.1073741855.501010836642439&amp;type=1\"><span style=\"color: #0000ff\">Haz click aqu\u00ed para ver la galer\u00eda de im\u00e1genes<\/span><\/a><\/span><\/p>\n<p><span style=\"font-size: 12pt;font-family: trebuchet ms,geneva\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: trebuchet ms,geneva;font-size: 12pt\">Periodista: P\u00eda Benavente Gonz\u00e1lez <span style=\"background-image: initial;background-position: initial\">\/ Fotograf\u00eda: Arturo Rubio Navarro<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En dependencias del Auditorio del Instituto de Agroindustria de la Universidad de La Frontera, se realiz\u00f3 la Segunda Reuni\u00f3n de Evaluaci\u00f3n del Proyecto Piloto Primer Ciclo Educaci\u00f3n B\u00e1sica de Tus Competencias en Ciencias (TCC) de nuestra regi\u00f3n. Con el prop\u00f3sito de analizar los avances y revisar las actividades finales de la iniciativa, se llevo a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1292","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"En dependencias del Auditorio del Instituto de Agroindustria de la Universidad de La Frontera, se realiz\u00f3 la Segunda Reuni\u00f3n de Evaluaci\u00f3n del Proyecto Piloto Primer Ciclo Educaci\u00f3n B\u00e1sica de Tus Competencias en Ciencias (TCC) de nuestra regi\u00f3n. Con el prop\u00f3sito de analizar los avances y revisar las actividades finales de la iniciativa, se llevo a [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-30T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:31+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC\",\"datePublished\":\"2015-10-30T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\"},\"wordCount\":503,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\",\"name\":\"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"datePublished\":\"2015-10-30T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:31+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/","og_locale":"es_ES","og_type":"article","og_title":"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC - Araucan\u00eda","og_description":"En dependencias del Auditorio del Instituto de Agroindustria de la Universidad de La Frontera, se realiz\u00f3 la Segunda Reuni\u00f3n de Evaluaci\u00f3n del Proyecto Piloto Primer Ciclo Educaci\u00f3n B\u00e1sica de Tus Competencias en Ciencias (TCC) de nuestra regi\u00f3n. Con el prop\u00f3sito de analizar los avances y revisar las actividades finales de la iniciativa, se llevo a [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-10-30T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:31+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC","datePublished":"2015-10-30T04:00:00+00:00","dateModified":"2019-05-20T18:54:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/"},"wordCount":503,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/","url":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/","name":"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"datePublished":"2015-10-30T04:00:00+00:00","dateModified":"2019-05-20T18:54:31+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/fructifero-segundo-encuentro-de-proyecto-piloto-primer-ciclo-tcc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"Fruct\u00edfero segundo encuentro de Proyecto Piloto Primer Ciclo TCC"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1292"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1292\/revisions"}],"predecessor-version":[{"id":38187,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1292\/revisions\/38187"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}