{"id":1276,"date":"2015-10-21T00:00:00","date_gmt":"2015-10-21T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/10\/21\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/"},"modified":"2019-05-20T18:54:38","modified_gmt":"2019-05-20T18:54:38","slug":"en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/","title":{"rendered":"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15908\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/f16a562b55625e594b8f40d0c125eb11.jpg\" alt=\"\" width=\"4608\" height=\"3456\" \/><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\"><i>Considerada como una de las actividades emblem\u00e1ticas de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda <\/i><span style=\"background-image: initial;background-position: initial\">(SNCyT) de Explora CONICYT. <\/span><i>En nuestra regi\u00f3n, son m\u00e1s de treinta establecimientos educacionales los que se han sumado a esta iniciativa desarrollada a lo largo del pa\u00eds.<\/i><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">Durante este mes, diversos jardines, colegios y liceos durante una semana o d\u00eda cambiaron parte de sus actividades curriculares para llevar a cabo ferias cient\u00edficas, concursos y presentaciones art\u00edsticas inspiradas en la ciencia. Lo anterior, con el fin de motivar el inter\u00e9s por la ciencia y la tecnolog\u00eda a toda la comunidad escolar.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">As\u00ed, en la actividad <span style=\"background-image: initial;background-position: initial\">promovida en la regi\u00f3n por el PAR Explora Araucan\u00eda,<\/span> docentes, &nbsp;estudiantes m\u00e1s apoderados junto a la comunidad escolar y p\u00fablico en general han participado de estas jornadas, efectuadas en m\u00e1s de quince comunas como Angol, Traigu\u00e9n, Lonquimay, Freire, Carahue, Saavedra, Temuco, Pitrufqu\u00e9n, Villarrica, entre otras.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">TCC en <span style=\"background-image: initial;background-position: initial\">SNCyT<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">La celebraci\u00f3n del <span style=\"background-image: initial;background-position: initial\">D\u00eda de la Ciencia en Mi Colegio<\/span> en La Araucan\u00eda, esta unida a la implementaci\u00f3n de Tus Competencias en Ciencias (TCC). Dicha propuesta metodol\u00f3gica, realiza mediante l\u00fadicos y did\u00e1cticos talleres cient\u00edficos la valoraci\u00f3n de la ciencia y tecnolog\u00eda en los colegios.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">Es por ello que en los establecimientos que se unieron a este d\u00eda especial, hay exposiciones de experimentos de la iniciativa presentados por los estudiantes inscritos en los talleres. De esta manera, \u201cBurbujas saltarinas\u201d, \u201c\u00bfPueden las casas resistir un terremoto?\u201d y \u201cVer para Comer\u201d despertaron el asombro de los asistentes, evidenciando que la ciencia y tecnolog\u00eda puede ser sencilla, entretenida y sobre todo sorprendente.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">Impresiones<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15909\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/zzzzdiaciencia20153.jpg\" style=\"float: left\" height=\"90\" width=\"82\" \/>\u201cLa actividad me pareci\u00f3 muy entretenida, porque tuvo una gran cantidad de temas como los terremotos, el experimento de cuando la sal se evapora o el puesto del liceo invitado\u201d.<\/span><\/p>\n<p style=\"margin: 11.25pt 0cm;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">Cristopher Vel\u00e1squez, estudiante de octavo a\u00f1o, Escuela Lucila Godoy Alcayaga de Angol<\/span><\/p>\n<p style=\"margin: 11.25pt 0cm;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15910\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/zzdiaciencia20152.jpg\" style=\"float: left\" height=\"90\" width=\"84\" \/>\u201cHa venido mucha gente, una aprende mucho aqu\u00ed y es s\u00faper lindo ver como los ni\u00f1os m\u00e1s peque\u00f1os exponen. Ahora estoy presentando el huevo geoda, que es un huevo que parece de cristal y es un experimento muy vistoso, entretenido de hacer y puede servir hasta de adorno\u201d,<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">Viviana Ortega, estudiante de s\u00e9ptimo a\u00f1o, Escuela Particular N\u00famero 2 de Lonquimay.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva;background-image: initial;background-position: initial\"><i style=\"font-family: 'trebuchet ms', geneva;font-size: 16px;text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15911\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/zzxDaniela-Curihual.jpg\" style=\"float: left\" height=\"90\" width=\"83\" \/><\/i>\u201cMe gust\u00f3 la participaci\u00f3n y motivaci\u00f3n de los estudiantes, aprend\u00ed que con experimentos sencillos, podemos lograr aprendizajes significativos en la comunidad educativa\u201d. &nbsp;&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;font-family: 'trebuchet ms', geneva;background-image: initial;background-position: initial\">Daniela Curihual, Facilitadora TCC Proyecto Piloto Primer Ciclo, Escuela Llaima, Temuco<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\"><a href=\"https:\/\/goo.gl\/IxMua8\"><span style=\"font-family: 'Trebuchet MS',sans-serif;border: 1pt none windowtext;padding: 0cm;font-size: 12pt;color: #0000ff\"><span style=\"color: #0000ff\"><span style=\"cursor: pointer;background-image: initial;background-position: initial\">\u00a1Haz click aqu\u00ed para ver la galer\u00eda de im\u00e1genes!<\/span><\/span><\/span><\/a><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1668551746696204.1073742101.1388936647991050&amp;type=3\"><span style=\"font-family: 'Trebuchet MS',sans-serif;border: 1pt none windowtext;padding: 0cm;font-size: 12pt;color: #0000ff\"><span style=\"color: #0000ff\"><span style=\"cursor: pointer;background-image: initial;background-position: initial\"><\/span><\/span><\/span><\/a><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'trebuchet ms', geneva\">Periodista: P\u00eda Benavente Gonz\u00e1lez&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 12pt\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerada como una de las actividades emblem\u00e1ticas de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda (SNCyT) de Explora CONICYT. En nuestra regi\u00f3n, son m\u00e1s de treinta establecimientos educacionales los que se han sumado a esta iniciativa desarrollada a lo largo del pa\u00eds. Durante este mes, diversos jardines, colegios y liceos durante una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Considerada como una de las actividades emblem\u00e1ticas de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda (SNCyT) de Explora CONICYT. En nuestra regi\u00f3n, son m\u00e1s de treinta establecimientos educacionales los que se han sumado a esta iniciativa desarrollada a lo largo del pa\u00eds. Durante este mes, diversos jardines, colegios y liceos durante una [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-21T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:38+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11-1024x768.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio\",\"datePublished\":\"2015-10-21T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\"},\"wordCount\":474,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\",\"name\":\"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg\",\"datePublished\":\"2015-10-21T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:38+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg\",\"width\":4608,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/","og_locale":"es_ES","og_type":"article","og_title":"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio - Araucan\u00eda","og_description":"Considerada como una de las actividades emblem\u00e1ticas de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda (SNCyT) de Explora CONICYT. En nuestra regi\u00f3n, son m\u00e1s de treinta establecimientos educacionales los que se han sumado a esta iniciativa desarrollada a lo largo del pa\u00eds. Durante este mes, diversos jardines, colegios y liceos durante una [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-10-21T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:38+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11-1024x768.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio","datePublished":"2015-10-21T04:00:00+00:00","dateModified":"2019-05-20T18:54:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/"},"wordCount":474,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/","url":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/","name":"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg","datePublished":"2015-10-21T04:00:00+00:00","dateModified":"2019-05-20T18:54:38+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#primaryimage","url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg","contentUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/f16a562b55625e594b8f40d0c125eb11.jpg","width":4608,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/en-la-araucania-tambien-celebran-el-dia-de-la-ciencia-en-mi-colegio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"En La Araucan\u00eda tambi\u00e9n celebran el D\u00eda de la Ciencia en Mi Colegio"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1276"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1276\/revisions"}],"predecessor-version":[{"id":38198,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1276\/revisions\/38198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media\/1277"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}