{"id":1264,"date":"2015-10-19T00:00:00","date_gmt":"2015-10-19T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/10\/19\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/"},"modified":"2019-05-20T18:54:41","modified_gmt":"2019-05-20T18:54:41","slug":"1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/","title":{"rendered":"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15849\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/4854123630dc4a547c6dfca9058d58c0.jpg\" alt=\"\" width=\"2912\" height=\"2000\" \/><\/p>\n<p><span style=\"font-size: 12pt\"><em><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm\">Continuando con la celebraci\u00f3n de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda, investigadores e investigadoras se trasladaron a distintos puntos de nuestra regi\u00f3n para compartir sus conocimientos <\/span><\/em><span style=\"font-family: 'Trebuchet MS', sans-serif\">y experiencias de vida<em><span style=\"border: 1pt none windowtext;padding: 0cm\"> con cientos de ni\u00f1os, ni\u00f1as, y j\u00f3venes,&nbsp; en el marco de la actividad \u201c1000 cient\u00edficos 1000 aulas\u201d.<\/span><\/em><\/span><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\">&nbsp;<\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">\u201cCreo que lo que m\u00e1s me llamo la atenci\u00f3n fue la parte donde nos dijeron que para ser un cient\u00edfico no hace falta ni tener mucho dinero, ni ser una mente incre\u00edble, s\u00f3lo se necesita curiosidad\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">Con estas palabras, Arturo Pacheco, estudiante de quinto b\u00e1sico de la Escuela Puralaco N\u00b016 de Tolt\u00e9n, manifiesta su entusiasmo por la visita de los cient\u00edficos, para \u00e9l esta experiencia le demuestra que todos los sue\u00f1os se pueden realizar, s\u00f3lo basta tener las ganas de desarrollarlos.<\/span><\/p>\n<p style=\"margin: 8.65pt 0cm;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">La iniciativa coordinada por el PAR Explora Araucan\u00eda y ejecutada por la Universidad de La Frontera, &nbsp;busca ser una instancia de encuentro entre la comunidad cient\u00edfica y la comunidad educativa, de modo que los estudiantes conozcan&nbsp; sobre ciencia de una manera m\u00e1s cercana, interes\u00e1ndose por ejecutarla y as\u00ed ayudar al desarrollo de la humanidad.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">La Mg. Andrea Arias, Directora de la Menci\u00f3n Qu\u00edmica de la carrera de <span style=\"background-image: initial;background-position: initial\">Pedagog\u00eda en Ciencias de la Universidad de La Frontera, es una de las protagonistas de 1000 cient\u00edficos 1000 aulas, con orgullo, nos manifiesta que lleva 10 a\u00f1os formando parte de esta linda actividad. Uno de sus principales objetivos es <\/span>llegar a las escuelas rurales, ya que muchas veces tienen menos posibilidades de conocer el asombroso mundo de la ciencia, pero m\u00e1s all\u00e1 de generar un aprendizaje del \u00e1rea cient\u00edfica, la acad\u00e9mica busca motivar <span style=\"background-image: initial;background-position: initial\">a trav\u00e9s &nbsp;de su <\/span>experiencia, mostr\u00e1ndole a los escolares que todo es posible, que ellos tambi\u00e9n pueden llegar a la universidad, a un centro de formaci\u00f3n t\u00e9cnica, que conozcan que el estudiar permite abrir los horizontes.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">\u201cQue los visite alguien de la universidad es algo ya muy llamativo, incluso, en pleno siglo XXI que los visite una mujer es algo sorprendente para ellos, en relaci\u00f3n a esto, siempre les hago el hincapi\u00e9 que yo estudie en una escuela rural y que independiente de cual lejos pueda estar nuestro colegio, del g\u00e9nero, condici\u00f3n econ\u00f3mica, siempre se pueden aprender cosas nuevas. Si alguien no quiere estudiar algo relacionado con la ciencia, les ense\u00f1o que ella est\u00e1 presente en el diario vivir, que &nbsp;s\u00f3lo debemos estar m\u00e1s atentos a lo que nos rodea\u201d. Afirm\u00f3, Arias. <\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">En la charla \u201cQu\u00edmica y sus encantos\u201d la acad\u00e9mica expone abordando temas generales de la qu\u00edmica, mostr\u00e1ndole a los estudiantes que normalmente hacen ciencia sin saberlo, que basta con observar unos instantes y podr\u00e1n ver alguna reacci\u00f3n qu\u00edmica, a su vez, entender c\u00f3mo est\u00e1 constituida la materia y sus procesos de transformaci\u00f3n, dependiendo de ciertos factores, generando actividades practicas &nbsp;para que ni\u00f1os y ni\u00f1as participen, pregunten y se asombren.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">Dentro de los experimentos realizados se pueden apreciar cambios qu\u00edmicos que tienen que ver mucho con la formaci\u00f3n de coloraciones, con la expresi\u00f3n de luces, b\u00e1sicamente cosas que los estudiantes pueden observar f\u00e1cilmente incorporando elementos de uso cotidiano, como, la leche, el jab\u00f3n, la bebida, cosas sencillas, para que ellos las puedan hacer en sus casas. <\/span><\/p>\n<p style=\"margin: 8.65pt 0cm;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif\">En tanto, el Dr. Juan Carlos Ram\u00edrez,&nbsp;<\/span><i><\/i><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">docente del Departamento de Ciencias Qu\u00edmicas y Recursos Naturales de la Universidad de La Frontera, tambi\u00e9n es un ente importante en el desarrollo de <span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 16px;line-height: 16.1333px;text-align: justify\">1000 cient\u00edficos 1000 aulas,<\/span>&nbsp;el acad\u00e9mico ha participado durante 5 &nbsp;<\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">a\u00f1os en la actividad &nbsp;impartiendo charlas sobre el medio ambiente, dando \u00e9nfasis al gran problema al cual se ve enfrentada la humanidad, con respecto a la contaminaci\u00f3n, &nbsp;degradaci\u00f3n de los recursos y creciente escasez, instando a los j\u00f3venes a que realicen una reflexi\u00f3n, sinti\u00e9ndose participes del gran conflicto ambiental que hay en el mundo.<\/span><\/span><\/p>\n<p style=\"margin: 8.65pt 0cm;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">Para el Dr. Ram\u00edrez, este tipo de actividad representa un tremendo beneficio, porque acerca el quehacer cient\u00edfico a las escuelas, situaci\u00f3n que no es habitual, ya que si bien los estudiantes tienen clases ciencia y laboratorios, el m\u00e9todo cient\u00edfico en su expresi\u00f3n m\u00e1s pura se aplica m\u00e1s que nada en las universidades, es por esto que en sus charlas &nbsp;realiza un acercamiento de m\u00e9todo cient\u00edfico con diferentes \u00e9nfasis.<\/span><\/p>\n<p style=\"margin: 8.65pt 0cm;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">&nbsp;\u201cLa indolencia y despreocupaci\u00f3n, son uno de los principales problemas, en especial en el contexto en el que nos encontramos con el boom digital, las personas se sienten m\u00e1s aisladas de todo lo que se refiere<br \/>\n a los recursos naturales,&nbsp; y la gente pierde la conciencia de su importancia. En mis charlas me preocupo que los ni\u00f1os y ni\u00f1as piensen, analicen y se den cuenta que con peque\u00f1as medidas podemos aportar al medio ambiente\u201d.<\/span><\/p>\n<p style=\"margin: 8.65pt 0cm;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">En La Araucan\u00eda son m\u00e1s de 100 las charlas que se est\u00e1n desarrollando, a trav\u00e9s de la cuales se espera beneficiar alrededor de&nbsp; 5000 estudiantes de primer ciclo b\u00e1sico a educaci\u00f3n media, quienes se podr\u00e1n sorprender con los enormes beneficios que el conocimiento cient\u00edfico entrega a la sociedad. <\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-size: 12pt\">Durante todo el mes de octubre se estar\u00e1 llevando &nbsp;a cabo esta iniciativa, donde simult\u00e1neamente cient\u00edficos expondr\u00e1n sobre variadas tem\u00e1ticas en toda la regi\u00f3n, &nbsp;en un encuentro fruct\u00edfero entre ciencia y comunidad educativa.<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15850\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/1000-Cientficos-1000-Aulas-2015-4.jpg\" alt=\"\" width=\"848\" height=\"228\" style=\"margin-left: auto;margin-right: auto\" \/><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif\"><span style=\"font-size: 12pt\">&nbsp;<\/span><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif\"><span style=\"font-size: 12pt\">&nbsp;<\/span><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;line-height: 12.1pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif\"><span style=\"font-size: 12pt\">Impresione<\/span>s<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15851\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/1000-Cientficos-1000-Aulas-2015-2.jpg\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cMe gust\u00f3 cuando experimentamos con el platito, pusimos la leche con el colorante y se formo un remolino de colores, fue muy entretenido, no pens\u00e9 que iba a pasar eso\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">Dianira Llancao, estudiante cuarto b\u00e1sico, Escuela San Antonio de Llamuco, Vilc\u00fan.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15852\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/1000-Cientficos-1000-Aulas-2015-1.jpg\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cLa actividad me pareci\u00f3 muy buena, me gustaron las reacciones qu\u00edmicas, cuando grande me gustar\u00eda estudiar una carrera relacionada con la ciencia, por eso quiero aprender mucho sobre ella\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">Camilo Trurreupan, estudiante quinto b\u00e1sico, Escuela San Antonio de Llamuco, Vilc\u00fan.<\/span><\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1665357380348974.1073742097.1388936647991050&amp;type=3\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/a><\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1665357380348974.1073742097.1388936647991050&amp;type=3\">&nbsp;<\/a><\/p>\n<p style=\"margin: 8.65pt 0cm;padding: 0px;border: 0px;color: #666666;font-family: 'Trebuchet MS', helvetica, arial, sans-serif;font-size: 15px;line-height: 12.1pt;text-align: center;background-image: initial;background-position: initial\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1665357380348974.1073742097.1388936647991050&amp;type=3\"><span style=\"margin: 0px;padding: 0px;border: 0px;font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\"><span style=\"margin: 0px;padding: 0px;border: 0px;font-size: 12pt;line-height: 18.4px;font-family: 'Trebuchet MS', sans-serif;color: #0000ff\"><span style=\"margin: 0px;padding: 0px;border: 0px;cursor: pointer;font-size: 12pt;line-height: 21px;background-image: initial;background-position: initial\"><span style=\"margin: 0px;padding: 0px;border: 0px;font-size: 12pt\"><span style=\"margin: 0px;padding: 0px;border: 0px;line-height: 26.2px\"><span style=\"margin: 0px;padding: 0px;border: 0px\"><span style=\"margin: 0px;padding: 0px;border: 0px;color: #3366ff\">\u00a1Haz click aqu\u00ed para ver la galer\u00eda de im\u00e1genes!<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1665357380348974.1073742097.1388936647991050&amp;type=3\">&nbsp;<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"margin: 8.65pt 0cm;padding: 0px;border: 0px;color: #666666;font-family: 'Trebuchet MS', helvetica, arial, sans-serif;font-size: 15px;line-height: 12.1pt;text-align: center;background-image: initial;background-position: initial\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif\">Periodista: Viarly Salazar Fritz \/Arturo Rubio Navarro<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuando con la celebraci\u00f3n de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda, investigadores e investigadoras se trasladaron a distintos puntos de nuestra regi\u00f3n para compartir sus conocimientos y experiencias de vida con cientos de ni\u00f1os, ni\u00f1as, y j\u00f3venes,&nbsp; en el marco de la actividad \u201c1000 cient\u00edficos 1000 aulas\u201d. &nbsp; \u201cCreo que lo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Continuando con la celebraci\u00f3n de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda, investigadores e investigadoras se trasladaron a distintos puntos de nuestra regi\u00f3n para compartir sus conocimientos y experiencias de vida con cientos de ni\u00f1os, ni\u00f1as, y j\u00f3venes,&nbsp; en el marco de la actividad \u201c1000 cient\u00edficos 1000 aulas\u201d. &nbsp; \u201cCreo que lo [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-19T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:41+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0-1024x703.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda\",\"datePublished\":\"2015-10-19T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\"},\"wordCount\":1090,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\",\"name\":\"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg\",\"datePublished\":\"2015-10-19T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:41+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg\",\"width\":2912,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/","og_locale":"es_ES","og_type":"article","og_title":"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda - Araucan\u00eda","og_description":"Continuando con la celebraci\u00f3n de la XXI Semana Nacional de la Ciencia y la Tecnolog\u00eda, investigadores e investigadoras se trasladaron a distintos puntos de nuestra regi\u00f3n para compartir sus conocimientos y experiencias de vida con cientos de ni\u00f1os, ni\u00f1as, y j\u00f3venes,&nbsp; en el marco de la actividad \u201c1000 cient\u00edficos 1000 aulas\u201d. &nbsp; \u201cCreo que lo [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-10-19T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:41+00:00","og_image":[{"width":1024,"height":703,"url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0-1024x703.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda","datePublished":"2015-10-19T04:00:00+00:00","dateModified":"2019-05-20T18:54:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/"},"wordCount":1090,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/","url":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/","name":"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg","datePublished":"2015-10-19T04:00:00+00:00","dateModified":"2019-05-20T18:54:41+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#primaryimage","url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg","contentUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/4854123630dc4a547c6dfca9058d58c0.jpg","width":2912,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/1000-cientificos-1000-aulas-investigadores-abandonan-sus-salas-de-clases-para-visitar-establecimientos-de-la-araucania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"\u201c1000 cient\u00edficos 1000 aulas\u201d investigadores abandonan sus salas de clases para visitar establecimientos de la Araucan\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1264"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1264\/revisions"}],"predecessor-version":[{"id":38203,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1264\/revisions\/38203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media\/1265"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}