{"id":1227,"date":"2015-10-09T00:00:00","date_gmt":"2015-10-09T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/10\/09\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/"},"modified":"2019-05-20T18:54:47","modified_gmt":"2019-05-20T18:54:47","slug":"cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/","title":{"rendered":"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15589\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/323b4bedbcd8f41b9749c79d20a9922c.jpg\" alt=\"\" width=\"3008\" height=\"2000\" \/><\/p>\n<p><span style=\"color: #575252\"><i><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">El PAR Explora Araucan\u00eda imparti\u00f3 entretenido taller de agricultura urbana sustentable con el objetivo de ense\u00f1arles a los escolares la importancia de la tierra y de generar los espacios para cultivar alimentos m\u00e1s saludables.<\/span><\/i><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"color: #575252\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">La agricultura es un arte de cultivo que lamentablemente cada vez es menos practicado y es que al parecer las nuevas generaciones han ido perdiendo el inter\u00e9s por aprender sobre la tierra y los m\u00faltiples beneficios que nos otorga. A su vez la migraci\u00f3n de personas del <\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">&nbsp;campo a la ciudad ha provocado que se pierdan muchas de las antiguas costumbres, como cultivar nuestra propia comida.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;color: #575252\"><span style=\"font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-15590\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/wwwwwwww-6.jpg\" alt=\"\" align=\"right\" width=\"345\" height=\"257\" \/>Es por esto, que a trav\u00e9s de una interactiva actividad las ingeniero agr\u00f3nomo&nbsp;<\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">Daniela Romero y Daniela Berr\u00edos, les ense\u00f1aron a estudiantes de cinco escuelas rurales de la Araucan\u00eda distintas t\u00e9cnicas agr\u00edcolas.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;color: #575252\"><span style=\"font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">En la primera etapa te\u00f3rica del taller, los escolares conocieron sobre los tipos de suelos, el <\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">arenoso, arcilloso&nbsp; y limoso, los que unidos forman la mezcla perfecta para sembrar gran variedad de hortalizas. Adem\u00e1s aprendieron sobre diversas interrogantes, como en qu\u00e9 \u00e9poca se siembran ciertos cultivos, analizaron verduras de invierno y verano, identificando su categor\u00eda seg\u00fan corresponda a &nbsp;tallo, hoja, fruto, etc.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"color: #575252;font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">\u201cA los peque\u00f1os les ense\u00f1amos sobre la clasificaci\u00f3n de las hortalizas, procuramos que ellos interact\u00faen con ellas, que las puedan &nbsp;tocar, agrupar seg\u00fan corresponda, que se cuestionen sobre su producci\u00f3n y que sepan que ellos pueden tener tambi\u00e9n las suyas\u201d. Afirm\u00f3, Romero.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"color: #575252;font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">En la segunda fase del taller, los escolares ponen en pr\u00e1ctica lo aprendido, pueden ver las diferencias y semejanzas de los tres tipos de suelo, plantar&nbsp; semillas en botellas, ver la profundidad de suelo que debe tener la tierra de acuerdo al tama\u00f1o de cada semilla, sembrar lechugas y aplicar fertilizantes a algunas para ir examinando su crecimiento.<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #575252;font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #575252;font-size: 12pt\">Adem\u00e1s, dentro del taller se contempla la entrega de un completo kit de materiales, que incluye una amplia caja de madera que utilizar\u00e1n como mini huerta y donde podr\u00e1n ir observando el crecimiento de sus plantas, un set de fichas con el nombre cient\u00edfico de cada hortaliza y sus beneficios, y semillas de reposici\u00f3n para que contin\u00faen el ciclo de sembrado.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"color: #575252\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">Las escuelas que fueron beneficiadas con esta actividad fueron la <\/span><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Escuela San Ram\u00f3n de Ercilla, Escuela San Luis de Puc\u00f3n, Escuela Coi Coi y Escuela el Manzano&nbsp;de Carahue, y la Escuela Allipen de Freire, quienes aprendieron un poco m\u00e1s sobre una agricultura responsable en base a la educaci\u00f3n.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright size-full wp-image-15591\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/wwwwwwww-1.jpg\" alt=\"\" align=\"right\" width=\"348\" height=\"254\" \/>Es fundamental que nuestros ni\u00f1os y ni\u00f1as aprendan la importancia de la agricultura, como esta ayuda al desarrollo de la humanidad y como nosotros podemos ayudar a construir un mundo mejor con peque\u00f1os detalles, con simplemente interesarnos por aprender cosas nuevas, crear una agricultura sustentable que incluso podemos cultivar en el jard\u00edn de la casa.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">En el mundo, la agricultura ocupa un sector econ\u00f3mico indispensable y fundamental para la alimentaci\u00f3n de millones de personas, es por esto la importancia de trabajar sobre nuestras ra\u00edces, ense\u00f1arle a nuestros estudiantes la relevancia de la tierra &nbsp;para que ellos puedan trasmitir estos conocimientos a las nuevas generaciones, recordemos que son los ni\u00f1os y ni\u00f1as quienes formar\u00e1n el futuro de nuestro pa\u00eds.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">Impresiones<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #575252;font-size: 12pt\">\u201cDecidimos crear la Consultora \u201cComo en el Campo\u201d, porque observamos la necesidad de ense\u00f1arle a las personas que sin importar los espacios se puede tener agricultura en el hogar, es por esto que a los ni\u00f1os, le mostramos como con elementos sencillos como los envases de yogurt, las bebidas, todos elementos reutilizables podemos tener cultivos en el hogar\u201d.<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #575252;font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #575252;font-size: 12pt\">Daniela Berrios, Consultora \u201cComo el Campo\u201d.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15592\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/Agricultura-sustentable-12.jpg\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cYo en mi casa con mi abuelita tenemos una huerta afuera y tambi\u00e9n tenemos un invernadero, ah\u00ed sembramos muchas plantitas, tenemos tomate, lechuga, repollo, y hartas cosas m\u00e1s. Lo que yo no sab\u00eda era que muchas de las verduras en realidad eran frutas porque ten\u00edan pepas adentro, adem\u00e1s tampoco sab\u00eda que las hortalizas se deb\u00edan sembrar a una profundidad que es el doble del tama\u00f1o de la semillas, todas esas cosas se las voy a ense\u00f1ar a mi abuelita para que&nbsp; tengamos verduras m\u00e1s ricas y grandes\u201d.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">Thomas&nbsp; Valencia, estudiante tercero b\u00e1sico, Escuela San Luis de Puc\u00f3n.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;color: #575252;background-image: initial;background-position: initial\">Periodista: Viarly Salazar Fritz \/Fotograf\u00eda: Arturo Rubio Navarro.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El PAR Explora Araucan\u00eda imparti\u00f3 entretenido taller de agricultura urbana sustentable con el objetivo de ense\u00f1arles a los escolares la importancia de la tierra y de generar los espacios para cultivar alimentos m\u00e1s saludables. La agricultura es un arte de cultivo que lamentablemente cada vez es menos practicado y es que al parecer las nuevas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El PAR Explora Araucan\u00eda imparti\u00f3 entretenido taller de agricultura urbana sustentable con el objetivo de ense\u00f1arles a los escolares la importancia de la tierra y de generar los espacios para cultivar alimentos m\u00e1s saludables. La agricultura es un arte de cultivo que lamentablemente cada vez es menos practicado y es que al parecer las nuevas [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-09T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:47+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c-1024x681.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable\",\"datePublished\":\"2015-10-09T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\"},\"wordCount\":786,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\",\"name\":\"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg\",\"datePublished\":\"2015-10-09T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:47+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg\",\"width\":3008,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/","og_locale":"es_ES","og_type":"article","og_title":"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable - Araucan\u00eda","og_description":"El PAR Explora Araucan\u00eda imparti\u00f3 entretenido taller de agricultura urbana sustentable con el objetivo de ense\u00f1arles a los escolares la importancia de la tierra y de generar los espacios para cultivar alimentos m\u00e1s saludables. La agricultura es un arte de cultivo que lamentablemente cada vez es menos practicado y es que al parecer las nuevas [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-10-09T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:47+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c-1024x681.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable","datePublished":"2015-10-09T04:00:00+00:00","dateModified":"2019-05-20T18:54:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/"},"wordCount":786,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/","url":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/","name":"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg","datePublished":"2015-10-09T04:00:00+00:00","dateModified":"2019-05-20T18:54:47+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#primaryimage","url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg","contentUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/323b4bedbcd8f41b9749c79d20a9922c.jpg","width":3008,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/cinco-fueron-las-escuelas-beneficiadas-con-didactico-taller-de-agricultura-sustentable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"Cinco fueron las escuelas beneficiadas con did\u00e1ctico taller de agricultura sustentable"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1227"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1227\/revisions"}],"predecessor-version":[{"id":38208,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1227\/revisions\/38208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media\/1228"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}