{"id":1222,"date":"2015-10-08T00:00:00","date_gmt":"2015-10-08T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/10\/08\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/"},"modified":"2019-05-20T18:54:47","modified_gmt":"2019-05-20T18:54:47","slug":"escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/","title":{"rendered":"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15503\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/1715a9bcafc4936d3266138c7b84781a.jpg\" alt=\"\" width=\"3008\" height=\"2000\" \/><\/p>\n<p><em><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;background-image: initial;background-position: initial\">En una interactiva experiencia 10 estudiantes de los Talleres de Rob\u00f3tica Educativa Mustakis conocieron Laboratorio de Centro de&nbsp; Control Num\u00e9rico.<\/span><\/span><\/em><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">Los talleres de <\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\">Fundaci\u00f3n<\/span><span style=\"font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\"> Mustakis promueven no s\u00f3lo el aprendizaje de programaci\u00f3n, sino que tambi\u00e9n el desarrollo de habilidades como el pensamiento l\u00f3gico, desarrollo personal, liderazgo, emprendimiento y trabajo en equipo. Es por esto que se busca &nbsp;que los estudiantes conozcan el mundo universitario y se contemplan visitas a laboratorios, conociendo de cerca la<\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\"> tecnolog\u00eda e innovaci\u00f3n presente en las maquinarias, oportunidad en que los j\u00f3venes pueden<\/span><span style=\"font-family: 'Trebuchet MS', sans-serif\"> aplicar los contenidos adquiridos.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">En el laboratorio del &nbsp;Departamento de Ingenier\u00eda Mec\u00e1nica de la Universidad de La Frontera, los estudiantes aprendieron sobre la elaboraci\u00f3n de dise\u00f1o en 3D, modelaci\u00f3n de herramientas y estructuras, entre otras cosas.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">En la oportunidad, el Dr. Mario Guzm\u00e1n Villase\u00f1or, acad\u00e9mico de la unidad, mostr\u00f3 las caracter\u00edsticas de las diversas maquinarias, como algunas ten\u00edan una utilizaci\u00f3n m\u00e1s manual y otras eran completamente computarizadas, explicando la manipulaci\u00f3n de materiales y labores en procesos espec\u00edficos.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">\u201cExisten procesos de producci\u00f3n para distintos tipos de productos, en la clase hablamos fundamentalmente de aquellos que se pueden deformar y obtener viruta, lo hice pensando en m\u00e1quinas antiguas convencionales y luego en el recorrido que hicimos al centro mecanizado pudimos realizar una operaci\u00f3n manual, observar las maquinas y ver como la tecnolog\u00eda se ha ido desarrollando a lo largo de los a\u00f1os\u201d. Afirm\u00f3, el acad\u00e9mico.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-family: 'Trebuchet MS', sans-serif\"><span style=\"font-size: 12pt\">La primera fase de la clase consisti\u00f3 en una parte te\u00f3rica, donde a trav\u00e9s de videos se les mostro a los estudiantes la utilizaci\u00f3n de las diversas maquinarias, lo que luego pudieron reforzar en terreno conociendo algunas de las aplicaciones industriales de la rob\u00f3tica, otorgando mayor sentido a lo aprendido y favoreciendo el desarrollo de habilidades en los ni\u00f1os, ni\u00f1as y j\u00f3venes.<\/span><\/span><\/p>\n<p><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">Esta iniciativa es liderada por la directora de la carrera de Ingenier\u00eda Civil Electr\u00f3nica, Ing. Patricia Mu\u00f1oz, y en ella tambi\u00e9n participan como monitores estudiantes de la Facultad de Ingenier\u00eda y Ciencias de la Universidad de La Frontera. Adem\u00e1s, cuenta con el respaldo de esta unidad universitaria y del PAR Explora Araucan\u00eda.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">La pr\u00f3xima visita se realizar\u00e1 el 16 de octubre, ocasi\u00f3n en la que los estudiantes tendr\u00e1n la oportunidad de conocer el moderno Centro Industrial de Rosen.&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15504\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/Robtica-visita-mecnica-0.jpg\" alt=\"\" width=\"856\" height=\"230\" style=\"margin-left: auto;margin-right: auto\" \/><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">&nbsp;<\/span><\/p>\n<p style=\"margin: 0cm 0cm 0.0001pt;text-align: justify;background-image: initial;background-position: initial\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt\">Impresiones<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15505\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/Robtica-visita-mecnica-03.jpg\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cLa actividad es muy importante para los j\u00f3venes, es una de las visitas a los laboratorios que tenemos programadas para que ellos conozcan las aplicaciones que tienen los contenidos que le ense\u00f1amos durante las sesiones de los talleres, as\u00ed tambi\u00e9n se sienten m\u00e1s motivados por aprender cosas nuevas\u201d.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Jos\u00e9 Manuel Rifo, coordinador zonal interescolar, Talleres de Rob\u00f3tica Educativa <\/span><span style=\"font-size: 12pt\"><em><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-style: normal;background-image: initial;background-position: initial\">Mustakis.<\/span><\/em><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt\"><em><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-style: normal;background-image: initial;background-position: initial\">&nbsp;<\/span><\/em><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt\"><em><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-style: normal;background-image: initial;background-position: initial\">&nbsp;<\/span><\/em><\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15506\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/10\/Robtic\na-visita-mecnica-02.jpg\" alt=\"\" align=\"left\" width=\"90\" height=\"90\" \/>\u201cMe parece muy entretenida esta oportunidad, no se da siempre por eso es bueno aprovecharla, yo quiero estudiar ingenier\u00eda comercial en la universidad y esta actividad &nbsp;me sirve bastante para conocer un poco m\u00e1s mi futura casa de estudios\u201d.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Aracely Melilao, estudiante s\u00e9ptimo b\u00e1sico, Escuela San Francisco de Cunco chico.<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: center\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: center\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1653666494851396.1073742081.1388936647991050&amp;type=3\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\"><span style=\"color: #0000ff;font-family: 'Trebuchet MS', sans-serif;font-size: 16px;line-height: 26.2px;text-align: center\">\u00a1Haz click aqu\u00ed para ver la galer\u00eda de im\u00e1genes!<\/span><\/span><\/a><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: center\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">&nbsp;<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt;text-align: justify\"><span style=\"font-size: 12pt;font-family: 'Trebuchet MS', sans-serif\">Periodista: Viarly Salazar Fritz \/ Fotograf\u00eda: Arturo Rubio Navarro<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una interactiva experiencia 10 estudiantes de los Talleres de Rob\u00f3tica Educativa Mustakis conocieron Laboratorio de Centro de&nbsp; Control Num\u00e9rico. Los talleres de Fundaci\u00f3n Mustakis promueven no s\u00f3lo el aprendizaje de programaci\u00f3n, sino que tambi\u00e9n el desarrollo de habilidades como el pensamiento l\u00f3gico, desarrollo personal, liderazgo, emprendimiento y trabajo en equipo. Es por esto que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"En una interactiva experiencia 10 estudiantes de los Talleres de Rob\u00f3tica Educativa Mustakis conocieron Laboratorio de Centro de&nbsp; Control Num\u00e9rico. Los talleres de Fundaci\u00f3n Mustakis promueven no s\u00f3lo el aprendizaje de programaci\u00f3n, sino que tambi\u00e9n el desarrollo de habilidades como el pensamiento l\u00f3gico, desarrollo personal, liderazgo, emprendimiento y trabajo en equipo. Es por esto que [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-08T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:54:47+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a-1024x681.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro\",\"datePublished\":\"2015-10-08T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\"},\"wordCount\":578,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\",\"name\":\"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg\",\"datePublished\":\"2015-10-08T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:54:47+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg\",\"width\":3008,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/","og_locale":"es_ES","og_type":"article","og_title":"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro - Araucan\u00eda","og_description":"En una interactiva experiencia 10 estudiantes de los Talleres de Rob\u00f3tica Educativa Mustakis conocieron Laboratorio de Centro de&nbsp; Control Num\u00e9rico. Los talleres de Fundaci\u00f3n Mustakis promueven no s\u00f3lo el aprendizaje de programaci\u00f3n, sino que tambi\u00e9n el desarrollo de habilidades como el pensamiento l\u00f3gico, desarrollo personal, liderazgo, emprendimiento y trabajo en equipo. Es por esto que [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-10-08T04:00:00+00:00","article_modified_time":"2019-05-20T18:54:47+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a-1024x681.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro","datePublished":"2015-10-08T04:00:00+00:00","dateModified":"2019-05-20T18:54:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/"},"wordCount":578,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/","url":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/","name":"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg","datePublished":"2015-10-08T04:00:00+00:00","dateModified":"2019-05-20T18:54:47+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#primaryimage","url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg","contentUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/1715a9bcafc4936d3266138c7b84781a.jpg","width":3008,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/escolares-conocen-moderno-laboratorio-de-programacion-de-la-ufro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"Escolares conocen moderno laboratorio de programaci\u00f3n de la Ufro"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"predecessor-version":[{"id":38209,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1222\/revisions\/38209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media\/1223"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}