{"id":1164,"date":"2015-09-15T00:00:00","date_gmt":"2015-09-15T04:00:00","guid":{"rendered":"https:\/\/dev.explora.cl\/araucania\/blog\/2015\/09\/15\/participa-en-casa-abierta-2015\/"},"modified":"2019-05-20T18:55:12","modified_gmt":"2019-05-20T18:55:12","slug":"participa-en-casa-abierta-2015","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/","title":{"rendered":"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015!"},"content":{"rendered":"<p style=\"text-align: justify\"><em><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm\">En el contexto de la Semana Nacional de la Ciencia y tecnolog\u00eda 2015, el PAR Explora Regi\u00f3n de la Araucan\u00eda, invita a toda la comunidad escolar a participar de la actividad &nbsp;\u201cCasa Abierta\u201d<\/span><\/span><\/em><\/p>\n<p style=\"margin: 11.25pt 0cm;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><em><em><span style=\"font-family: 'Trebuchet MS', sans-serif;border: 1pt none windowtext;padding: 0cm;font-style: normal\">Por un d\u00eda profesores y estudiantes podr\u00e1n cambiar sus habituales espacios de aprendizaje para visitar las dependencias y laboratorios de investigaci\u00f3n de la Universidad de La Frontera, Universidad Cat\u00f3lica de Temuco y Planta de Tratamiento de Aguas Servidas de Temuco, instituciones que preparan demostraciones experimentales con el objetivo de<\/span><\/em><\/em><span style=\"font-family: 'Trebuchet MS', sans-serif\"> encantar a la comunidad con los enormes beneficios que genera el desarrollo cient\u00edfico y tecnol\u00f3gico. <\/span><\/span><\/p>\n<p style=\"margin: 11.25pt 0cm;text-align: justify;line-height: 15.75pt;background-image: initial;background-position: initial\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif\">Dicho evento est\u00e1 dirigido a estudiantes de sexto b\u00e1sico a cuarto medio y se realizar\u00e1 el mi\u00e9rcoles 04 de noviembre del presente a\u00f1o.<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">Casa Abierta es una actividad que se desarrolla todos los a\u00f1os, mediante la cual cientos de laboratorios de todo el pa\u00eds abren sus puertas para recibir la visita de escolares, con el fin de que descubran el sorprendente quehacer cient\u00edfico que se desarrolla en estos espacios, labor que muchas veces constituye un mundo desconocido para los ni\u00f1os, ni\u00f1as y j\u00f3venes<\/span>.<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">Los interesados en participar deben completar la ficha adjunta y enviarla al e-mail:<span style=\"color: #0000ff\"> <span style=\"color: #0000ff\"><a href=\"mailto:exploraaraucania@gmail.com\">exploraaraucania@gmail.com<\/a><a href=\"mailto:exploraaraucania@gmail.com\"><\/a><\/span><\/span><a href=\"mailto:exploraaraucania@gmail.com\"><\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #666666;border: 1pt none windowtext;padding: 0cm\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">&nbsp;<\/span><\/span><\/span><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14784\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/09\/bbbbbb-2.jpg\" alt=\"\" width=\"270\" height=\"180\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14785\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/09\/bbbbbb-3.jpg\" alt=\"\" width=\"265\" height=\"178\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-14786\" src=\"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/wp-content\/uploads\/2015\/09\/bbbbbb-1.jpg\" alt=\"\" width=\"261\" height=\"178\" \/><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\"><span style=\"font-family: 'Trebuchet MS', sans-serif;color: #666666;border: 1pt none windowtext;padding: 0cm\"><span style=\"font-size: 12pt;line-height: 115%;font-family: 'Trebuchet MS', sans-serif;background-image: initial;background-position: initial\">&nbsp;<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Trebuchet MS', sans-serif;font-size: 12pt;line-height: 115%\">Periodista: Viarly Salazar Fritz \/ Fotograf\u00eda: Arturo Rubio Navarro<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el contexto de la Semana Nacional de la Ciencia y tecnolog\u00eda 2015, el PAR Explora Regi\u00f3n de la Araucan\u00eda, invita a toda la comunidad escolar a participar de la actividad &nbsp;\u201cCasa Abierta\u201d Por un d\u00eda profesores y estudiantes podr\u00e1n cambiar sus habituales espacios de aprendizaje para visitar las dependencias y laboratorios de investigaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Inscr\u00edbete y participa en Casa Abierta 2015! - Araucan\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015! - Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"En el contexto de la Semana Nacional de la Ciencia y tecnolog\u00eda 2015, el PAR Explora Regi\u00f3n de la Araucan\u00eda, invita a toda la comunidad escolar a participar de la actividad &nbsp;\u201cCasa Abierta\u201d Por un d\u00eda profesores y estudiantes podr\u00e1n cambiar sus habituales espacios de aprendizaje para visitar las dependencias y laboratorios de investigaci\u00f3n de [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Araucan\u00eda\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-15T04:00:00+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T18:55:12+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"332\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015!\",\"datePublished\":\"2015-09-15T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:55:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\"},\"wordCount\":234,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\",\"name\":\"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015! - Araucan\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg\",\"datePublished\":\"2015-09-15T04:00:00+00:00\",\"dateModified\":\"2019-05-20T18:55:12+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg\",\"width\":500,\"height\":332},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/araucania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#website\",\"url\":\"https:\/\/dev.explora.cl\/araucania\/\",\"name\":\"Araucan\u00eda\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/araucania\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015! - Araucan\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015! - Araucan\u00eda","og_description":"En el contexto de la Semana Nacional de la Ciencia y tecnolog\u00eda 2015, el PAR Explora Regi\u00f3n de la Araucan\u00eda, invita a toda la comunidad escolar a participar de la actividad &nbsp;\u201cCasa Abierta\u201d Por un d\u00eda profesores y estudiantes podr\u00e1n cambiar sus habituales espacios de aprendizaje para visitar las dependencias y laboratorios de investigaci\u00f3n de [&hellip;]","og_url":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/","og_site_name":"Araucan\u00eda","article_published_time":"2015-09-15T04:00:00+00:00","article_modified_time":"2019-05-20T18:55:12+00:00","og_image":[{"width":500,"height":332,"url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015!","datePublished":"2015-09-15T04:00:00+00:00","dateModified":"2019-05-20T18:55:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/"},"wordCount":234,"commentCount":0,"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg","articleSection":["Noticias"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/","url":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/","name":"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015! - Araucan\u00eda","isPartOf":{"@id":"https:\/\/dev.explora.cl\/araucania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg","datePublished":"2015-09-15T04:00:00+00:00","dateModified":"2019-05-20T18:55:12+00:00","author":{"@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#primaryimage","url":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg","contentUrl":"https:\/\/dev.explora.cl\/araucania\/wp-content\/uploads\/sites\/15\/2018\/06\/bbbbbb-2.jpg","width":500,"height":332},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/araucania\/participa-en-casa-abierta-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/araucania\/"},{"@type":"ListItem","position":2,"name":"\u00a1Inscr\u00edbete y participa en Casa Abierta 2015!"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/araucania\/#website","url":"https:\/\/dev.explora.cl\/araucania\/","name":"Araucan\u00eda","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/araucania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/araucania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/araucania\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/comments?post=1164"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1164\/revisions"}],"predecessor-version":[{"id":38222,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/posts\/1164\/revisions\/38222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media\/1165"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/media?parent=1164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/categories?post=1164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/araucania\/wp-json\/wp\/v2\/tags?post=1164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}