{"id":38395,"date":"2017-11-30T20:05:22","date_gmt":"2017-11-30T20:05:22","guid":{"rendered":"https:\/\/dev.explora.cl\/antofagasta\/blog\/2017\/11\/30\/excursion-ganadora-del-album-completo\/"},"modified":"2019-05-16T03:17:18","modified_gmt":"2019-05-16T03:17:18","slug":"excursion-ganadora-del-album-completo","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/","title":{"rendered":"Excursi\u00f3n ganadora del \u00c1lbum Completo"},"content":{"rendered":"<ul>\n<li style=\"text-align: center\"><em>El 4to b\u00e1sico A de la escuela Dar\u00edo Salas D-75 de Antofagasta, fue el primer curso en disfrutar de su premio.<\/em><\/li>\n<\/ul>\n<p>Como parte de las actividades que completan la celebraci\u00f3n de la XXIII Semana Nacional de Ciencia y Tecnolog\u00eda, el \u00c1lbum Explora \u201cUn gran viaje por el Oc\u00e9ano\u201d, cumple un rol fundamental, ya que no solamente aporta con experimentos para trabajar en las salas de clases, sino que tambi\u00e9n, se realiza un sorteo de \u00e1lbum completo para quienes env\u00eden sus cupones.<\/p>\n<p>Bajo esta medida, el pasado lunes, los estudiantes del 4to b\u00e1sico A, de la Escuela Dar\u00edo Salas D-75 de Antofagasta, recibieron su premio gracias a que su compa\u00f1ero, Nicol\u00e1s Culma, sali\u00f3 como el cup\u00f3n ganador de la Provincia de Antofagasta.<\/p>\n<p><strong>Excursi\u00f3n cient\u00edfica<\/strong><\/p>\n<p>Cerca de 40 fueron los ni\u00f1os y ni\u00f1as que disfrutaron de la excursi\u00f3n donde, junto al Dr. Manuel Zapata de la Universidad de Antofagasta, conocieron el sector de los Ojos de Mar que se encuentran en La Rinconada de Antofagasta. Adem\u00e1s, aprendieron sobre la importancia del osti\u00f3n y la reserva que se encuentra protegida en la zona. Finalmente, realizaron un trabajo pr\u00e1ctico donde comparaban arenas contaminadas y no contaminadas pertenecientes a la misma zona donde ellos habitan.<\/p>\n<p>Clara Alfaro, profesora de Ciencias de la escuela Dar\u00edo Salas, se encontr\u00f3 muy agradecida por la experiencia vivida, tanto para ella como para su curso. \u201cLos ni\u00f1os se van con un muy buen regalo en el sentido de los conocimientos que adquirieron y yo, en lo personal, me voy impresionada porque no imaginaba el nivel de contaminaci\u00f3n que existe en nuestras playas\u201d, declar\u00f3.<\/p>\n<p>Conjuntamente, aprovecha la oportunidad para adquirir nuevas t\u00e9cnicas de trabajo y poder aplicarlas en el aula. \u201cEncontr\u00e9 unas ideas nuevas para trabajar el pr\u00f3ximo a\u00f1o en el tema de los oc\u00e9anos con los chicos. Fue aprendizaje para todos. Yo agradecida por todo lo que nos comparten\u201d, manifest\u00f3.<\/p>\n<p><strong>Premio \u00c1lbum Explora<\/strong><\/p>\n<p>Los otros ganadores del \u00e1lbum completo, fue el 5\u00baA del Colegio Sagrada Familia de Tocopilla, quienes realizar\u00e1n su excursi\u00f3n en las playas de Tocopilla; y el 5\u00baB de la Escuela Rep\u00fablica de Chile de Calama, que investigar\u00e1n las aguas del rio Loa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 4to b\u00e1sico A de la escuela Dar\u00edo Salas D-75 de Antofagasta, fue el primer curso en disfrutar de su premio. Como parte de las actividades que completan la celebraci\u00f3n de la XXIII Semana Nacional de Ciencia y Tecnolog\u00eda, el \u00c1lbum Explora \u201cUn gran viaje por el Oc\u00e9ano\u201d, cumple un rol fundamental, ya que no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29225,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-38395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Excursi\u00f3n ganadora del \u00c1lbum Completo - Antofagasta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Excursi\u00f3n ganadora del \u00c1lbum Completo - Antofagasta\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El 4to b\u00e1sico A de la escuela Dar\u00edo Salas D-75 de Antofagasta, fue el primer curso en disfrutar de su premio. Como parte de las actividades que completan la celebraci\u00f3n de la XXIII Semana Nacional de Ciencia y Tecnolog\u00eda, el \u00c1lbum Explora \u201cUn gran viaje por el Oc\u00e9ano\u201d, cumple un rol fundamental, ya que no [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Antofagasta\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-30T20:05:22+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T03:17:18+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Excursi\u00f3n ganadora del \u00c1lbum Completo\",\"datePublished\":\"2017-11-30T20:05:22+00:00\",\"dateModified\":\"2019-05-16T03:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\"},\"wordCount\":391,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\",\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\",\"name\":\"Excursi\u00f3n ganadora del \u00c1lbum Completo - Antofagasta\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-11-30T20:05:22+00:00\",\"dateModified\":\"2019-05-16T03:17:18+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/antofagasta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excursi\u00f3n ganadora del \u00c1lbum Completo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#website\",\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/\",\"name\":\"Antofagasta\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/antofagasta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Excursi\u00f3n ganadora del \u00c1lbum Completo - Antofagasta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/","og_locale":"es_ES","og_type":"article","og_title":"Excursi\u00f3n ganadora del \u00c1lbum Completo - Antofagasta","og_description":"El 4to b\u00e1sico A de la escuela Dar\u00edo Salas D-75 de Antofagasta, fue el primer curso en disfrutar de su premio. Como parte de las actividades que completan la celebraci\u00f3n de la XXIII Semana Nacional de Ciencia y Tecnolog\u00eda, el \u00c1lbum Explora \u201cUn gran viaje por el Oc\u00e9ano\u201d, cumple un rol fundamental, ya que no [&hellip;]","og_url":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/","og_site_name":"Antofagasta","article_published_time":"2017-11-30T20:05:22+00:00","article_modified_time":"2019-05-16T03:17:18+00:00","author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Excursi\u00f3n ganadora del \u00c1lbum Completo","datePublished":"2017-11-30T20:05:22+00:00","dateModified":"2019-05-16T03:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/"},"wordCount":391,"image":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/","url":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/","name":"Excursi\u00f3n ganadora del \u00c1lbum Completo - Antofagasta","isPartOf":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-11-30T20:05:22+00:00","dateModified":"2019-05-16T03:17:18+00:00","author":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/antofagasta\/excursion-ganadora-del-album-completo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/antofagasta\/"},{"@type":"ListItem","position":2,"name":"Excursi\u00f3n ganadora del \u00c1lbum Completo"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/antofagasta\/#website","url":"https:\/\/dev.explora.cl\/antofagasta\/","name":"Antofagasta","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/antofagasta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/antofagasta\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts\/38395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/comments?post=38395"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts\/38395\/revisions"}],"predecessor-version":[{"id":38481,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts\/38395\/revisions\/38481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/media?parent=38395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/categories?post=38395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/tags?post=38395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}