{"id":30811,"date":"2018-04-16T20:50:28","date_gmt":"2018-04-16T20:50:28","guid":{"rendered":"http:\/\/ec2-54-245-22-188.us-west-2.compute.amazonaws.com\/2018\/04\/16\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/"},"modified":"2019-05-16T03:17:08","modified_gmt":"2019-05-16T03:17:08","slug":"cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018","status":"publish","type":"post","link":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/","title":{"rendered":"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018"},"content":{"rendered":"<p><em>El objetivo fue ense\u00f1ar a los participantes a trav\u00e9s de una manera entretenida el tema del a\u00f1o del Programa Explora de CONICYT, el a\u00f1o de los por qu\u00e9, con dos talleres: \u00bfQu\u00e9 crees que ocurri\u00f3? Y \u00bfLa flota de barcos flota?<\/em><\/p>\n<p>Durante tres d\u00edas, el PAR Explora Antofagasta, junto con la Universidad de Antofagasta, realiz\u00f3 dos talleres en el V Festival de Ciencia Puerto de Ideas Antofagasta 2018. Ambas iniciativas, efectuadas en el Centro Cultural Estaci\u00f3n Antofagasta, estuvieron enfocadas en desarrollar, en los participantes, habilidades como la curiosidad y el razonamiento cr\u00edtico y reflexivo, entre otras.. Todo enmarcado en el tema del a\u00f1o del Programa Explora de CONICYT, el a\u00f1o de los por qu\u00e9; y sobre todo en uno de sus ejes tem\u00e1ticos, el pensamiento cr\u00edtico.<\/p>\n<p>Los dos talleres del PAR Explora Antofagasta fueron: \u201c\u00bfLa flota de barcos flota?\u201d y \u201c\u00bfQu\u00e9 crees que ocurri\u00f3?\u201d. El primero estuvo dirigido a ni\u00f1os y ni\u00f1as entre 6 a 9 a\u00f1os, efectuado los d\u00edas 14 y 15 de abril; mientras el segundo se realiz\u00f3 el viernes 13 de abril, y participaron estudiantes de 10 a 13 a\u00f1os.<\/p>\n<p>\u201cEs el quinto a\u00f1o que participamos en este festival de ciencia una vez m\u00e1s se logr\u00f3 el objetivo, transmitir contenido cient\u00edfico principalmente a p\u00fablico infantil. No s\u00f3lo entregamos la informaci\u00f3n a los ni\u00f1os, sino que adem\u00e1s, generamos instancias en que se trabaja con habilidades, permitiendo valorar la ciencia, la importancia de hacer preguntas y que se puede aprender de manera interactiva y participativa\u201d coment\u00f3 la directora del PAR Explora de CONICYT Antofagasta, Gladys Hayashida.<\/p>\n<p>A trav\u00e9s de experimentos, se motiv\u00f3 a los peque\u00f1os a cuestionar situaciones desde temprana edad, como poner a prueba con diversos materiales como podr\u00eda flotar un barco \u201cme parece excelente porque los ni\u00f1os hoy en d\u00eda est\u00e1n expuestos a tanta informaci\u00f3n que es bueno que aprendan cosas que ven en el d\u00eda a d\u00eda de forma pr\u00e1ctica, interviniendo con las manos para poder explicarles los fen\u00f3menos que ellos observan, me parece fant\u00e1stico que se impulsen este tipo de actividades\u201d afirm\u00f3 Alex Bastias, uno de los padres que junto a su hijo asisti\u00f3 al taller \u00bfla flota de barcos flota?, que explicaba el fen\u00f3meno de la flotabilidad.<\/p>\n<p>La participaci\u00f3n del PAR Explora Antofagasta en esta quinta edici\u00f3n del Festival Puerto de Ideas fue una instancia que sirvi\u00f3 a los objetivos del proyecto de acercar la ciencia y tecnolog\u00eda a las futuras generaciones, buscando contribuir al desarrollo integral de las personas y una mejor comprensi\u00f3n del entorno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo fue ense\u00f1ar a los participantes a trav\u00e9s de una manera entretenida el tema del a\u00f1o del Programa Explora de CONICYT, el a\u00f1o de los por qu\u00e9, con dos talleres: \u00bfQu\u00e9 crees que ocurri\u00f3? Y \u00bfLa flota de barcos flota? Durante tres d\u00edas, el PAR Explora Antofagasta, junto con la Universidad de Antofagasta, realiz\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30810,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-30811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018 - Antofagasta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018 - Antofagasta\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"El objetivo fue ense\u00f1ar a los participantes a trav\u00e9s de una manera entretenida el tema del a\u00f1o del Programa Explora de CONICYT, el a\u00f1o de los por qu\u00e9, con dos talleres: \u00bfQu\u00e9 crees que ocurri\u00f3? Y \u00bfLa flota de barcos flota? Durante tres d\u00edas, el PAR Explora Antofagasta, junto con la Universidad de Antofagasta, realiz\u00f3 [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Antofagasta\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-16T20:50:28+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-16T03:17:08+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"webman\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\"},\"author\":{\"name\":\"webman\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"headline\":\"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018\",\"datePublished\":\"2018-04-16T20:50:28+00:00\",\"dateModified\":\"2019-05-16T03:17:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\"},\"wordCount\":468,\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\",\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\",\"name\":\"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018 - Antofagasta\",\"isPartOf\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg\",\"datePublished\":\"2018-04-16T20:50:28+00:00\",\"dateModified\":\"2019-05-16T03:17:08+00:00\",\"author\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage\",\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg\",\"contentUrl\":\"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg\",\"width\":300,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dev.explora.cl\/antofagasta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#website\",\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/\",\"name\":\"Antofagasta\",\"description\":\"Otro sitio m\u00e1s de dev.explora.cl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.explora.cl\/antofagasta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d\",\"name\":\"webman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g\",\"caption\":\"webman\"},\"url\":\"https:\/\/dev.explora.cl\/antofagasta\/author\/webman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018 - Antofagasta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/","og_locale":"es_ES","og_type":"article","og_title":"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018 - Antofagasta","og_description":"El objetivo fue ense\u00f1ar a los participantes a trav\u00e9s de una manera entretenida el tema del a\u00f1o del Programa Explora de CONICYT, el a\u00f1o de los por qu\u00e9, con dos talleres: \u00bfQu\u00e9 crees que ocurri\u00f3? Y \u00bfLa flota de barcos flota? Durante tres d\u00edas, el PAR Explora Antofagasta, junto con la Universidad de Antofagasta, realiz\u00f3 [&hellip;]","og_url":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/","og_site_name":"Antofagasta","article_published_time":"2018-04-16T20:50:28+00:00","article_modified_time":"2019-05-16T03:17:08+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg","type":"image\/jpeg"}],"author":"webman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webman","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#article","isPartOf":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/"},"author":{"name":"webman","@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"headline":"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018","datePublished":"2018-04-16T20:50:28+00:00","dateModified":"2019-05-16T03:17:08+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/"},"wordCount":468,"image":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg","articleSection":["Noticias"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/","url":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/","name":"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018 - Antofagasta","isPartOf":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage"},"image":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg","datePublished":"2018-04-16T20:50:28+00:00","dateModified":"2019-05-16T03:17:08+00:00","author":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d"},"breadcrumb":{"@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#primaryimage","url":"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg","contentUrl":"https:\/\/dev.explora.cl\/antofagasta\/wp-content\/uploads\/sites\/4\/2018\/04\/IMG_7134-8.jpg","width":300,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/dev.explora.cl\/antofagasta\/cerca-de-cien-ninos-y-ninas-participaron-de-los-talleres-del-par-explora-en-el-v-festival-puerto-de-ideas-antofagasta-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.explora.cl\/antofagasta\/"},{"@type":"ListItem","position":2,"name":"Cerca de cien ni\u00f1os y ni\u00f1as participaron de los talleres del PAR Explora en el V Festival Puerto de Ideas Antofagasta 2018"}]},{"@type":"WebSite","@id":"https:\/\/dev.explora.cl\/antofagasta\/#website","url":"https:\/\/dev.explora.cl\/antofagasta\/","name":"Antofagasta","description":"Otro sitio m\u00e1s de dev.explora.cl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.explora.cl\/antofagasta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Person","@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/cb8349c13ea2d324080adf8480d7ba5d","name":"webman","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/dev.explora.cl\/antofagasta\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eeff3c82f2c02f7177d13663b7e6f890e9a6a0647ce9bb29cae02dcb094c7312?s=96&d=mm&r=g","caption":"webman"},"url":"https:\/\/dev.explora.cl\/antofagasta\/author\/webman\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts\/30811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/comments?post=30811"}],"version-history":[{"count":1,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts\/30811\/revisions"}],"predecessor-version":[{"id":38459,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/posts\/30811\/revisions\/38459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/media\/30810"}],"wp:attachment":[{"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/media?parent=30811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/categories?post=30811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.explora.cl\/antofagasta\/wp-json\/wp\/v2\/tags?post=30811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}